{"id":144219,"date":"2026-05-28T17:29:46","date_gmt":"2026-05-28T21:29:46","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=144219"},"modified":"2026-05-28T17:29:47","modified_gmt":"2026-05-28T21:29:47","slug":"patrullas-del-ejercito-interceptan-a-65-extranjeros-indocumentados-en-operativos-en-la-frontera-con-dajabon","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2026\/05\/28\/patrullas-del-ejercito-interceptan-a-65-extranjeros-indocumentados-en-operativos-en-la-frontera-con-dajabon\/","title":{"rendered":"Patrullas del Ej\u00e9rcito interceptan a 65 extranjeros indocumentados en operativos en la frontera con Dajab\u00f3n"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/05\/8c3d2f87-1a9b-4852-8b1c-9a2283b336ff-1024x576.jpg\" alt=\"\" class=\"wp-image-144220\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/05\/8c3d2f87-1a9b-4852-8b1c-9a2283b336ff-1024x576.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/05\/8c3d2f87-1a9b-4852-8b1c-9a2283b336ff-800x450.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/05\/8c3d2f87-1a9b-4852-8b1c-9a2283b336ff-768x432.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/05\/8c3d2f87-1a9b-4852-8b1c-9a2283b336ff.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las operaciones fueron realizadas en diferentes comunidades de la provincia fronteriza.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dajab\u00f3n, R.D. \u2013 Patrullas integradas por miembros del Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD), adscritos al 10mo. Batall\u00f3n de Infanter\u00eda y a distintos puestos militares de la provincia Dajab\u00f3n, detuvieron a sesenta y cinco (65) nacionales haitianos en condici\u00f3n migratoria irregular durante varios operativos de interdicci\u00f3n realizados en esa demarcaci\u00f3n fronteriza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una primera intervenci\u00f3n, soldados del Puesto Masacre, detuvieron a veinte (20) extranjeros indocumentados que intentaban ingresar al territorio dominicano desde Hait\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, soldados asignados al mismo puesto del ERD, apresaron a otros trece (13) nacionales haitianos indocumentados, integrados por doce (12) hombres y una (01) mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, una patrulla del 10mo. Batall\u00f3n de Infanter\u00eda adscrita al puesto de chequeo La Ci\u00e9nega detuvo a otros veinti\u00fan (21) nacionales haitianos indocumentados, entre ellos catorce (14) hombres, seis (06) mujeres y un (01) menor de edad, quienes intentaban evadir el referido puesto militar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro operativo, mientras una patrulla del ERD, adscrita a la Inspector\u00eda ERD de Loma de Cabrera, realizaba labores de patrullaje de interdicci\u00f3n en la secci\u00f3n Los Pomos, municipio Loma de Cabrera, detuvo a once (11) extranjeros en condici\u00f3n migratoria irregular, de los cuales ocho (08) eran hombres, dos (02) mujeres y un (01) menor de edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los extranjeros detenidos fueron trasladados a las respectivas dotaciones militares y posteriormente entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM) para los fines legales correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las labores de vigilancia, patrullaje e interdicci\u00f3n se mantienen reforzadas en toda la zona fronteriza por parte del Ej\u00e9rcito de Rep\u00fablica Dominicana, como parte de las acciones orientadas a combatir el tr\u00e1fico ilegal de personas y a garantizar la seguridad nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las operaciones fueron realizadas en diferentes comunidades de la provincia fronteriza. Dajab\u00f3n, R.D. \u2013 Patrullas integradas por miembros del Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD), adscritos al 10mo. Batall\u00f3n de Infanter\u00eda y a distintos puestos militares de la provincia Dajab\u00f3n, detuvieron a sesenta y cinco (65) nacionales haitianos en condici\u00f3n migratoria irregular durante varios operativos de interdicci\u00f3n realizados en esa demarcaci\u00f3n fronteriza. En una primera intervenci\u00f3n, soldados del Puesto Masacre, detuvieron a veinte (20) extranjeros indocumentados que intentaban ingresar al territorio dominicano desde Hait\u00ed. M\u00e1s tarde, soldados asignados al mismo puesto del ERD, apresaron a otros trece (13) nacionales haitianos indocumentados, integrados por doce (12) hombres y una (01) mujer. Por otra parte, una patrulla del 10mo. Batall\u00f3n de Infanter\u00eda adscrita al puesto de chequeo La Ci\u00e9nega detuvo a otros veinti\u00fan (21) nacionales haitianos indocumentados, entre ellos catorce (14) hombres, seis (06) mujeres y un (01) menor de edad, quienes intentaban evadir el referido puesto militar. En otro operativo, mientras una patrulla del ERD, adscrita a la Inspector\u00eda ERD de Loma de Cabrera, realizaba labores de patrullaje de interdicci\u00f3n en la secci\u00f3n Los Pomos, municipio Loma de Cabrera, detuvo a once (11) extranjeros en condici\u00f3n migratoria irregular, de los cuales ocho (08) eran hombres, dos (02) mujeres y un (01) menor de edad. Los extranjeros detenidos fueron trasladados a las respectivas dotaciones militares y posteriormente entregados a la Direcci\u00f3n General de Migraci\u00f3n (DGM) para los fines legales correspondientes. Las labores de vigilancia, patrullaje e interdicci\u00f3n se mantienen reforzadas en toda la zona fronteriza por parte del Ej\u00e9rcito de Rep\u00fablica Dominicana, como parte de las acciones orientadas a combatir el tr\u00e1fico ilegal de personas y a garantizar la seguridad nacional.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-144219","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/144219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=144219"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/144219\/revisions"}],"predecessor-version":[{"id":144221,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/144219\/revisions\/144221"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=144219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=144219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=144219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}