{"id":145107,"date":"2026-07-15T17:25:05","date_gmt":"2026-07-15T21:25:05","guid":{"rendered":"https:\/\/conexiondigital.com.do\/?p=145107"},"modified":"2026-07-15T17:36:10","modified_gmt":"2026-07-15T21:36:10","slug":"presidente-abinader-y-primera-dama-participan-en-la-celebracion-de-la-fiesta-nacional-de-francia-y-reafirman-solida-relacion-bilateral","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2026\/07\/15\/presidente-abinader-y-primera-dama-participan-en-la-celebracion-de-la-fiesta-nacional-de-francia-y-reafirman-solida-relacion-bilateral\/","title":{"rendered":"Presidente Abinader y primera dama participan en la celebraci\u00f3n de la Fiesta Nacional de Francia y reafirman s\u00f3lida relaci\u00f3n bilateral"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-1024x683.jpg\" alt=\"\" class=\"wp-image-145120\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-300x400.jpg 300w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/01ec1d9d-f6ad-41c4-b9a7-e3e898dc71a2-scaled.jpg 2560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Embajadora Sonia Barbry destaca amistad y confianza entre Francia y Rep\u00fablica Dominicana, la cooperaci\u00f3n en \u00e1reas estrat\u00e9gicas y el compromiso de continuar fortaleciendo su agenda com\u00fan<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santo Domingo. \u2013 El presidente Luis Abinader, acompa\u00f1ado de la primera dama Raquel Arbaje, particip\u00f3 este lunes en la celebraci\u00f3n de la Fiesta Nacional de Francia, tambi\u00e9n conocida como el D\u00eda de la Bastilla, fecha que cada 14 de julio conmemora el asalto a la prisi\u00f3n de la Bastilla en 1789, que marc\u00f3 el inicio de la Revoluci\u00f3n Francesa y el fin de la monarqu\u00eda absoluta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario y la primera dama fueron recibidos por la embajadora de Francia en la Rep\u00fablica Dominicana, Sonia Barbry, y, luego de las fotograf\u00edas oficiales, sostuvieron un breve encuentro privado en el que tambi\u00e9n participaron el viceministro de Pol\u00edtica Exterior Bilateral, Francisco Caraballo, y el viceministro para Asuntos Consulares y Migratorios, Opinio Antonio D\u00edaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su discurso, la embajadora Barbry resalt\u00f3 la profunda amistad que une a Francia y la Rep\u00fablica Dominicana, una relaci\u00f3n sustentada en valores compartidos como la libertad, la igualdad, la fraternidad, la defensa del derecho internacional, la soberan\u00eda de los Estados y el di\u00e1logo entre las naciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, destac\u00f3 la presencia de m\u00e1s de 6,000 dominicanos residentes en Francia y record\u00f3 que la reciente visita oficial del presidente Abinader a Par\u00eds permiti\u00f3 fortalecer la confianza entre ambos gobiernos y reafirmar la voluntad de seguir trabajando de manera conjunta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Barbry tambi\u00e9n subray\u00f3 que Francia ha financiado durante m\u00e1s de dos d\u00e9cadas proyectos estrat\u00e9gicos que impactan positivamente la calidad de vida de millones de dominicanos. Indic\u00f3 que, a trav\u00e9s de la Agencia Francesa de Desarrollo (AFD), se han movilizado m\u00e1s de US$1,500 millones para iniciativas de transporte urbano, agua potable, saneamiento, energ\u00eda y desarrollo territorial, y con proyecciones de firmar una nueva hoja de ruta de cooperaci\u00f3n bilateral.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-scaled.jpg\" alt=\"\" class=\"wp-image-145109\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-scaled.jpg 2560w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/6a5ed8a1-27aa-4f73-a19c-c5f9c80bfa74-1-300x400.jpg 300w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s valor\u00f3 la estrecha colaboraci\u00f3n en la lucha contra el narcotr\u00e1fico, resaltando los trabajos conjuntos con la Direcci\u00f3n Nacional de Control de Drogas (DNCD), y anunci\u00f3 la construcci\u00f3n de una Academia Regional de Capacitaci\u00f3n contra el Narcotr\u00e1fico, que fortalecer\u00e1 la formaci\u00f3n de especialistas de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La embajadora tambi\u00e9n resalt\u00f3 la cooperaci\u00f3n cultural, cient\u00edfica y educativa entre ambas naciones, que incluye la formaci\u00f3n de profesores de franc\u00e9s, proyectos de investigaci\u00f3n cient\u00edfica, apoyo a las artes y la pr\u00f3xima firma de un nuevo acuerdo intergubernamental de cooperaci\u00f3n educativa y cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n del ministro de Relaciones Exteriores, Roberto \u00c1lvarez, el viceministro de Pol\u00edtica Exterior Bilateral, Francisco Caraballo, afirm\u00f3 que Francia y la Rep\u00fablica Dominicana contin\u00faan consolidando una relaci\u00f3n basada en la confianza, el respeto mutuo y una visi\u00f3n compartida de futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que en los \u00faltimos a\u00f1os el v\u00ednculo bilateral se ha fortalecido mediante un di\u00e1logo pol\u00edtico que ha logrado traducirse en una agenda de cooperaci\u00f3n cada vez m\u00e1s amplia y sustantiva, orientada a enfrentar desaf\u00edos comunes en \u00e1reas como el desarrollo, la sostenibilidad, la seguridad, la lucha contra el narcotr\u00e1fico y la estabilidad regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, expres\u00f3 que ambos pa\u00edses trabajan juntos por un futuro m\u00e1s s\u00f3lido y humano, impulsando proyectos que generan bienestar para sus pueblos y reflejan una voluntad compartida de continuar fortaleciendo la relaci\u00f3n con sentido estrat\u00e9gico, respeto mutuo y vocaci\u00f3n de futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la celebraci\u00f3n asistieron miembros del cuerpo diplom\u00e1tico, funcionarios del Gobierno, empresarios e invitados especiales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-scaled.jpg\" alt=\"\" class=\"wp-image-145110\" srcset=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-scaled.jpg 2560w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-800x533.jpg 800w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-1024x683.jpg 1024w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-768x512.jpg 768w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-1536x1024.jpg 1536w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-2048x1365.jpg 2048w, https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2026\/07\/0d3e983a-4f08-4c95-85aa-d82dee300fab-300x400.jpg 300w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Embajadora Sonia Barbry destaca amistad y confianza entre Francia y Rep\u00fablica Dominicana, la cooperaci\u00f3n en \u00e1reas estrat\u00e9gicas y el compromiso de continuar fortaleciendo su agenda com\u00fan Santo Domingo. \u2013 El presidente Luis Abinader, acompa\u00f1ado de la primera dama Raquel Arbaje, particip\u00f3 este lunes en la celebraci\u00f3n de la Fiesta Nacional de Francia, tambi\u00e9n conocida como el D\u00eda de la Bastilla, fecha que cada 14 de julio conmemora el asalto a la prisi\u00f3n de la Bastilla en 1789, que marc\u00f3 el inicio de la Revoluci\u00f3n Francesa y el fin de la monarqu\u00eda absoluta. El mandatario y la primera dama fueron recibidos por la embajadora de Francia en la Rep\u00fablica Dominicana, Sonia Barbry, y, luego de las fotograf\u00edas oficiales, sostuvieron un breve encuentro privado en el que tambi\u00e9n participaron el viceministro de Pol\u00edtica Exterior Bilateral, Francisco Caraballo, y el viceministro para Asuntos Consulares y Migratorios, Opinio Antonio D\u00edaz. Durante su discurso, la embajadora Barbry resalt\u00f3 la profunda amistad que une a Francia y la Rep\u00fablica Dominicana, una relaci\u00f3n sustentada en valores compartidos como la libertad, la igualdad, la fraternidad, la defensa del derecho internacional, la soberan\u00eda de los Estados y el di\u00e1logo entre las naciones. Asimismo, destac\u00f3 la presencia de m\u00e1s de 6,000 dominicanos residentes en Francia y record\u00f3 que la reciente visita oficial del presidente Abinader a Par\u00eds permiti\u00f3 fortalecer la confianza entre ambos gobiernos y reafirmar la voluntad de seguir trabajando de manera conjunta. Barbry tambi\u00e9n subray\u00f3 que Francia ha financiado durante m\u00e1s de dos d\u00e9cadas proyectos estrat\u00e9gicos que impactan positivamente la calidad de vida de millones de dominicanos. Indic\u00f3 que, a trav\u00e9s de la Agencia Francesa de Desarrollo (AFD), se han movilizado m\u00e1s de US$1,500 millones para iniciativas de transporte urbano, agua potable, saneamiento, energ\u00eda y desarrollo territorial, y con proyecciones de firmar una nueva hoja de ruta de cooperaci\u00f3n bilateral. Adem\u00e1s valor\u00f3 la estrecha colaboraci\u00f3n en la lucha contra el narcotr\u00e1fico, resaltando los trabajos conjuntos con la Direcci\u00f3n Nacional de Control de Drogas (DNCD), y anunci\u00f3 la construcci\u00f3n de una Academia Regional de Capacitaci\u00f3n contra el Narcotr\u00e1fico, que fortalecer\u00e1 la formaci\u00f3n de especialistas de la regi\u00f3n. La embajadora tambi\u00e9n resalt\u00f3 la cooperaci\u00f3n cultural, cient\u00edfica y educativa entre ambas naciones, que incluye la formaci\u00f3n de profesores de franc\u00e9s, proyectos de investigaci\u00f3n cient\u00edfica, apoyo a las artes y la pr\u00f3xima firma de un nuevo acuerdo intergubernamental de cooperaci\u00f3n educativa y cultural. En representaci\u00f3n del ministro de Relaciones Exteriores, Roberto \u00c1lvarez, el viceministro de Pol\u00edtica Exterior Bilateral, Francisco Caraballo, afirm\u00f3 que Francia y la Rep\u00fablica Dominicana contin\u00faan consolidando una relaci\u00f3n basada en la confianza, el respeto mutuo y una visi\u00f3n compartida de futuro. Se\u00f1al\u00f3 que en los \u00faltimos a\u00f1os el v\u00ednculo bilateral se ha fortalecido mediante un di\u00e1logo pol\u00edtico que ha logrado traducirse en una agenda de cooperaci\u00f3n cada vez m\u00e1s amplia y sustantiva, orientada a enfrentar desaf\u00edos comunes en \u00e1reas como el desarrollo, la sostenibilidad, la seguridad, la lucha contra el narcotr\u00e1fico y la estabilidad regional. Asimismo, expres\u00f3 que ambos pa\u00edses trabajan juntos por un futuro m\u00e1s s\u00f3lido y humano, impulsando proyectos que generan bienestar para sus pueblos y reflejan una voluntad compartida de continuar fortaleciendo la relaci\u00f3n con sentido estrat\u00e9gico, respeto mutuo y vocaci\u00f3n de futuro. A la celebraci\u00f3n asistieron miembros del cuerpo diplom\u00e1tico, funcionarios del Gobierno, empresarios e invitados especiales.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-145107","post","type-post","status-publish","format-standard","hentry","category-politic"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/145107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=145107"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/145107\/revisions"}],"predecessor-version":[{"id":145122,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/145107\/revisions\/145122"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=145107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=145107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=145107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}