{"id":70629,"date":"2018-06-24T13:47:18","date_gmt":"2018-06-24T13:47:18","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=70629"},"modified":"2018-06-24T13:47:37","modified_gmt":"2018-06-24T13:47:37","slug":"banco-acusa-empleados-de-robar-rd5-millones-a-cuentas-de-clientes","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/06\/24\/banco-acusa-empleados-de-robar-rd5-millones-a-cuentas-de-clientes\/","title":{"rendered":"Banco acusa empleados de robar RD$5 millones a cuentas de clientes"},"content":{"rendered":"<p>SANTO DOMINGO, Rep\u00fablica Dominicana.- Cinco exempleados del Banco de Reservas\u00a0 fueron sometidos este viernes a la justicia, acusados de ser los cabecillas de una banda dedicada a retirar dinero de cuentas de clientes de esa entidad ya fallecidos.<\/p>\n<p>Los imputados son Jos\u00e9 Antonio Aybar de la Rosa, Rafael Orlando Pimentel D\u00edaz, Diana Martina Gonz\u00e1lez Salazar, Ronny Alberto de los Santos Mena y Jonathan Tejada Almonte, quienes supuestamente retiraron m\u00e1s de RD$5 millones en diferentes sucursales.<\/p>\n<p>De acuerdo con los documentos judiciales, la investigaci\u00f3n comenz\u00f3 a ra\u00edz de\u00a0 denuncias de clientes de esa entidad, quienes aseguran que se retir\u00f3 dinero de las cuentas de sus familiares fallecidos.\u00a0En otros casos, tambi\u00e9n hubo quejas de clientes por retiros fraudulentos.<\/p>\n<p>La documentaci\u00f3n judicial rese\u00f1a que estos exempleados se asociaron con otras personas que no laboraban en la entidad bancaria para hacer grandes retiros.<\/p>\n<p>En la red, el papel de los trabajadores del banco era reclutar a personas que no laboraban en la entidad bancaria para cometer la acci\u00f3n fraudulenta, con quienes\u00a0se repart\u00edan la ganancias obtenidas por las transacciones, caus\u00e1ndo grandes p\u00e9rdidas a la entidad bancaria y al Estado Dominicano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO, Rep\u00fablica Dominicana.- Cinco exempleados del Banco de Reservas\u00a0 fueron sometidos este viernes a la justicia, acusados de ser los cabecillas de una banda dedicada a retirar dinero de cuentas de clientes de esa entidad ya fallecidos. Los imputados son Jos\u00e9 Antonio Aybar de la Rosa, Rafael Orlando Pimentel D\u00edaz, Diana Martina Gonz\u00e1lez Salazar, Ronny Alberto de los Santos Mena y Jonathan Tejada Almonte, quienes supuestamente retiraron m\u00e1s de RD$5 millones en diferentes sucursales. De acuerdo con los documentos judiciales, la investigaci\u00f3n comenz\u00f3 a ra\u00edz de\u00a0 denuncias de clientes de esa entidad, quienes aseguran que se retir\u00f3 dinero de las cuentas de sus familiares fallecidos.\u00a0En otros casos, tambi\u00e9n hubo quejas de clientes por retiros fraudulentos. La documentaci\u00f3n judicial rese\u00f1a que estos exempleados se asociaron con otras personas que no laboraban en la entidad bancaria para hacer grandes retiros. En la red, el papel de los trabajadores del banco era reclutar a personas que no laboraban en la entidad bancaria para cometer la acci\u00f3n fraudulenta, con quienes\u00a0se repart\u00edan la ganancias obtenidas por las transacciones, caus\u00e1ndo grandes p\u00e9rdidas a la entidad bancaria y al Estado Dominicano.<\/p>\n","protected":false},"author":2,"featured_media":70630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-70629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=70629"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70629\/revisions"}],"predecessor-version":[{"id":70632,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70629\/revisions\/70632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/70630"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=70629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=70629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=70629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}