{"id":70775,"date":"2018-06-28T02:45:15","date_gmt":"2018-06-28T02:45:15","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=70775"},"modified":"2018-06-28T02:45:15","modified_gmt":"2018-06-28T02:45:15","slug":"desaprensivo-utilizan-a-nacionales-haitianos-para-depredar-la-zona-el-rio-sonador-en-cerro-montoso","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/06\/28\/desaprensivo-utilizan-a-nacionales-haitianos-para-depredar-la-zona-el-rio-sonador-en-cerro-montoso\/","title":{"rendered":"Desaprensivo utilizan a nacionales haitianos para depredar la zona el Rio Sonador en Cerro Montoso."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-70776 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/06\/f7ef98b6-b1d7-4176-a6f1-d28243f7e0f3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>Autoridades de Medio Ambiente de la zona \u00a0provincia Monse\u00f1or \u00a0Nouel han \u00a0tomado el caso y han iniciado una investigaci\u00f3n para tomar \u00a0las medidas necesarias para denunciar a las personas que est\u00e1n desforestando \u00a0la afluente de yuboa del Rio Yuna<\/p>\n<p>Autoridades de Medio Ambiente han denunciados en varias ocasiones \u00a0que han apresado a personas por\u00a0 depredar \u00a0la zona, pero cuando estos son sometidos a la justicia simplemente son liberados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-70777\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/06\/3b9ec333-f153-4717-ab18-983e5471df27-300x169.jpg\" alt=\"\" width=\"328\" height=\"185\" \/><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-70778 alignright\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/06\/8bcd28d6-ad81-45d1-af7a-1f1aad8e000e-300x169.jpg\" alt=\"\" width=\"332\" height=\"187\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades de Medio Ambiente de la zona \u00a0provincia Monse\u00f1or \u00a0Nouel han \u00a0tomado el caso y han iniciado una investigaci\u00f3n para tomar \u00a0las medidas necesarias para denunciar a las personas que est\u00e1n desforestando \u00a0la afluente de yuboa del Rio Yuna Autoridades de Medio Ambiente han denunciados en varias ocasiones \u00a0que han apresado a personas por\u00a0 depredar \u00a0la zona, pero cuando estos son sometidos a la justicia simplemente son liberados. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":70779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-70775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=70775"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70775\/revisions"}],"predecessor-version":[{"id":70780,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/70775\/revisions\/70780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/70779"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=70775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=70775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=70775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}