{"id":71154,"date":"2018-07-05T01:52:18","date_gmt":"2018-07-05T01:52:18","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=71154"},"modified":"2018-07-05T01:52:18","modified_gmt":"2018-07-05T01:52:18","slug":"senador-asegura-policias-querian-dar-un-tumbe-a-acusado-de-asalto-en-banco-popular","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/07\/05\/senador-asegura-policias-querian-dar-un-tumbe-a-acusado-de-asalto-en-banco-popular\/","title":{"rendered":"Senador asegura polic\u00edas quer\u00edan \u201cdar un tumbe\u201d a acusado de asalto en Banco Popular"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-71155 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/07\/80442cf2-c1bd-41c5-86c6-4ba6651e21c6-300x197.jpg\" alt=\"\" width=\"300\" height=\"197\" \/>Santo Domingo.- El senador por la provincia Peravia, Wilton Guerrero Dum\u00e9 asegur\u00f3 hoy que la intenci\u00f3n de los oficiales que ejecutaron el \u201callanamiento\u201d en el sector \u00abMaleconcito\u00bb de Los Mina Norte, era dar un tumbe a la persona se\u00f1alada en el asalto a la sucursal del Banco Popular en el ensanche Isabelita.<\/p>\n<p>Dijo que esto explica por qu\u00e9 los oficiales no se hicieron acompa\u00f1ar de un representante del Ministerio P\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El senador por la provincia Peravia, Wilton Guerrero Dum\u00e9 asegur\u00f3 hoy que la intenci\u00f3n de los oficiales que ejecutaron el \u201callanamiento\u201d en el sector \u00abMaleconcito\u00bb de Los Mina Norte, era dar un tumbe a la persona se\u00f1alada en el asalto a la sucursal del Banco Popular en el ensanche Isabelita. Dijo que esto explica por qu\u00e9 los oficiales no se hicieron acompa\u00f1ar de un representante del Ministerio P\u00fablico.<\/p>\n","protected":false},"author":2,"featured_media":71155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-71154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=71154"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71154\/revisions"}],"predecessor-version":[{"id":71156,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71154\/revisions\/71156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/71155"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=71154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=71154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=71154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}