{"id":71583,"date":"2018-07-14T13:33:04","date_gmt":"2018-07-14T13:33:04","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=71583"},"modified":"2018-07-14T13:33:04","modified_gmt":"2018-07-14T13:33:04","slug":"ministro-de-medio-ambiente-advierte-a-empresarios-hay-que-reducir-los-plasticos","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/07\/14\/ministro-de-medio-ambiente-advierte-a-empresarios-hay-que-reducir-los-plasticos\/","title":{"rendered":"Ministro de Medio Ambiente advierte a empresarios: \u201chay que reducir los pl\u00e1sticos\u201d"},"content":{"rendered":"<p>a class=\u00bbmln_uppercase_mln\u00bb><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-71584 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/07\/image_content_10293142_20180713165913-300x160.jpg\" alt=\"\" width=\"300\" height=\"160\" \/>SANTO DOMINGO.<\/a>\u00a0El alcalde del Distrito Nacional, David Collado, lament\u00f3 ayer que por falta de coordinaci\u00f3n entre instituciones se hayan acumulado toneladas de basura en \u00e1reas del Malec\u00f3n arrastradas por los r\u00edos Ozama e Isabela durante las lluvias del pasado martes.<\/p>\n<p>Los puntos m\u00e1s cr\u00edticos donde bailotea la basura al ritmo de las olas est\u00e1n pr\u00f3ximos a la plaza Fray Ant\u00f3n de Montesinos, por el \u201cObelisco Hembra\u201d y en la zona de G\u00fcibia.<\/p>\n<p>Collado encabez\u00f3 el operativo de recogida de los residuos, principalmente pl\u00e1sticos y jacintos de agua, mejor conocido como lilas.<\/p>\n<p>Inform\u00f3 que m\u00e1s de 200 hombres y mujeres trabajan en sacar los residuos, tarea que seg\u00fan el alcalde, tardar\u00e1 varios d\u00edas.<\/p>\n<p>Dijo que lo que se ha dicho es que el puente flotante fue levantado para mantenimiento, pero que no se le inform\u00f3 a la autoridad municipal de esa acci\u00f3n que tuvo como consecuencia la cantidad de basura acumulada en el litoral sur del Malec\u00f3n.<\/p>\n<p>A las tareas de recogida de los residuos se sumaron el Ministerio de Obras P\u00fablicas, que seg\u00fan inform\u00f3 tiene 600 hombres en tres frentes, y la Armada Dominicana. Abog\u00f3 para que en una pr\u00f3xima ocasi\u00f3n se le haga part\u00edcipe al cabildo de una decisi\u00f3n de esa naturaleza.<\/p>\n<p>\u201cNo fuimos nosotros que abrimos el puente flotante; no fuimos nosotros que provocamos eso, esa basura no es del Distrito Nacional, es de todo el Gran Santo Domingo y nada m\u00e1s el municipio Santo Domingo Este tiene el doble de los habitantes que el Distrito Nacional, pero \u00bfqui\u00e9n la est\u00e1 recogiendo?, la Alcald\u00eda del Distrito Nacional\u201d, manifest\u00f3 Collado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>a class=\u00bbmln_uppercase_mln\u00bb>SANTO DOMINGO.\u00a0El alcalde del Distrito Nacional, David Collado, lament\u00f3 ayer que por falta de coordinaci\u00f3n entre instituciones se hayan acumulado toneladas de basura en \u00e1reas del Malec\u00f3n arrastradas por los r\u00edos Ozama e Isabela durante las lluvias del pasado martes. Los puntos m\u00e1s cr\u00edticos donde bailotea la basura al ritmo de las olas est\u00e1n pr\u00f3ximos a la plaza Fray Ant\u00f3n de Montesinos, por el \u201cObelisco Hembra\u201d y en la zona de G\u00fcibia. Collado encabez\u00f3 el operativo de recogida de los residuos, principalmente pl\u00e1sticos y jacintos de agua, mejor conocido como lilas. Inform\u00f3 que m\u00e1s de 200 hombres y mujeres trabajan en sacar los residuos, tarea que seg\u00fan el alcalde, tardar\u00e1 varios d\u00edas. Dijo que lo que se ha dicho es que el puente flotante fue levantado para mantenimiento, pero que no se le inform\u00f3 a la autoridad municipal de esa acci\u00f3n que tuvo como consecuencia la cantidad de basura acumulada en el litoral sur del Malec\u00f3n. A las tareas de recogida de los residuos se sumaron el Ministerio de Obras P\u00fablicas, que seg\u00fan inform\u00f3 tiene 600 hombres en tres frentes, y la Armada Dominicana. Abog\u00f3 para que en una pr\u00f3xima ocasi\u00f3n se le haga part\u00edcipe al cabildo de una decisi\u00f3n de esa naturaleza. \u201cNo fuimos nosotros que abrimos el puente flotante; no fuimos nosotros que provocamos eso, esa basura no es del Distrito Nacional, es de todo el Gran Santo Domingo y nada m\u00e1s el municipio Santo Domingo Este tiene el doble de los habitantes que el Distrito Nacional, pero \u00bfqui\u00e9n la est\u00e1 recogiendo?, la Alcald\u00eda del Distrito Nacional\u201d, manifest\u00f3 Collado.<\/p>\n","protected":false},"author":1,"featured_media":71584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-71583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=71583"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71583\/revisions"}],"predecessor-version":[{"id":71586,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71583\/revisions\/71586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/71584"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=71583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=71583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=71583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}