{"id":71914,"date":"2018-07-19T11:25:04","date_gmt":"2018-07-19T11:25:04","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=71914"},"modified":"2018-07-20T16:12:57","modified_gmt":"2018-07-20T16:12:57","slug":"andres-navarro-da-apertura-a-foro-nacional-estudiantil-por-una-ciberciudadania-responsable","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/07\/19\/andres-navarro-da-apertura-a-foro-nacional-estudiantil-por-una-ciberciudadania-responsable\/","title":{"rendered":"ANDR\u00c9S NAVARRO DA APERTURA A FORO NACIONAL ESTUDIANTIL POR UNA CIBERCIUDADAN\u00cdA RESPONSABLE"},"content":{"rendered":"<p class=\"x_MsoNormal\">\n<p class=\"x_MsoNormal\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-71916 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/07\/thumbnail_DCS_8223-2-300x217.jpg\" alt=\"\" width=\"300\" height=\"217\" \/>Por segundo a\u00f1o consecutivo, el ministro de Educaci\u00f3n, Andr\u00e9s Navarro, encabez\u00f3 el \u201cForo Nacional Estudiantil por una Cultura de Paz: Rep\u00fablica Digital, una oportunidad para construir una ciberciudadan\u00eda responsable\u201d, espacio donde debatir\u00e1 cara a cara con 360 estudiantes de todo el pa\u00eds sobre la sana convivencia en los centros educativos y otras inquietudes que coadyuven con el mejoramiento del ambiente escolar.<\/p>\n<p class=\"x_MsoNormal\">Esta hist\u00f3rica iniciativa, participativa y democr\u00e1tica, con estudiantes del nivel secundario, se desarrollar\u00e1 durante tres d\u00edas en el sal\u00f3n de convenciones de la Canciller\u00eda de la Rep\u00fablica, bajo la firme convicci\u00f3n del ministro Andr\u00e9s Navarro de que los estudiantes representan el pilar de la Revoluci\u00f3n Educativa y por tanto, merecen ser escuchados.<\/p>\n<p class=\"x_MsoNormal\">Durante su discurso central en el acto, el ministro Navarro dijo que el segundo foro es un espacio abierto que permitir\u00e1 a las autoridades educativas, escuchar y constituirse en int\u00e9rpretes de las inquietudes y causas sociales de los estudiantes, por lo que los conmin\u00f3 a \u201cno quedarse callados y aportar en el an\u00e1lisis con un sentido pro positivo, en un debate franco y sincero que s\u00f3lo busca el mejor ambiente y desempe\u00f1o en el sistema educativo\u201d.<\/p>\n<p class=\"x_MsoNormal\">Precis\u00f3, ante centenares de estudiantes, docentes, funcionarios del Minerd, directores de gesti\u00f3n escolar y de representantes de distintos organismos internacionales y nacionales vinculados al sector educaci\u00f3n, que la Rep\u00fablica Dominicana necesita de ciudadanos referentes positivos desde las escuelas, las familias y el coraz\u00f3n de la naci\u00f3n.<\/p>\n<p class=\"x_MsoNormal\">\u201cNos sentimos orgullosos de ustedes queridos estudiantes, y en esa direcci\u00f3n estamos confiados de que presentar\u00e1n las mejores propuestas en la consecuci\u00f3n de la soluci\u00f3n de las distintas problem\u00e1ticas que se generen a lo largo de estos tres d\u00edas de debates\u201d, expuso.<\/p>\n<p class=\"x_MsoNormal\">Manifest\u00f3 que \u201cestamos comprometidos a incorporar cotidiana y permanentemente, las tecnolog\u00edas de la informaci\u00f3n, que les permitan convertirse en los protagonistas de la transformaci\u00f3n que vive el sistema educativo, a trav\u00e9s de la Revoluci\u00f3n Educativa que impulsa nuestro presidente Danilo Medina, asumiendo las herramientas digitales para la promoci\u00f3n efectiva del desarrollo humano con sentido integral\u201d.<\/p>\n<p class=\"x_MsoNormal\">\n<p class=\"x_MsoNormal\">\u201cLos estudiantes merecen ser escuchados como protagonistas en este proceso de reformas y cambios que se lleva a cabo en el marco de la Revoluci\u00f3n Educativa que impulsa nuestro presidente Danilo Medina. Ellos deben ser vistos como sujetos que tributen a la mejora de la calidad educativa. Por eso hemos decidido escucharlos nuevamente para conocer sus puntos de vista como sujetos principales del proceso, capaces de aportar a la calidad de la educaci\u00f3n\u201d, expres\u00f3 Navarro.<\/p>\n<p class=\"x_MsoNormal\">Los alumnos podr\u00e1n expresar cara a cara al ministro sus inquietudes, sue\u00f1os, propuestas y esperanzas relacionadas con el uso de la tecnolog\u00eda, entendida como herramienta de transformaci\u00f3n y mejora de su realidad, formaci\u00f3n y desarrollo integral. En esta oportunidad el eje tem\u00e1tico es el emblem\u00e1tico programa Rep\u00fablica Digital Educaci\u00f3n, emprendido por el presidente Danilo medina para reducir la brecha digital.<\/p>\n<p class=\"x_MsoNormal\">\n\u201dEste foro debe ser interpretado como un modelo de gesti\u00f3n p\u00fablica para el cambio de la educaci\u00f3n. Este foro lo estamos realizando por segundo a\u00f1o consecutivo con estas caracter\u00edsticas en un contexto institucional que est\u00e1 caracterizado por una pol\u00edtica emblem\u00e1tica del presidente Danilo Medina, la Revoluci\u00f3n Educativa. Esta Revoluci\u00f3n que es expresi\u00f3n de transformaci\u00f3n y cambio\u201d, sostuvo.<\/p>\n<p class=\"x_MsoNormal\">\nRep\u00fablica Digital Educaci\u00f3n se inici\u00f3 en el 2017 con la participaci\u00f3n de m\u00e1s de 63 mil estudiantes de los niveles Primario y Secundario de 150 centros educativos que disponen de conectividad, tecnolog\u00eda y contenidos digitales. Este a\u00f1o se sumar\u00e1n otros 350 planteles con una matr\u00edcula superior a los 158 mil estudiantes, con el objetivo desarrollar sus competencias digitales de manera gratuita, de sus familiares, los docentes y de los directivos de gesti\u00f3n en las escuelas, \u201cen un paso sin precedente que redundar\u00e1 en una sustancial mejora de la calidad de los aprendizajes\u201d.<\/p>\n<p class=\"x_MsoNormal\">\nLa invocaci\u00f3n religiosa para la apertura del foro estuvo a cargo del estudiante Francisco Alberto S\u00e1nchez, del Polit\u00e9cnico Santa Cruz, Fe y Alegr\u00eda de la Regional 12-Hig\u00fcey, mientras que los estudiantes Jeraldith Paulino Marte, Ricarly Fr\u00f3meta y Nataly Michel Berroa, se desempe\u00f1aron como conductores generales del evento.<\/p>\n<p class=\"x_MsoNormal\">\nMinerva P\u00e9rez, directora de Orientaci\u00f3n y Psicolog\u00eda del Ministerio de Educaci\u00f3n, pronunci\u00f3 el discurso de bienvenida a los estudiantes y al resto de las personalidades invitadas, incluyendo representantes de entidades que trabajan por el desarrollo del sistema educativo. En tanto, la familia del estudiante Dayron Col\u00e1s, participante del foro del 2017, refiri\u00f3 su experiencia sobre el evento del a\u00f1o pasado, y la estudiante Clara Mar\u00eda Sim\u00e9 Pep\u00edn, del Liceo Don Juan Hern\u00e1ndez, tuvo a su cargo las palabras de agradecimiento en nombre todas las comunidades educativas.<\/p>\n<p class=\"x_MsoNormal\">\nDurante los tres d\u00edas que dura el foro, los estudiantes realizar\u00e1n un recorrido por el edificio sede de Rep\u00fablica Digital Educaci\u00f3n para conocer sus operaciones, adem\u00e1s de que participar\u00e1n de charlas con los temas \u201cConstruyendo una Ciberciudadan\u00eda Responsable\u201d, \u201cInternet Sano\u201d, \u201cCiberbullying\u201d, \u201cFake News \u2013noticias falsas-en las Redes Sociales\u201d y \u201cCompromiso de la Familia con Rep\u00fablica Digital Educaci\u00f3n\u201d.<\/p>\n<p class=\"x_MsoNormal\">Tambi\u00e9n disfrutar\u00e1n de un programa art\u00edstico con participaci\u00f3n de diferentes regionales educativas.<\/p>\n<p class=\"x_MsoNormal\">A la actividad asistieron, adem\u00e1s, los viceministros Ram\u00f3n Valerio y Luis De Le\u00f3n; Johan Rodr\u00edguez, director de Rep\u00fablica Digital Educaci\u00f3n; Adolfo Cede\u00f1o, de Infraestructura Escolar; Andr\u00e9s de las Mercedes, del Instituto Nacional de Formaci\u00f3n Magisterial (INAFOCAM); Yuri Rodr\u00edguez, del Instituto Nacional de Bienestar Magisterial (INABIMA); Ren\u00e9 J\u00e1quez, del Instituto Nacional de Bienestar Estudiantil (INABIE); Jos\u00e9 Miguel Mart\u00ednez, de Gesti\u00f3n de Riesgo; Remigio Garc\u00eda, de Curr\u00edculo, y Miguel Medina, de Comunicaciones del Minerd, entre otros funcionarios.<\/p>\n<p class=\"x_MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>Por segundo a\u00f1o consecutivo, el ministro de Educaci\u00f3n, Andr\u00e9s Navarro, encabez\u00f3 el \u201cForo Nacional Estudiantil por una Cultura de Paz: Rep\u00fablica Digital, una oportunidad para construir una ciberciudadan\u00eda responsable\u201d, espacio donde debatir\u00e1 cara a cara con 360 estudiantes de todo el pa\u00eds sobre la sana convivencia en los centros educativos y otras inquietudes que coadyuven con el mejoramiento del ambiente escolar. Esta hist\u00f3rica iniciativa, participativa y democr\u00e1tica, con estudiantes del nivel secundario, se desarrollar\u00e1 durante tres d\u00edas en el sal\u00f3n de convenciones de la Canciller\u00eda de la Rep\u00fablica, bajo la firme convicci\u00f3n del ministro Andr\u00e9s Navarro de que los estudiantes representan el pilar de la Revoluci\u00f3n Educativa y por tanto, merecen ser escuchados. Durante su discurso central en el acto, el ministro Navarro dijo que el segundo foro es un espacio abierto que permitir\u00e1 a las autoridades educativas, escuchar y constituirse en int\u00e9rpretes de las inquietudes y causas sociales de los estudiantes, por lo que los conmin\u00f3 a \u201cno quedarse callados y aportar en el an\u00e1lisis con un sentido pro positivo, en un debate franco y sincero que s\u00f3lo busca el mejor ambiente y desempe\u00f1o en el sistema educativo\u201d. Precis\u00f3, ante centenares de estudiantes, docentes, funcionarios del Minerd, directores de gesti\u00f3n escolar y de representantes de distintos organismos internacionales y nacionales vinculados al sector educaci\u00f3n, que la Rep\u00fablica Dominicana necesita de ciudadanos referentes positivos desde las escuelas, las familias y el coraz\u00f3n de la naci\u00f3n. \u201cNos sentimos orgullosos de ustedes queridos estudiantes, y en esa direcci\u00f3n estamos confiados de que presentar\u00e1n las mejores propuestas en la consecuci\u00f3n de la soluci\u00f3n de las distintas problem\u00e1ticas que se generen a lo largo de estos tres d\u00edas de debates\u201d, expuso. Manifest\u00f3 que \u201cestamos comprometidos a incorporar cotidiana y permanentemente, las tecnolog\u00edas de la informaci\u00f3n, que les permitan convertirse en los protagonistas de la transformaci\u00f3n que vive el sistema educativo, a trav\u00e9s de la Revoluci\u00f3n Educativa que impulsa nuestro presidente Danilo Medina, asumiendo las herramientas digitales para la promoci\u00f3n efectiva del desarrollo humano con sentido integral\u201d. \u201cLos estudiantes merecen ser escuchados como protagonistas en este proceso de reformas y cambios que se lleva a cabo en el marco de la Revoluci\u00f3n Educativa que impulsa nuestro presidente Danilo Medina. Ellos deben ser vistos como sujetos que tributen a la mejora de la calidad educativa. Por eso hemos decidido escucharlos nuevamente para conocer sus puntos de vista como sujetos principales del proceso, capaces de aportar a la calidad de la educaci\u00f3n\u201d, expres\u00f3 Navarro. Los alumnos podr\u00e1n expresar cara a cara al ministro sus inquietudes, sue\u00f1os, propuestas y esperanzas relacionadas con el uso de la tecnolog\u00eda, entendida como herramienta de transformaci\u00f3n y mejora de su realidad, formaci\u00f3n y desarrollo integral. En esta oportunidad el eje tem\u00e1tico es el emblem\u00e1tico programa Rep\u00fablica Digital Educaci\u00f3n, emprendido por el presidente Danilo medina para reducir la brecha digital. \u201dEste foro debe ser interpretado como un modelo de gesti\u00f3n p\u00fablica para el cambio de la educaci\u00f3n. Este foro lo estamos realizando por segundo a\u00f1o consecutivo con estas caracter\u00edsticas en un contexto institucional que est\u00e1 caracterizado por una pol\u00edtica emblem\u00e1tica del presidente Danilo Medina, la Revoluci\u00f3n Educativa. Esta Revoluci\u00f3n que es expresi\u00f3n de transformaci\u00f3n y cambio\u201d, sostuvo. Rep\u00fablica Digital Educaci\u00f3n se inici\u00f3 en el 2017 con la participaci\u00f3n de m\u00e1s de 63 mil estudiantes de los niveles Primario y Secundario de 150 centros educativos que disponen de conectividad, tecnolog\u00eda y contenidos digitales. Este a\u00f1o se sumar\u00e1n otros 350 planteles con una matr\u00edcula superior a los 158 mil estudiantes, con el objetivo desarrollar sus competencias digitales de manera gratuita, de sus familiares, los docentes y de los directivos de gesti\u00f3n en las escuelas, \u201cen un paso sin precedente que redundar\u00e1 en una sustancial mejora de la calidad de los aprendizajes\u201d. La invocaci\u00f3n religiosa para la apertura del foro estuvo a cargo del estudiante Francisco Alberto S\u00e1nchez, del Polit\u00e9cnico Santa Cruz, Fe y Alegr\u00eda de la Regional 12-Hig\u00fcey, mientras que los estudiantes Jeraldith Paulino Marte, Ricarly Fr\u00f3meta y Nataly Michel Berroa, se desempe\u00f1aron como conductores generales del evento. Minerva P\u00e9rez, directora de Orientaci\u00f3n y Psicolog\u00eda del Ministerio de Educaci\u00f3n, pronunci\u00f3 el discurso de bienvenida a los estudiantes y al resto de las personalidades invitadas, incluyendo representantes de entidades que trabajan por el desarrollo del sistema educativo. En tanto, la familia del estudiante Dayron Col\u00e1s, participante del foro del 2017, refiri\u00f3 su experiencia sobre el evento del a\u00f1o pasado, y la estudiante Clara Mar\u00eda Sim\u00e9 Pep\u00edn, del Liceo Don Juan Hern\u00e1ndez, tuvo a su cargo las palabras de agradecimiento en nombre todas las comunidades educativas. Durante los tres d\u00edas que dura el foro, los estudiantes realizar\u00e1n un recorrido por el edificio sede de Rep\u00fablica Digital Educaci\u00f3n para conocer sus operaciones, adem\u00e1s de que participar\u00e1n de charlas con los temas \u201cConstruyendo una Ciberciudadan\u00eda Responsable\u201d, \u201cInternet Sano\u201d, \u201cCiberbullying\u201d, \u201cFake News \u2013noticias falsas-en las Redes Sociales\u201d y \u201cCompromiso de la Familia con Rep\u00fablica Digital Educaci\u00f3n\u201d. Tambi\u00e9n disfrutar\u00e1n de un programa art\u00edstico con participaci\u00f3n de diferentes regionales educativas. A la actividad asistieron, adem\u00e1s, los viceministros Ram\u00f3n Valerio y Luis De Le\u00f3n; Johan Rodr\u00edguez, director de Rep\u00fablica Digital Educaci\u00f3n; Adolfo Cede\u00f1o, de Infraestructura Escolar; Andr\u00e9s de las Mercedes, del Instituto Nacional de Formaci\u00f3n Magisterial (INAFOCAM); Yuri Rodr\u00edguez, del Instituto Nacional de Bienestar Magisterial (INABIMA); Ren\u00e9 J\u00e1quez, del Instituto Nacional de Bienestar Estudiantil (INABIE); Jos\u00e9 Miguel Mart\u00ednez, de Gesti\u00f3n de Riesgo; Remigio Garc\u00eda, de Curr\u00edculo, y Miguel Medina, de Comunicaciones del Minerd, entre otros funcionarios.<\/p>\n","protected":false},"author":3,"featured_media":71916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-71914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=71914"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71914\/revisions"}],"predecessor-version":[{"id":71917,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71914\/revisions\/71917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/71916"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=71914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=71914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=71914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}