{"id":72352,"date":"2018-07-23T01:51:05","date_gmt":"2018-07-23T01:51:05","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=72352"},"modified":"2018-07-23T01:51:05","modified_gmt":"2018-07-23T01:51:05","slug":"miembros-de-la-cuarta-brigada-del-ejercito-decomisa-124-sacos-de-ajo-que-transportaban-en-una-jeepeta-otro-golpe-al-contrabando","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/07\/23\/miembros-de-la-cuarta-brigada-del-ejercito-decomisa-124-sacos-de-ajo-que-transportaban-en-una-jeepeta-otro-golpe-al-contrabando\/","title":{"rendered":"Miembros de la Cuarta Brigada del Ej\u00e9rcito decomisa 124 sacos de ajo que transportaban en una Jeepeta; otro golpe al contrabando"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-72353 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/07\/UNSET-18-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/>\u00a0En horas de la ma\u00f1ana del d\u00eda de hoy miembros de la Cuarta Brigada del Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD) de servicio en la comunidad Ca\u00f1ongo del municipio Dajabon incautaron 124 sacos de ajo mientras eran transportados de manera ilegal dentro de un Jeepeta.<\/p>\n<p>La mercanc\u00eda incautada corresponde a la cantidad de 2,728 libras de ajo estaban siendo \u00a0transportados en una Jeepeta cuando fue detectada por los militares que iniciaron la persecuci\u00f3n de inmediato logrando apresar el veh\u00edculo.<\/p>\n<p>El contrabando seg\u00fan se explic\u00f3 \u00a0 proced\u00eda de la frontera con Hait\u00ed, zona que es constantemente utilizada por los traficantes tanto de mercanc\u00edas como de personas para cometer sus violaciones a la ley.<\/p>\n<p>El veh\u00edculo apresado es una jeepeta de la marca Jeep Cherokee, negra, placa X-378037,, chasis 1C4RJFBG6EC153053.<\/p>\n<p>Se indic\u00f3 que el veh\u00edculo era conducido por el reconocido contrabandista llamado LEYBI, qui\u00e9n emprendi\u00f3 la huida dej\u00e1ndolo abandonado, por los montes de la zona, la mercanc\u00eda se encuentra en poder del Ministerio P\u00fablico para los fines de ley correspondientes. \u00a0Estas operaciones est\u00e1n enmarcadas en el Plan de Seguridad de La Frontera, dispuesto por el Ministro de Defensa y el Comandante General del Ej\u00e9rcito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0En horas de la ma\u00f1ana del d\u00eda de hoy miembros de la Cuarta Brigada del Ej\u00e9rcito de Rep\u00fablica Dominicana (ERD) de servicio en la comunidad Ca\u00f1ongo del municipio Dajabon incautaron 124 sacos de ajo mientras eran transportados de manera ilegal dentro de un Jeepeta. La mercanc\u00eda incautada corresponde a la cantidad de 2,728 libras de ajo estaban siendo \u00a0transportados en una Jeepeta cuando fue detectada por los militares que iniciaron la persecuci\u00f3n de inmediato logrando apresar el veh\u00edculo. El contrabando seg\u00fan se explic\u00f3 \u00a0 proced\u00eda de la frontera con Hait\u00ed, zona que es constantemente utilizada por los traficantes tanto de mercanc\u00edas como de personas para cometer sus violaciones a la ley. El veh\u00edculo apresado es una jeepeta de la marca Jeep Cherokee, negra, placa X-378037,, chasis 1C4RJFBG6EC153053. Se indic\u00f3 que el veh\u00edculo era conducido por el reconocido contrabandista llamado LEYBI, qui\u00e9n emprendi\u00f3 la huida dej\u00e1ndolo abandonado, por los montes de la zona, la mercanc\u00eda se encuentra en poder del Ministerio P\u00fablico para los fines de ley correspondientes. \u00a0Estas operaciones est\u00e1n enmarcadas en el Plan de Seguridad de La Frontera, dispuesto por el Ministro de Defensa y el Comandante General del Ej\u00e9rcito.<\/p>\n","protected":false},"author":3,"featured_media":72353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-72352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/72352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=72352"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/72352\/revisions"}],"predecessor-version":[{"id":72354,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/72352\/revisions\/72354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/72353"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=72352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=72352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=72352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}