{"id":73328,"date":"2018-08-02T11:10:59","date_gmt":"2018-08-02T11:10:59","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=73328"},"modified":"2018-08-02T11:10:59","modified_gmt":"2018-08-02T11:10:59","slug":"estable-la-mujer-herida-por-bala-perdida-en-navarrete","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/08\/02\/estable-la-mujer-herida-por-bala-perdida-en-navarrete\/","title":{"rendered":"Estable la mujer herida por \u2018\u2019bala perdida\u2019\u2019 en Navarrete"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-73330 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/08\/UNSET-8-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" \/>Santiago.- Contin\u00faa estable la mujer que la madrugada de este mi\u00e9rcoles fue hospitalizada con una herida de bala que penetr\u00f3 por el techo de su residencia en el barrio Manolo Tavarez Justo de Navarrete.<\/p>\n<p>Maritza Polanco Dur\u00e1n de 40 a\u00f1os de edad, residente en la calle segunda del Manolo Tavares Justo, fue recluida en el hospital Regional Jos\u00e9\u00a0Mar\u00eda Cabral y B\u00e1ez, referida desde el hospital Lilian Fern\u00e1ndez del municipio.<\/p>\n<p>Se dijo que la \u2018\u2019bala perdida\u2019\u2019 perfor\u00f3 el zinc de la casa de la v\u00edctima, quien se encontraba acostada y escuch\u00f3 la detonaci\u00f3n, levant\u00e1ndose y percat\u00e1ndose del sangrado en su est\u00f3mago.<\/p>\n<p>El hecho ocurre en medio de una jornada de protestas por tiempo indefinido, al que han convocado los grupos populares y sociales de Navarrete, en reclamo de la construcci\u00f3n de un acueducto y el asfaltado de calles y caminos vecinales.<\/p>\n<p>Tambi\u00e9n reclaman energ\u00eda el\u00e9ctrica 24 horas, y la construcci\u00f3n de escuelas.<\/p>\n<p>El Frente Amplio de Lucha Popular (FALPO), anunci\u00f3 que las huelgas en Navarrete y Monte Adentro, se desarrollaron con un \u00e9xito total. En ambas \u00a0localidades, expresa en un comunicado en que eval\u00faa sus planes de lucha, la poblaci\u00f3n respald\u00f3, \u2018\u2019de forma contundente\u2019\u2019.<\/p>\n<p>El FALPO sostiene que la huelga en Navarrete, continuar\u00e1 por tiempo indefinido, hasta que se inicie la construcci\u00f3n del acueducto.<\/p>\n<p>\u2018\u2019Criminalizar las protestas no detendr\u00e1 nuestra decisi\u00f3n firme de luchar. Solo estamos exigiendo nuestros derechos a una vida digna, y la respuesta del gobierno del PLD es la represi\u00f3n\u2019\u2019 dice el informe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago.- Contin\u00faa estable la mujer que la madrugada de este mi\u00e9rcoles fue hospitalizada con una herida de bala que penetr\u00f3 por el techo de su residencia en el barrio Manolo Tavarez Justo de Navarrete. Maritza Polanco Dur\u00e1n de 40 a\u00f1os de edad, residente en la calle segunda del Manolo Tavares Justo, fue recluida en el hospital Regional Jos\u00e9\u00a0Mar\u00eda Cabral y B\u00e1ez, referida desde el hospital Lilian Fern\u00e1ndez del municipio. Se dijo que la \u2018\u2019bala perdida\u2019\u2019 perfor\u00f3 el zinc de la casa de la v\u00edctima, quien se encontraba acostada y escuch\u00f3 la detonaci\u00f3n, levant\u00e1ndose y percat\u00e1ndose del sangrado en su est\u00f3mago. El hecho ocurre en medio de una jornada de protestas por tiempo indefinido, al que han convocado los grupos populares y sociales de Navarrete, en reclamo de la construcci\u00f3n de un acueducto y el asfaltado de calles y caminos vecinales. Tambi\u00e9n reclaman energ\u00eda el\u00e9ctrica 24 horas, y la construcci\u00f3n de escuelas. El Frente Amplio de Lucha Popular (FALPO), anunci\u00f3 que las huelgas en Navarrete y Monte Adentro, se desarrollaron con un \u00e9xito total. En ambas \u00a0localidades, expresa en un comunicado en que eval\u00faa sus planes de lucha, la poblaci\u00f3n respald\u00f3, \u2018\u2019de forma contundente\u2019\u2019. El FALPO sostiene que la huelga en Navarrete, continuar\u00e1 por tiempo indefinido, hasta que se inicie la construcci\u00f3n del acueducto. \u2018\u2019Criminalizar las protestas no detendr\u00e1 nuestra decisi\u00f3n firme de luchar. Solo estamos exigiendo nuestros derechos a una vida digna, y la respuesta del gobierno del PLD es la represi\u00f3n\u2019\u2019 dice el informe.<\/p>\n","protected":false},"author":3,"featured_media":73330,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-73328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=73328"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73328\/revisions"}],"predecessor-version":[{"id":73331,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73328\/revisions\/73331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/73330"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=73328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=73328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=73328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}