{"id":74436,"date":"2018-08-17T03:08:14","date_gmt":"2018-08-17T03:08:14","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=74436"},"modified":"2018-08-17T03:08:14","modified_gmt":"2018-08-17T03:08:14","slug":"desmantelan-red-que-se-dedicaba-a-robar-en-un-resort-y-varias-empresas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/08\/17\/desmantelan-red-que-se-dedicaba-a-robar-en-un-resort-y-varias-empresas\/","title":{"rendered":"Desmantelan red que se dedicaba a robar en un resort y varias empresas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-74437 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/08\/images-8.jpg\" alt=\"\" width=\"160\" height=\"90\" \/>LA ROMANA, Rep\u00fablica Dominicana.-\u00a0\u00a0El Ministerio P\u00fablico y la Polic\u00eda Nacional desmantelaron una red que se dedicaba a robar en un resort y varias empresas privadas de la regi\u00f3n este del pa\u00eds y apresaron a sus principales actores, quienes fueron sometidos a la justicia y se le impuso prisi\u00f3n preventiva por su vinculaci\u00f3n a esos hechos delictivos.<\/p>\n<p>La Oficina de Judicial de Servicios de Atenci\u00f3n Permanente de La Romana le dict\u00f3 seis meses de prisi\u00f3n preventiva a Juan Manuel Morales Solano, alias Bojote, en tanto que tres meses de prisi\u00f3n les fueron impuestos a Orlando Soriano, Oscal de Jes\u00fas, alias El Cu\u00f1ao, y a David Hip\u00f3lito Contreras Severino, alias El Fumigador, \u00e9ste \u00faltimo quien realizaba labores de fumigaci\u00f3n en el resort, resaltando que durante toda la fase del proceso de investigaci\u00f3n el Ministerio P\u00fablico cont\u00f3 con la completa colaboraci\u00f3n del Resort y las empresas privadas con resultados positivos a favor de la investigaci\u00f3n.<\/p>\n<p>El Ministerio P\u00fablico inform\u00f3 que en otro operativo tambi\u00e9n fue apresado el presunto cabecilla de la red criminal, Juan Francisco Morla Castro, alias Checo, el cual igualmente fue sometido a la justicia y se solicit\u00f3 que se le imponga prisi\u00f3n preventiva, como medida de coerci\u00f3n quedando a la espera de la decisi\u00f3n judicial.<\/p>\n<p>De igual manera, el \u00f3rgano del sistema de justicia inform\u00f3 que por su vinculaci\u00f3n a este caso han activado la localizaci\u00f3n de los pr\u00f3fugos Elvis Genao, alias El Boy El Joyero; Silvio Javier, alias Tomasito, y otro implicado identificado como \u201cEl Menol\u201d.<\/p>\n<p>Indic\u00f3 que a esta red tambi\u00e9n estaba vinculado Willian Soliver Herrera, alias Pipe, quien result\u00f3 muerto mientras perpetraba otra acci\u00f3n delictiva en El Seibo.<\/p>\n<p>La instituci\u00f3n explic\u00f3 mediante un comunicado de prensa, que los integrantes de la estructura criminal organizada se dedicaban a sustraer distintos tipos de prendas y objetos de valor, tales como relojes, joyas y dinero en efectivo.<\/p>\n<p>Detall\u00f3 que el grupo perpetr\u00f3 alrededor de ocho robos en igual n\u00famero de establecimientos, de donde sustrajeron varios relojes, anillos de matrimonio y compromiso, cadenas de oro y plata, pulseras, varios documentos de propiedad y dinero en d\u00f3lares y pesos dominicanos, as\u00ed como varios aparatos celulares, entre otros.<\/p>\n<p>Al dar a conocer los detalles del caso, explic\u00f3 que inici\u00f3 una investigaci\u00f3n a ra\u00edz de varias denuncias de robos que hab\u00edan sido perpetrados contra los citados negocios, encontrando evidencias durante las pesquisas que vinculan a los imputados con dichos actos delictivos, que constituyen una violaci\u00f3n a varios art\u00edculos del C\u00f3digo Penal Dominicano y la nueva Ley No. 631-16 sobre Armas, Municiones y Materiales Relacionados.<\/p>\n<p>El \u00f3rgano de persecuci\u00f3n destac\u00f3 que desde que asumi\u00f3 sus funciones hace dos a\u00f1os, el procurador general de la Rep\u00fablica, Jean Rodr\u00edguez, ha ejecutado diferentes acciones para proteger a este importante sector de la econom\u00eda nacional como lo es el turismo y contrarrestar las principales problem\u00e1ticas que les afectan, siendo una muestra reciente de ello el desmantelamiento de esta red criminal, cuyos presuntos integrantes est\u00e1n siendo procesados judicialmente.<\/p>\n<p>Resalt\u00f3 en ese mismo orden, que esta nueva operaci\u00f3n llevada a cabo junto a la Polic\u00eda Nacional contra el crimen organizado, es una muestra m\u00e1s de la voluntad y el compromiso que han asumido en la lucha contra el crimen junto a todos los organismos de seguridad del Estado.<\/p>\n<p>Expres\u00f3 que el combate efectivo de esos delitos constituye una de las prioridades y metas institucionales que han trazado junto a los citados organismos para garantizar la paz, la tranquilidad y mayor seguridad a toda la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA ROMANA, Rep\u00fablica Dominicana.-\u00a0\u00a0El Ministerio P\u00fablico y la Polic\u00eda Nacional desmantelaron una red que se dedicaba a robar en un resort y varias empresas privadas de la regi\u00f3n este del pa\u00eds y apresaron a sus principales actores, quienes fueron sometidos a la justicia y se le impuso prisi\u00f3n preventiva por su vinculaci\u00f3n a esos hechos delictivos. La Oficina de Judicial de Servicios de Atenci\u00f3n Permanente de La Romana le dict\u00f3 seis meses de prisi\u00f3n preventiva a Juan Manuel Morales Solano, alias Bojote, en tanto que tres meses de prisi\u00f3n les fueron impuestos a Orlando Soriano, Oscal de Jes\u00fas, alias El Cu\u00f1ao, y a David Hip\u00f3lito Contreras Severino, alias El Fumigador, \u00e9ste \u00faltimo quien realizaba labores de fumigaci\u00f3n en el resort, resaltando que durante toda la fase del proceso de investigaci\u00f3n el Ministerio P\u00fablico cont\u00f3 con la completa colaboraci\u00f3n del Resort y las empresas privadas con resultados positivos a favor de la investigaci\u00f3n. El Ministerio P\u00fablico inform\u00f3 que en otro operativo tambi\u00e9n fue apresado el presunto cabecilla de la red criminal, Juan Francisco Morla Castro, alias Checo, el cual igualmente fue sometido a la justicia y se solicit\u00f3 que se le imponga prisi\u00f3n preventiva, como medida de coerci\u00f3n quedando a la espera de la decisi\u00f3n judicial. De igual manera, el \u00f3rgano del sistema de justicia inform\u00f3 que por su vinculaci\u00f3n a este caso han activado la localizaci\u00f3n de los pr\u00f3fugos Elvis Genao, alias El Boy El Joyero; Silvio Javier, alias Tomasito, y otro implicado identificado como \u201cEl Menol\u201d. Indic\u00f3 que a esta red tambi\u00e9n estaba vinculado Willian Soliver Herrera, alias Pipe, quien result\u00f3 muerto mientras perpetraba otra acci\u00f3n delictiva en El Seibo. La instituci\u00f3n explic\u00f3 mediante un comunicado de prensa, que los integrantes de la estructura criminal organizada se dedicaban a sustraer distintos tipos de prendas y objetos de valor, tales como relojes, joyas y dinero en efectivo. Detall\u00f3 que el grupo perpetr\u00f3 alrededor de ocho robos en igual n\u00famero de establecimientos, de donde sustrajeron varios relojes, anillos de matrimonio y compromiso, cadenas de oro y plata, pulseras, varios documentos de propiedad y dinero en d\u00f3lares y pesos dominicanos, as\u00ed como varios aparatos celulares, entre otros. Al dar a conocer los detalles del caso, explic\u00f3 que inici\u00f3 una investigaci\u00f3n a ra\u00edz de varias denuncias de robos que hab\u00edan sido perpetrados contra los citados negocios, encontrando evidencias durante las pesquisas que vinculan a los imputados con dichos actos delictivos, que constituyen una violaci\u00f3n a varios art\u00edculos del C\u00f3digo Penal Dominicano y la nueva Ley No. 631-16 sobre Armas, Municiones y Materiales Relacionados. El \u00f3rgano de persecuci\u00f3n destac\u00f3 que desde que asumi\u00f3 sus funciones hace dos a\u00f1os, el procurador general de la Rep\u00fablica, Jean Rodr\u00edguez, ha ejecutado diferentes acciones para proteger a este importante sector de la econom\u00eda nacional como lo es el turismo y contrarrestar las principales problem\u00e1ticas que les afectan, siendo una muestra reciente de ello el desmantelamiento de esta red criminal, cuyos presuntos integrantes est\u00e1n siendo procesados judicialmente. Resalt\u00f3 en ese mismo orden, que esta nueva operaci\u00f3n llevada a cabo junto a la Polic\u00eda Nacional contra el crimen organizado, es una muestra m\u00e1s de la voluntad y el compromiso que han asumido en la lucha contra el crimen junto a todos los organismos de seguridad del Estado. Expres\u00f3 que el combate efectivo de esos delitos constituye una de las prioridades y metas institucionales que han trazado junto a los citados organismos para garantizar la paz, la tranquilidad y mayor seguridad a toda la ciudadan\u00eda.<\/p>\n","protected":false},"author":3,"featured_media":74437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-74436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/74436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=74436"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/74436\/revisions"}],"predecessor-version":[{"id":74438,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/74436\/revisions\/74438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/74437"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=74436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=74436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=74436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}