{"id":75476,"date":"2018-08-30T17:13:18","date_gmt":"2018-08-30T17:13:18","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=75476"},"modified":"2018-08-30T17:13:18","modified_gmt":"2018-08-30T17:13:18","slug":"el-idac-lleva-operativo-medico-a-chirino-de-monte-plata-acorde-a-programa-de-responsabilidad-social","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/08\/30\/el-idac-lleva-operativo-medico-a-chirino-de-monte-plata-acorde-a-programa-de-responsabilidad-social\/","title":{"rendered":"El IDAC lleva operativo m\u00e9dico a Chirino de Monte Plata acorde a programa de responsabilidad social"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-75477 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/08\/thumbnail_NI-132-18-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" \/>Santo Domingo.-\u00a0El equipo de salud del\u00a0 Instituto Dominicano de Aviaci\u00f3n Civil (IDAC) desarroll\u00f3 un operativo m\u00e9dico especializado en mujeres embarazadas en el distrito municipal Chirino, provincia Monte Plata, en cumplimiento con su programa de responsabilidad social y en respuesta a una solicitud de esa comunidad.<\/p>\n<p>Decenas de mujeres en estado de gestaci\u00f3n fueron examinadas por un equipo m\u00e9dico especializado que estudi\u00f3 cada caso y las orient\u00f3 sobre el comportamiento a seguir en su embarazo y la preparaci\u00f3n para el parto.<\/p>\n<p>Los galenos entregaron medicamentos, multivitam\u00ednicos y otros suplementos alimenticios\u00a0 a las pacientes para el mejor desarrollo del feto y de las futuras madres.<\/p>\n<p>Durante el operativo m\u00e9dico las mujeres tambi\u00e9n recibieron canastillas, colchonetas, mosquiteros, raciones alimenticias, cajas de cloro y repelentes.<\/p>\n<p>Orientadores del Ministerio de la Mujer impartieron charlas a las futuras madres sobre la necesidad de la lactancia materna y orientando sobre la violencia de g\u00e9nero, como parte del acuerdo entre ese organismo y el IDAC.<\/p>\n<p>Para la ejecuci\u00f3n del operativo m\u00e9dico en Chirino el IDAC recibi\u00f3\u00a0 la solicitud y posterior\u00a0 colaboraci\u00f3n de la directora del distrito municipal, Jomayri Concepci\u00f3n, inform\u00f3 Lucrecio Polanco, subdirector general del IDAC, quien represent\u00f3 al director general Alejandro Herrera.<\/p>\n<p>El Doctor Enmanuel Ram\u00edrez, coordinador de la Unidad M\u00e9dica del IDAC, \u00a0inform\u00f3 de los servicios brindados y las atenciones recibidas en la comunidad y \u00a0la \u00a0colaboraci\u00f3n \u00a0de las damas atendidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Santo Domingo.-\u00a0El equipo de salud del\u00a0 Instituto Dominicano de Aviaci\u00f3n Civil (IDAC) desarroll\u00f3 un operativo m\u00e9dico especializado en mujeres embarazadas en el distrito municipal Chirino, provincia Monte Plata, en cumplimiento con su programa de responsabilidad social y en respuesta a una solicitud de esa comunidad. Decenas de mujeres en estado de gestaci\u00f3n fueron examinadas por un equipo m\u00e9dico especializado que estudi\u00f3 cada caso y las orient\u00f3 sobre el comportamiento a seguir en su embarazo y la preparaci\u00f3n para el parto. Los galenos entregaron medicamentos, multivitam\u00ednicos y otros suplementos alimenticios\u00a0 a las pacientes para el mejor desarrollo del feto y de las futuras madres. Durante el operativo m\u00e9dico las mujeres tambi\u00e9n recibieron canastillas, colchonetas, mosquiteros, raciones alimenticias, cajas de cloro y repelentes. Orientadores del Ministerio de la Mujer impartieron charlas a las futuras madres sobre la necesidad de la lactancia materna y orientando sobre la violencia de g\u00e9nero, como parte del acuerdo entre ese organismo y el IDAC. Para la ejecuci\u00f3n del operativo m\u00e9dico en Chirino el IDAC recibi\u00f3\u00a0 la solicitud y posterior\u00a0 colaboraci\u00f3n de la directora del distrito municipal, Jomayri Concepci\u00f3n, inform\u00f3 Lucrecio Polanco, subdirector general del IDAC, quien represent\u00f3 al director general Alejandro Herrera. El Doctor Enmanuel Ram\u00edrez, coordinador de la Unidad M\u00e9dica del IDAC, \u00a0inform\u00f3 de los servicios brindados y las atenciones recibidas en la comunidad y \u00a0la \u00a0colaboraci\u00f3n \u00a0de las damas atendidas.<\/p>\n","protected":false},"author":3,"featured_media":75477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-75476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=75476"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75476\/revisions"}],"predecessor-version":[{"id":75478,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75476\/revisions\/75478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/75477"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=75476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=75476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=75476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}