{"id":75694,"date":"2018-09-02T19:14:37","date_gmt":"2018-09-02T19:14:37","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=75694"},"modified":"2018-09-02T19:14:37","modified_gmt":"2018-09-02T19:14:37","slug":"transparencia-internacional-condena-los-intentos-de-bloquear-la-lucha-anticorrupcion-en-guatemala","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/09\/02\/transparencia-internacional-condena-los-intentos-de-bloquear-la-lucha-anticorrupcion-en-guatemala\/","title":{"rendered":"Transparencia Internacional condena los intentos de bloquear la lucha anticorrupci\u00f3n en Guatemala"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-75695 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/09\/Transparency_International_Logo-300x95.png\" alt=\"\" width=\"300\" height=\"95\" \/>El presidente de Guatemala, Jimmy Morales, revoc\u00f3 el mandato de la Comisi\u00f3n Internacional contra la Impunidad de las Naciones Unidas en Guatemala (CICIG), el organismo auspiciado por la Naciones Unidas y encargado de apoyar las investigaciones contra la corrupci\u00f3n en el pa\u00eds. La Comisi\u00f3n Internacional ha trabajado con las autoridades nacionales desde 2007 y ha tenido un \u00e9xito significativo en el procesamiento de numerosos casos de corrupci\u00f3n de alto nivel.<\/p>\n<p>El Presidente hizo el anuncio rodeado de l\u00edderes militares y policiales mientras los medios informaban del despliegue simult\u00e1neo de militares en las inmediaciones de las oficinas de la CICIG. La medida fue anunciada precisamente cuando el Congreso de Guatemala inici\u00f3 audiencias preliminares contra el Presidente Morales por irregularidades en el financiamiento de campa\u00f1as, y es otro intento de atacar y debilitar la lucha contra la corrupci\u00f3n en el pa\u00eds.<\/p>\n<p>La decisi\u00f3n no cuenta con respaldo nacional ni internacional. Una\u00a0encuesta\u00a0reciente muestra que el 70% de los guatemaltecos conf\u00eda en el trabajo de la CICIG. De hecho, la Comision Internacional ha producido excelentes resultados, desmantelando redes de corrupci\u00f3n en el pa\u00eds. La Fiscal General de Guatemala, contraparte nacional de la CICIG, afirm\u00f3 que estar\u00e1 vigilante ante las consecuencias para el sistema de justicia y la lucha contra la impunidad y la corrupci\u00f3n causada por la no renovaci\u00f3n del mandato de la Comisi\u00f3n.<\/p>\n<p>Delia Ferreira Rubio, Presidenta de Transparencia Internacional dijo: \u201cEl anuncio del presidente Morales de no renovar el mandato de la Comisi\u00f3n Internacional contra la Impunidad de las Naciones Unidas en Guatemala representa un duro golpe contra la transparencia y la integridad en Guatemala y en toda Am\u00e9rica Latina. La CICIG ha sido un modelo en la lucha contra la corrupci\u00f3n. El hecho que el Presidente hiciera el anuncio rodeado de militares y el despliegue de fuerzas militares cerca de las oficinas de la CICG son un intento de intimidaci\u00f3n. Es muy peligroso involucrar a los militares en asunto pol\u00edticos o de justicia\u201d<\/p>\n<p>\u201cTransparencia Internacional reconoce el excelente trabajo y los resultados del CICIG, apoya plenamente su continuaci\u00f3n en Guatemala y expresa su solidaridad con el Comisionado Iv\u00e1n Vel\u00e1zquez. Esta es una decisi\u00f3n pol\u00edtica que s\u00f3lo beneficiar\u00e1 a los corruptos, quienes podr\u00e1n actuar con impunidad mientras los guatemaltecos contin\u00faan sufriendo de la corrupci\u00f3n end\u00e9mica\u201d.<\/p>\n<p>Esta decisi\u00f3n es la continuaci\u00f3n de una serie de intentos del Presidente y sus aliados para detener la lucha contra la corrupci\u00f3n, reducir la libertad de expresi\u00f3n y restringir a las organizaciones de la sociedad civil. Manfredo Marroquin, Presidente de Acci\u00f3n Ciudadana, el cap\u00edtulo de Transparencia International en Guatemala, fue v\u00edctima de acoso pol\u00edtico por parte del Congreso de la Rep\u00fablica en abril de 2018.Transparencia International est\u00e1 muy preocupada por la tendencia a socavar las normas democr\u00e1ticas, cuyo resultado es la proliferaci\u00f3n de corrupci\u00f3n, impunidad y autoritarismo.<\/p>\n<p>Transparencia Internacional insta a las Naciones Unidas y a la comunidad internacional a que muestren un apoyo en\u00e9rgico a la lucha contra la corrupci\u00f3n en Guatemala y apoyen la continuaci\u00f3n e la independencia del CICCG.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Guatemala, Jimmy Morales, revoc\u00f3 el mandato de la Comisi\u00f3n Internacional contra la Impunidad de las Naciones Unidas en Guatemala (CICIG), el organismo auspiciado por la Naciones Unidas y encargado de apoyar las investigaciones contra la corrupci\u00f3n en el pa\u00eds. La Comisi\u00f3n Internacional ha trabajado con las autoridades nacionales desde 2007 y ha tenido un \u00e9xito significativo en el procesamiento de numerosos casos de corrupci\u00f3n de alto nivel. El Presidente hizo el anuncio rodeado de l\u00edderes militares y policiales mientras los medios informaban del despliegue simult\u00e1neo de militares en las inmediaciones de las oficinas de la CICIG. La medida fue anunciada precisamente cuando el Congreso de Guatemala inici\u00f3 audiencias preliminares contra el Presidente Morales por irregularidades en el financiamiento de campa\u00f1as, y es otro intento de atacar y debilitar la lucha contra la corrupci\u00f3n en el pa\u00eds. La decisi\u00f3n no cuenta con respaldo nacional ni internacional. Una\u00a0encuesta\u00a0reciente muestra que el 70% de los guatemaltecos conf\u00eda en el trabajo de la CICIG. De hecho, la Comision Internacional ha producido excelentes resultados, desmantelando redes de corrupci\u00f3n en el pa\u00eds. La Fiscal General de Guatemala, contraparte nacional de la CICIG, afirm\u00f3 que estar\u00e1 vigilante ante las consecuencias para el sistema de justicia y la lucha contra la impunidad y la corrupci\u00f3n causada por la no renovaci\u00f3n del mandato de la Comisi\u00f3n. Delia Ferreira Rubio, Presidenta de Transparencia Internacional dijo: \u201cEl anuncio del presidente Morales de no renovar el mandato de la Comisi\u00f3n Internacional contra la Impunidad de las Naciones Unidas en Guatemala representa un duro golpe contra la transparencia y la integridad en Guatemala y en toda Am\u00e9rica Latina. La CICIG ha sido un modelo en la lucha contra la corrupci\u00f3n. El hecho que el Presidente hiciera el anuncio rodeado de militares y el despliegue de fuerzas militares cerca de las oficinas de la CICG son un intento de intimidaci\u00f3n. Es muy peligroso involucrar a los militares en asunto pol\u00edticos o de justicia\u201d \u201cTransparencia Internacional reconoce el excelente trabajo y los resultados del CICIG, apoya plenamente su continuaci\u00f3n en Guatemala y expresa su solidaridad con el Comisionado Iv\u00e1n Vel\u00e1zquez. Esta es una decisi\u00f3n pol\u00edtica que s\u00f3lo beneficiar\u00e1 a los corruptos, quienes podr\u00e1n actuar con impunidad mientras los guatemaltecos contin\u00faan sufriendo de la corrupci\u00f3n end\u00e9mica\u201d. Esta decisi\u00f3n es la continuaci\u00f3n de una serie de intentos del Presidente y sus aliados para detener la lucha contra la corrupci\u00f3n, reducir la libertad de expresi\u00f3n y restringir a las organizaciones de la sociedad civil. Manfredo Marroquin, Presidente de Acci\u00f3n Ciudadana, el cap\u00edtulo de Transparencia International en Guatemala, fue v\u00edctima de acoso pol\u00edtico por parte del Congreso de la Rep\u00fablica en abril de 2018.Transparencia International est\u00e1 muy preocupada por la tendencia a socavar las normas democr\u00e1ticas, cuyo resultado es la proliferaci\u00f3n de corrupci\u00f3n, impunidad y autoritarismo. Transparencia Internacional insta a las Naciones Unidas y a la comunidad internacional a que muestren un apoyo en\u00e9rgico a la lucha contra la corrupci\u00f3n en Guatemala y apoyen la continuaci\u00f3n e la independencia del CICCG.<\/p>\n","protected":false},"author":3,"featured_media":75695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-75694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=75694"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75694\/revisions"}],"predecessor-version":[{"id":75696,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/75694\/revisions\/75696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/75695"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=75694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=75694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=75694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}