{"id":76558,"date":"2018-09-12T15:40:26","date_gmt":"2018-09-12T15:40:26","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=76558"},"modified":"2018-09-12T15:40:26","modified_gmt":"2018-09-12T15:40:26","slug":"un-juzgado-popular-para-dominicana-que-confeso-haber-asesinado-al-hijo-de-su-pareja","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/09\/12\/un-juzgado-popular-para-dominicana-que-confeso-haber-asesinado-al-hijo-de-su-pareja\/","title":{"rendered":"Un juzgado popular para dominicana que confes\u00f3 haber asesinado al hijo de su pareja"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-76559 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/09\/image_content_10589759_20180912105225-300x160.jpg\" alt=\"\" width=\"300\" height=\"160\" \/>SANTO DOMINGO. La dominicana detenida por el asesinato de un ni\u00f1o de ocho a\u00f1os en Espa\u00f1a, hijo de su pareja, ser\u00e1 enjuiciada por un jurado popular, acord\u00f3 el juez instructor del crimen, que la ha citado para el 17 de este mes para comunicarle la acusaci\u00f3n en su contra.<\/p>\n<p>Seg\u00fan medios espa\u00f1oles, el magistrado Rafael Soriano dict\u00f3 la resoluci\u00f3n por la que transforma las diligencias previas en procedimiento por tribunal de jurado.<\/p>\n<p>Ana Julia Quezada, autora confesa de la muerte violenta del menor en febrero de este a\u00f1o, en la N\u00edjar, Almer\u00eda, admiti\u00f3 el crimen despu\u00e9s de participar en la b\u00fasqueda del ni\u00f1o que hab\u00eda sido reportado desaparecido.<\/p>\n<p>El cuerpo de Gabriel fue hallado dentro del carro de Quezada, que buscaba la forma de deshacerse del cad\u00e1ver.<\/p>\n<p>Tras ser apresada, la mujer, quien tiene la nacionalidad espa\u00f1ola, dijo que hab\u00eda matado accidentalmente al peque\u00f1o luego de una discusi\u00f3n con \u00e9l. Lo hab\u00eda recogido cuando sali\u00f3 de la casa de su abuela donde estaba de visita. De acuerdo a informes, el menor muri\u00f3 estrangulado y golpeado.<\/p>\n<p>A la citada comparecencia, el d\u00eda 17, est\u00e1n citados el Ministerio Fiscal, y todas las partes en el proceso que se le sigue a la acusada, incluida la acusaci\u00f3n popular que ejerce la Asociaci\u00f3n Clara Campoamor, cita el medio Elperi\u00f3dico.com<\/p>\n<p>El citado diario dice que este tipo de audiencia est\u00e1 prevista en el art\u00edculo 75 de la Ley Org\u00e1nica del Tribunal de Jurado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. La dominicana detenida por el asesinato de un ni\u00f1o de ocho a\u00f1os en Espa\u00f1a, hijo de su pareja, ser\u00e1 enjuiciada por un jurado popular, acord\u00f3 el juez instructor del crimen, que la ha citado para el 17 de este mes para comunicarle la acusaci\u00f3n en su contra. Seg\u00fan medios espa\u00f1oles, el magistrado Rafael Soriano dict\u00f3 la resoluci\u00f3n por la que transforma las diligencias previas en procedimiento por tribunal de jurado. Ana Julia Quezada, autora confesa de la muerte violenta del menor en febrero de este a\u00f1o, en la N\u00edjar, Almer\u00eda, admiti\u00f3 el crimen despu\u00e9s de participar en la b\u00fasqueda del ni\u00f1o que hab\u00eda sido reportado desaparecido. El cuerpo de Gabriel fue hallado dentro del carro de Quezada, que buscaba la forma de deshacerse del cad\u00e1ver. Tras ser apresada, la mujer, quien tiene la nacionalidad espa\u00f1ola, dijo que hab\u00eda matado accidentalmente al peque\u00f1o luego de una discusi\u00f3n con \u00e9l. Lo hab\u00eda recogido cuando sali\u00f3 de la casa de su abuela donde estaba de visita. De acuerdo a informes, el menor muri\u00f3 estrangulado y golpeado. A la citada comparecencia, el d\u00eda 17, est\u00e1n citados el Ministerio Fiscal, y todas las partes en el proceso que se le sigue a la acusada, incluida la acusaci\u00f3n popular que ejerce la Asociaci\u00f3n Clara Campoamor, cita el medio Elperi\u00f3dico.com El citado diario dice que este tipo de audiencia est\u00e1 prevista en el art\u00edculo 75 de la Ley Org\u00e1nica del Tribunal de Jurado.<\/p>\n","protected":false},"author":1,"featured_media":76559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-76558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/76558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=76558"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/76558\/revisions"}],"predecessor-version":[{"id":76560,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/76558\/revisions\/76560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/76559"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=76558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=76558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=76558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}