{"id":79847,"date":"2018-11-06T18:47:16","date_gmt":"2018-11-06T18:47:16","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=79847"},"modified":"2018-11-06T18:47:16","modified_gmt":"2018-11-06T18:47:16","slug":"asesinan-a-tiros-a-dos-jovenes-tras-reclamo-por-una-gorra-robada-en-la-zurza","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/11\/06\/asesinan-a-tiros-a-dos-jovenes-tras-reclamo-por-una-gorra-robada-en-la-zurza\/","title":{"rendered":"Asesinan a tiros a dos j\u00f3venes tras reclamo por una gorra robada en La Zurza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-79848 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/11\/download-7.jpg\" alt=\"\" width=\"315\" height=\"160\" \/>SANTO DOMINGO.- Desconocidos abatieron a tiros a dos j\u00f3venes, en momentos en que una de las v\u00edctimas reclamaba una gorra robada a un familiar, en un hecho registrado en el sector La Zurza de esta ciudad.<\/p>\n<p>La Polic\u00eda indic\u00f3 que los occisos fueron identificados como Joel Antonio Pujols de los Santos (Joel Nariz), de 24 a\u00f1os, y Jes\u00fas Eduardo Lorenzo (Eduardito), de 20 a\u00f1os.<\/p>\n<p>La uniformada se\u00f1al\u00f3 que Pujols de los Santos muri\u00f3 en el Hospital Dar\u00edo Contreras, mientras recib\u00eda atenciones m\u00e9dicas, en tanto que Lorenzo falleci\u00f3 cuando era intervenido en el Moscoso Puello.<\/p>\n<p>El Cuerpo del Orden manifestaron que agentes del Departamento de Investigaciones de Homicidios investigan el caso para apresar a los autores del hecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Desconocidos abatieron a tiros a dos j\u00f3venes, en momentos en que una de las v\u00edctimas reclamaba una gorra robada a un familiar, en un hecho registrado en el sector La Zurza de esta ciudad. La Polic\u00eda indic\u00f3 que los occisos fueron identificados como Joel Antonio Pujols de los Santos (Joel Nariz), de 24 a\u00f1os, y Jes\u00fas Eduardo Lorenzo (Eduardito), de 20 a\u00f1os. La uniformada se\u00f1al\u00f3 que Pujols de los Santos muri\u00f3 en el Hospital Dar\u00edo Contreras, mientras recib\u00eda atenciones m\u00e9dicas, en tanto que Lorenzo falleci\u00f3 cuando era intervenido en el Moscoso Puello. El Cuerpo del Orden manifestaron que agentes del Departamento de Investigaciones de Homicidios investigan el caso para apresar a los autores del hecho.<\/p>\n","protected":false},"author":1,"featured_media":79848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-79847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/79847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=79847"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/79847\/revisions"}],"predecessor-version":[{"id":79849,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/79847\/revisions\/79849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/79848"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=79847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=79847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=79847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}