{"id":80150,"date":"2018-11-12T09:39:34","date_gmt":"2018-11-12T13:39:34","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=80150"},"modified":"2018-11-12T09:39:34","modified_gmt":"2018-11-12T13:39:34","slug":"sns-nombra-observadores-para-supervisar-acciones-que-buscan-reducir-mortalidad-materna-neonatal-2","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/11\/12\/sns-nombra-observadores-para-supervisar-acciones-que-buscan-reducir-mortalidad-materna-neonatal-2\/","title":{"rendered":"SNS nombra observadores para supervisar acciones que buscan reducir mortalidad materna neonatal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-80151 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/11\/UNSET-7-800x351.jpg\" alt=\"\" width=\"438\" height=\"192\" \/>Santo Domingo.\u00a0\u2013 El Servicio Nacional de Salud (SNS) design\u00f3 un equipo de observadores de la pr\u00e1ctica cl\u00ednica, seleccionado y capacitado por el Fondo de las Naciones Unidas para la Infancia (UNICEF), quienes supervisar\u00e1n en los hospitales el cumplimiento de los procedimientos dirigidos a reducir la mortalidad materna neonatal.<\/p>\n<p>El director del SNS, Chanel Rosa Chupany, inform\u00f3 que el equipo estar\u00e1 conformado por 20 t\u00e9cnicos que depender\u00e1n de la direcci\u00f3n ejecutiva del SNS por lo que afirm\u00f3<\/p>\n<p>De su lado, la representante en el pa\u00eds de UNICEFF consider\u00f3 que el pr\u00f3ximo a\u00f1o podr\u00eda ser hist\u00f3rico en la reducci\u00f3n de la mortalidad materna neonatal porque asegur\u00f3 le consta existe la voluntad pol\u00edtica por parte de las autoridades de salud.<\/p>\n<p>El organismo internacional a favor de la infancia donar\u00e1 tabletas y otros equipos a los observadores para la gesti\u00f3n y presentaci\u00f3n de sus informes.<\/p>\n<p>El nuevo personal fue presentado en el marco del taller sobre Metodolog\u00eda para la Mejora Continua de la Calidad y Humanizaci\u00f3n de la Atenci\u00f3n Materna y Neonatal dirigido a directores y t\u00e9cnicos de los Servicios Regionales de Salud (SRS), directores de hospitales y personal de ginecobstetricia, pediatr\u00eda, neonatolog\u00eda, enfermer\u00eda y epidemiologia.<\/p>\n<p>En este escenario, el director del SNS tambi\u00e9n anunci\u00f3 que en enero iniciar\u00e1 la implementaci\u00f3n de servicios de Atenci\u00f3n al Usuario 24\/7 en los hospitales del pa\u00eds con el concepto de designar un personal que trabaje en defensa del ciudadano frente a deficiencias del centro de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.\u00a0\u2013 El Servicio Nacional de Salud (SNS) design\u00f3 un equipo de observadores de la pr\u00e1ctica cl\u00ednica, seleccionado y capacitado por el Fondo de las Naciones Unidas para la Infancia (UNICEF), quienes supervisar\u00e1n en los hospitales el cumplimiento de los procedimientos dirigidos a reducir la mortalidad materna neonatal. El director del SNS, Chanel Rosa Chupany, inform\u00f3 que el equipo estar\u00e1 conformado por 20 t\u00e9cnicos que depender\u00e1n de la direcci\u00f3n ejecutiva del SNS por lo que afirm\u00f3 De su lado, la representante en el pa\u00eds de UNICEFF consider\u00f3 que el pr\u00f3ximo a\u00f1o podr\u00eda ser hist\u00f3rico en la reducci\u00f3n de la mortalidad materna neonatal porque asegur\u00f3 le consta existe la voluntad pol\u00edtica por parte de las autoridades de salud. El organismo internacional a favor de la infancia donar\u00e1 tabletas y otros equipos a los observadores para la gesti\u00f3n y presentaci\u00f3n de sus informes. El nuevo personal fue presentado en el marco del taller sobre Metodolog\u00eda para la Mejora Continua de la Calidad y Humanizaci\u00f3n de la Atenci\u00f3n Materna y Neonatal dirigido a directores y t\u00e9cnicos de los Servicios Regionales de Salud (SRS), directores de hospitales y personal de ginecobstetricia, pediatr\u00eda, neonatolog\u00eda, enfermer\u00eda y epidemiologia. En este escenario, el director del SNS tambi\u00e9n anunci\u00f3 que en enero iniciar\u00e1 la implementaci\u00f3n de servicios de Atenci\u00f3n al Usuario 24\/7 en los hospitales del pa\u00eds con el concepto de designar un personal que trabaje en defensa del ciudadano frente a deficiencias del centro de salud.<\/p>\n","protected":false},"author":1,"featured_media":80151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-80150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=80150"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80150\/revisions"}],"predecessor-version":[{"id":80152,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80150\/revisions\/80152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/80151"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=80150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=80150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=80150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}