{"id":80232,"date":"2018-11-13T11:24:04","date_gmt":"2018-11-13T15:24:04","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=80232"},"modified":"2018-11-13T11:24:04","modified_gmt":"2018-11-13T15:24:04","slug":"direccion-general-de-control-de-drogas-ocupa-345-paquetes-cocaina-en-el-dn","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/11\/13\/direccion-general-de-control-de-drogas-ocupa-345-paquetes-cocaina-en-el-dn\/","title":{"rendered":"Direcci\u00f3n General de Control de Drogas ocupa 345 paquetes coca\u00edna en el DN"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-80233 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/11\/images-8.jpg\" alt=\"\" width=\"402\" height=\"212\" \/>Santo Domingo-La Direcci\u00f3n Nacional de Control de Drogas (DNCD) con el apoyo del Ministerio P\u00fablico y de otras agencias de seguridad e inteligencia, decomisaron 345 paquetes presumiblemente coca\u00edna, cuando eran transportados en un cami\u00f3n en el Distrito Nacional.<\/p>\n<p>Los agentes antinarc\u00f3ticos acompa\u00f1ados de varios fiscales, procedieron a intervenir el veh\u00edculo cuando se realizaba el traslado del alijo y tras una revisi\u00f3n se encontraron en su\u00a0\u00a0interior los paquetes de la sustancia.<\/p>\n<p>Por el caso fue detenido el chofer del cami\u00f3n, se profundiza la investigaci\u00f3n y se activa la localizaci\u00f3n de otros posibles implicados para ser sometidos a la justicia por violaci\u00f3n a la ley 50-88 sobre drogas y sustancias controladas.<\/p>\n<p>Las autoridades ocuparon el cami\u00f3n en el que era transportada la carga, as\u00ed como otras evidencias que fueron enviadas al Ministerio P\u00fablico para los fines correspondientes.<\/p>\n<p>La DNCD informo que los 345 paquetes de la sustancia incautada est\u00e1n siendo enviados al Instituto Nacional de Ciencias Forenses (INACIF) para determinar el tipo y peso exacto de la sustancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-La Direcci\u00f3n Nacional de Control de Drogas (DNCD) con el apoyo del Ministerio P\u00fablico y de otras agencias de seguridad e inteligencia, decomisaron 345 paquetes presumiblemente coca\u00edna, cuando eran transportados en un cami\u00f3n en el Distrito Nacional. Los agentes antinarc\u00f3ticos acompa\u00f1ados de varios fiscales, procedieron a intervenir el veh\u00edculo cuando se realizaba el traslado del alijo y tras una revisi\u00f3n se encontraron en su\u00a0\u00a0interior los paquetes de la sustancia. Por el caso fue detenido el chofer del cami\u00f3n, se profundiza la investigaci\u00f3n y se activa la localizaci\u00f3n de otros posibles implicados para ser sometidos a la justicia por violaci\u00f3n a la ley 50-88 sobre drogas y sustancias controladas. Las autoridades ocuparon el cami\u00f3n en el que era transportada la carga, as\u00ed como otras evidencias que fueron enviadas al Ministerio P\u00fablico para los fines correspondientes. La DNCD informo que los 345 paquetes de la sustancia incautada est\u00e1n siendo enviados al Instituto Nacional de Ciencias Forenses (INACIF) para determinar el tipo y peso exacto de la sustancia.<\/p>\n","protected":false},"author":1,"featured_media":80233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-80232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=80232"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80232\/revisions"}],"predecessor-version":[{"id":80234,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80232\/revisions\/80234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/80233"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=80232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=80232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=80232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}