{"id":80739,"date":"2018-11-19T13:48:08","date_gmt":"2018-11-19T17:48:08","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=80739"},"modified":"2018-11-19T13:48:08","modified_gmt":"2018-11-19T17:48:08","slug":"detienen-haitiano-por-asaltar-y-golpear-a-una-mujer-en-su-residencia","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/11\/19\/detienen-haitiano-por-asaltar-y-golpear-a-una-mujer-en-su-residencia\/","title":{"rendered":"Detienen haitiano por asaltar y golpear a una mujer en su residencia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-80741 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/11\/19f585a2-image_content_9208423_20171205174513.jpg\" alt=\"\" width=\"415\" height=\"221\" \/>Santo Domingo-La Polic\u00eda Nacional inform\u00f3 este lunes que apres\u00f3 en Dajab\u00f3n a uno de cuatro haitianos acusados de penetrar a la vivienda de una pareja dominicana, donde golpearon salvajemente a la mujer que estaba sola, robaron un rev\u00f3lver y una cartera con documentos personales.<\/p>\n<p>El detenido de nacionalidad haitiana fue identificado como Nene Pie, de\u00a0 19 a\u00f1os, quien vive \u00a0pr\u00f3ximo al estadio de b\u00e9isbol de la secci\u00f3n Lajas Esper\u00f3n, donde ocurri\u00f3 el hecho, alrededor de las 7:00 de la ma\u00f1ana de ayer.<\/p>\n<p>De acuerdo con una nota de prensa, los atacantes agredieron a la mujer, de 50 a\u00f1os, quien, de acuerdo a las declaraciones de su c\u00f3nyuge, \u00e9sta permanece inconsciente en una cl\u00ednica privada de Dajab\u00f3n, debido a golpes diversos y a fractura de la segunda v\u00e9rtebra cervical.<\/p>\n<p>El esposo de la afectada dijo a las autoridades que su pareja estaba sola, con la puerta abierta, situaci\u00f3n que los haitianos aprovecharon para entrar a la vivienda, la golpearon, la tiraron al suelo y trataron de ahorcarla, dej\u00e1ndola por muerta.<\/p>\n<p>La Polic\u00eda Nacional agreg\u00f3 trabaja en la identificaci\u00f3n de los otros tres \u00a0participantes en el hecho, para ponerlos junto al detenido bajo a disposici\u00f3n de la justicia a trav\u00e9s del Ministerio P\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-La Polic\u00eda Nacional inform\u00f3 este lunes que apres\u00f3 en Dajab\u00f3n a uno de cuatro haitianos acusados de penetrar a la vivienda de una pareja dominicana, donde golpearon salvajemente a la mujer que estaba sola, robaron un rev\u00f3lver y una cartera con documentos personales. El detenido de nacionalidad haitiana fue identificado como Nene Pie, de\u00a0 19 a\u00f1os, quien vive \u00a0pr\u00f3ximo al estadio de b\u00e9isbol de la secci\u00f3n Lajas Esper\u00f3n, donde ocurri\u00f3 el hecho, alrededor de las 7:00 de la ma\u00f1ana de ayer. De acuerdo con una nota de prensa, los atacantes agredieron a la mujer, de 50 a\u00f1os, quien, de acuerdo a las declaraciones de su c\u00f3nyuge, \u00e9sta permanece inconsciente en una cl\u00ednica privada de Dajab\u00f3n, debido a golpes diversos y a fractura de la segunda v\u00e9rtebra cervical. El esposo de la afectada dijo a las autoridades que su pareja estaba sola, con la puerta abierta, situaci\u00f3n que los haitianos aprovecharon para entrar a la vivienda, la golpearon, la tiraron al suelo y trataron de ahorcarla, dej\u00e1ndola por muerta. La Polic\u00eda Nacional agreg\u00f3 trabaja en la identificaci\u00f3n de los otros tres \u00a0participantes en el hecho, para ponerlos junto al detenido bajo a disposici\u00f3n de la justicia a trav\u00e9s del Ministerio P\u00fablico. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":80741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-80739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=80739"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80739\/revisions"}],"predecessor-version":[{"id":80742,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80739\/revisions\/80742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/80741"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=80739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=80739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=80739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}