{"id":80876,"date":"2018-11-21T13:15:24","date_gmt":"2018-11-21T17:15:24","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=80876"},"modified":"2018-11-21T13:15:24","modified_gmt":"2018-11-21T17:15:24","slug":"ray-guevara-el-tribunal-constitucional-es-absolutamente-independiente","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/11\/21\/ray-guevara-el-tribunal-constitucional-es-absolutamente-independiente\/","title":{"rendered":"Ray Guevara el Tribunal Constitucional es absolutamente independiente"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-80883 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/11\/Magistrado-Milton-Ray-Guevara-presidente-del-TC-junto-a-directivos-de-Anje-800x505.jpeg\" alt=\"\" width=\"408\" height=\"257\" \/>Santo Domingo-El magistrado presidente del Tribunal Constitucional (TC) doctor Milton Ray Guevara, afirm\u00f3 que el TC es un tribunal absolutamente independiente y que ha cumplido su dif\u00edcil tarea sin inferencias en el quehacer de sus jueces.<\/p>\n<p>Al emitir consideraciones sobre la reprochada independencia del poder judicial, el magistrado expres\u00f3 que \u201ca este Tribunal Constitucional nadie, absolutamente nadie, puede decirle por d\u00f3nde orienta sus decisiones. All\u00ed los jueces hacen lo que ellos entienden que deben hacer\u201d, subray\u00f3<\/p>\n<p>Ray Guevara hizo esta aseveraci\u00f3n al dictar la conferencia de apertura del Foro \u201cLa Participaci\u00f3n, Un Derecho Ciudadano\u201d, organizada por la Asociaci\u00f3n Nacional de J\u00f3venes Empresarios (ANJE), y en el que participaron connotados juristas, l\u00edderes de opini\u00f3n, congresistas y l\u00edderes municipales.<\/p>\n<p>En la conferencia, titulada \u201cNuevos Derechos de la Ciudadan\u00eda en la Constituci\u00f3n y el Rol de Garante del Tribunal Constitucional\u201d, el magistrado analiz\u00f3 la democracia participativa a partir de la Constituci\u00f3n de 2010 y los nuevos derechos y mecanismos de participaci\u00f3n ciudadana que esta confiere, tales como el plebiscito, el referendo y la iniciativa legislativa popular.<\/p>\n<p>Dijo que \u201cLo m\u00e1s importante que tiene la Constituci\u00f3n de 2010, que no es suficientemente conocida por el pueblo dominicano y no se ha querido que sea suficientemente conocida, es el poder ciudadano\u201d, destacando que este poder supone el cumplimiento completo de la Constituci\u00f3n.<\/p>\n<p>El presidente del TC comparti\u00f3 estas impresiones al participar como orador principal en el Foro ANJE sobre Participaci\u00f3n Ciudadana, iniciativa que se organiza con el prop\u00f3sito de fortalecer la institucionalidad en el pa\u00eds y fomentar el intercambio de ideas con miras al desarrollo nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El magistrado presidente del Tribunal Constitucional (TC) doctor Milton Ray Guevara, afirm\u00f3 que el TC es un tribunal absolutamente independiente y que ha cumplido su dif\u00edcil tarea sin inferencias en el quehacer de sus jueces. Al emitir consideraciones sobre la reprochada independencia del poder judicial, el magistrado expres\u00f3 que \u201ca este Tribunal Constitucional nadie, absolutamente nadie, puede decirle por d\u00f3nde orienta sus decisiones. All\u00ed los jueces hacen lo que ellos entienden que deben hacer\u201d, subray\u00f3 Ray Guevara hizo esta aseveraci\u00f3n al dictar la conferencia de apertura del Foro \u201cLa Participaci\u00f3n, Un Derecho Ciudadano\u201d, organizada por la Asociaci\u00f3n Nacional de J\u00f3venes Empresarios (ANJE), y en el que participaron connotados juristas, l\u00edderes de opini\u00f3n, congresistas y l\u00edderes municipales. En la conferencia, titulada \u201cNuevos Derechos de la Ciudadan\u00eda en la Constituci\u00f3n y el Rol de Garante del Tribunal Constitucional\u201d, el magistrado analiz\u00f3 la democracia participativa a partir de la Constituci\u00f3n de 2010 y los nuevos derechos y mecanismos de participaci\u00f3n ciudadana que esta confiere, tales como el plebiscito, el referendo y la iniciativa legislativa popular. Dijo que \u201cLo m\u00e1s importante que tiene la Constituci\u00f3n de 2010, que no es suficientemente conocida por el pueblo dominicano y no se ha querido que sea suficientemente conocida, es el poder ciudadano\u201d, destacando que este poder supone el cumplimiento completo de la Constituci\u00f3n. El presidente del TC comparti\u00f3 estas impresiones al participar como orador principal en el Foro ANJE sobre Participaci\u00f3n Ciudadana, iniciativa que se organiza con el prop\u00f3sito de fortalecer la institucionalidad en el pa\u00eds y fomentar el intercambio de ideas con miras al desarrollo nacional.<\/p>\n","protected":false},"author":1,"featured_media":80883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-80876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=80876"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80876\/revisions"}],"predecessor-version":[{"id":80884,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/80876\/revisions\/80884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/80883"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=80876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=80876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=80876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}