{"id":82252,"date":"2018-12-17T14:12:51","date_gmt":"2018-12-17T18:12:51","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=82252"},"modified":"2018-12-17T14:12:51","modified_gmt":"2018-12-17T18:12:51","slug":"ceccom-ofrece-agasajo-navideno-a-decenas-de-soldados-disfrutando-una-noche-de-gran-alegria","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2018\/12\/17\/ceccom-ofrece-agasajo-navideno-a-decenas-de-soldados-disfrutando-una-noche-de-gran-alegria\/","title":{"rendered":"CECCOM ofrece agasajo navide\u00f1o a decenas de soldados, disfrutando una noche de gran alegr\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-82253 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2018\/12\/UNSET-8-800x800.jpg\" alt=\"\" width=\"599\" height=\"599\" \/>Santo Domingo-El Cuerpo Especializado de Control de Combustible (CECCOM), brind\u00f3 una noche de entusiasmo y diversi\u00f3n a todo su personal en un encuentro en el cual fueron rifados un autom\u00f3vil, dinero en efectivo y regalos a los soldados quienes deleitaron con m\u00fasica de diversos artistas.<\/p>\n<p>Asimismo, el encuentro se inici\u00f3 a las 7:00 pm, del s\u00e1bado 15 de diciembre, en el sal\u00f3n restauraci\u00f3n de Ministerio de Defensa, donde se concentraron los militares con sus esposas, tras recibir boletos para rifas y comestibles.<\/p>\n<p>En tanto, la festividad fue encabezada por el coronel piloto, Wascar Dario Gonz\u00e1lez Payano, FARD (DEM), director general del CECCOM.<\/p>\n<p>Adem\u00e1s, oficiales generales y superiores, as\u00ed como la plana mayor disfrutaron junto a los oficiales subalternos, alistados y asimilados que se dieron cita en el lugar.<\/p>\n<p>Orquestas e int\u00e9rpretes amenizaron la fiesta con m\u00fasica y humor, con la actuaci\u00f3n del Invencible de la Bachata, el Poeta Callejero, la banda de m\u00fasica del Ej\u00e9rcito, asi como tambi\u00e9n de la Armada, varios comediantes de telemicro, entre otros que merecieron grandes aplausos.<\/p>\n<p>El agasajo navide\u00f1o, del CECCOM, es una tradici\u00f3n que une en la alegr\u00eda a sus miembros todos los a\u00f1os, con las rifas de veh\u00edculos, dinero en efectivo y otros premios, fortaleciendo los lazos de hermandad y alegrando las festividades de la \u00e9poca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El Cuerpo Especializado de Control de Combustible (CECCOM), brind\u00f3 una noche de entusiasmo y diversi\u00f3n a todo su personal en un encuentro en el cual fueron rifados un autom\u00f3vil, dinero en efectivo y regalos a los soldados quienes deleitaron con m\u00fasica de diversos artistas. Asimismo, el encuentro se inici\u00f3 a las 7:00 pm, del s\u00e1bado 15 de diciembre, en el sal\u00f3n restauraci\u00f3n de Ministerio de Defensa, donde se concentraron los militares con sus esposas, tras recibir boletos para rifas y comestibles. En tanto, la festividad fue encabezada por el coronel piloto, Wascar Dario Gonz\u00e1lez Payano, FARD (DEM), director general del CECCOM. Adem\u00e1s, oficiales generales y superiores, as\u00ed como la plana mayor disfrutaron junto a los oficiales subalternos, alistados y asimilados que se dieron cita en el lugar. Orquestas e int\u00e9rpretes amenizaron la fiesta con m\u00fasica y humor, con la actuaci\u00f3n del Invencible de la Bachata, el Poeta Callejero, la banda de m\u00fasica del Ej\u00e9rcito, asi como tambi\u00e9n de la Armada, varios comediantes de telemicro, entre otros que merecieron grandes aplausos. El agasajo navide\u00f1o, del CECCOM, es una tradici\u00f3n que une en la alegr\u00eda a sus miembros todos los a\u00f1os, con las rifas de veh\u00edculos, dinero en efectivo y otros premios, fortaleciendo los lazos de hermandad y alegrando las festividades de la \u00e9poca.<\/p>\n","protected":false},"author":1,"featured_media":82253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-82252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/82252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=82252"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/82252\/revisions"}],"predecessor-version":[{"id":82254,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/82252\/revisions\/82254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/82253"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=82252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=82252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=82252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}