{"id":83054,"date":"2019-01-07T11:11:06","date_gmt":"2019-01-07T15:11:06","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83054"},"modified":"2019-01-07T11:20:47","modified_gmt":"2019-01-07T15:20:47","slug":"miembros-del-falpo-lanzan-excrementos-a-la-suprema-corte-justicia","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/07\/miembros-del-falpo-lanzan-excrementos-a-la-suprema-corte-justicia\/","title":{"rendered":"Miembros del FALPO lanzan excrementos a la Suprema Corte Justicia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-83062 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/364082f9-cf41-4612-9dcd-e360d8555c60-1-800x440.jpg\" alt=\"\" width=\"589\" height=\"324\" \/>Santo Domingo-Miembros del Frente Amplio de Lucha Popular lanzaron fundas con excrementos al edificio que aloja a la Suprema Corte de Justicia y la Procuradur\u00eda General de la Rep\u00fablica, por lo cual fueron detenidos cinco hombres y dos mujeres.<\/p>\n<p>\u201cEn el d\u00eda de hoy que mal se celebra el D\u00eda del Poder Judicial el FALPO y las ligas populares hemos asumido una acci\u00f3n para llamar la atenci\u00f3n del pueblo dominicano. Hemos decidido lanzar mierda justamente a este edificio porque entendemos que esta es una justicia de mierda\u201d, dijo el vocero del FALPO, Gabriel S\u00e1nchez, mientras era llevado detenido.<\/p>\n<p>El incidente no provoc\u00f3 disturbios en el momento en que eran llevados detenidos los j\u00f3venes, quienes rechazaron que sea una actitud vand\u00e1lica lo que acababan de realizar.<\/p>\n<p>Justamente, en ese momento, los jueces asist\u00edan a una misa en la iglesia de la Paz, pr\u00f3ximo al edificio de la Suprema Corte, con motivo de la conmemoraci\u00f3n del D\u00eda del Poder Judicial. A las 11:15 se tiene previsto que acudan a la sala augusta de la citada alta corte para escuchar el discurso del presidente de la Suprema Corte de Justicia, Mariano Germ\u00e1n, al que asistir\u00e1 el presidente de la Rep\u00fablica, Danilo Medina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-Miembros del Frente Amplio de Lucha Popular lanzaron fundas con excrementos al edificio que aloja a la Suprema Corte de Justicia y la Procuradur\u00eda General de la Rep\u00fablica, por lo cual fueron detenidos cinco hombres y dos mujeres. \u201cEn el d\u00eda de hoy que mal se celebra el D\u00eda del Poder Judicial el FALPO y las ligas populares hemos asumido una acci\u00f3n para llamar la atenci\u00f3n del pueblo dominicano. Hemos decidido lanzar mierda justamente a este edificio porque entendemos que esta es una justicia de mierda\u201d, dijo el vocero del FALPO, Gabriel S\u00e1nchez, mientras era llevado detenido. El incidente no provoc\u00f3 disturbios en el momento en que eran llevados detenidos los j\u00f3venes, quienes rechazaron que sea una actitud vand\u00e1lica lo que acababan de realizar. Justamente, en ese momento, los jueces asist\u00edan a una misa en la iglesia de la Paz, pr\u00f3ximo al edificio de la Suprema Corte, con motivo de la conmemoraci\u00f3n del D\u00eda del Poder Judicial. A las 11:15 se tiene previsto que acudan a la sala augusta de la citada alta corte para escuchar el discurso del presidente de la Suprema Corte de Justicia, Mariano Germ\u00e1n, al que asistir\u00e1 el presidente de la Rep\u00fablica, Danilo Medina.<\/p>\n","protected":false},"author":1,"featured_media":83055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83054"}],"version-history":[{"count":6,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83054\/revisions"}],"predecessor-version":[{"id":83065,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83054\/revisions\/83065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83055"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}