{"id":83352,"date":"2019-01-11T09:24:30","date_gmt":"2019-01-11T13:24:30","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83352"},"modified":"2019-01-11T09:24:30","modified_gmt":"2019-01-11T13:24:30","slug":"dictan-pena-maxima-a-chaman-chacra-confeso-asesino-de-pareja-y-tres-hijastros","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/11\/dictan-pena-maxima-a-chaman-chacra-confeso-asesino-de-pareja-y-tres-hijastros\/","title":{"rendered":"Dictan pena m\u00e1xima a \u201cCham\u00e1n Chacra\u201d, confeso asesino de pareja y tres hijastros"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-83353 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/download-13.jpg\" alt=\"\" width=\"440\" height=\"293\" \/>Santo Domingo-Un tribunal de primera instancia impuso este mi\u00e9rcoles la pena m\u00e1xima de 30 a\u00f1os de reclusi\u00f3n a un hombre que mat\u00f3 a su compa\u00f1era sentimental y a los tres hijos de esta en febrero del a\u00f1o pasado en un barrio de la capital, en un hecho que estremeci\u00f3 a la sociedad.<\/p>\n<p>V\u00edctor Alexander Portorreal Mendoza \u201cCham\u00e1n Chacra\u201d fue condenado por asesinar a su pareja Reyna Isabel Encarnaci\u00f3n Gonz\u00e1lez y a sus tres hijastros menores de edad, entre ellos dos ni\u00f1as de quienes abus\u00f3 sexualmente luego de asesinarlas, seg\u00fan el expediente acusador.<\/p>\n<p>Un d\u00eda despu\u00e9s de dar muerte a su concubina y a las dos ni\u00f1as, Portorreal tambi\u00e9n asesin\u00f3 al tercer hijo, un ni\u00f1o de nueve a\u00f1os, en la casa donde viv\u00edan los cinco en el sector Enriquillo del Distrito Nacional.<\/p>\n<p>El Ministerio P\u00fablico determin\u00f3 que Portorreal cometi\u00f3 el cu\u00e1druple asesinato luego de que su pareja descubriera que hab\u00eda abusado sexualmente de una de las ni\u00f1as.<\/p>\n<p>El Primer Tribunal Colegiado del Distrito Nacional orden\u00f3 que el condenado cumpla la pena en la c\u00e1rcel p\u00fablica de la provincia de San pedro de Macor\u00eds.<\/p>\n<p>Tras consumar los hechos, Portorreal se fue a la playa con una amiga y luego divag\u00f3 por algunos puntos de la ciudad de Santo Domingo.<\/p>\n<p>En la audiencia de hoy el condenado pidi\u00f3 perd\u00f3n a la sociedad dominicana y a la familia de las v\u00edctimas y afirm\u00f3 que no se quit\u00f3 la vida porque ni as\u00ed pod\u00eda pagar lo que hizo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-Un tribunal de primera instancia impuso este mi\u00e9rcoles la pena m\u00e1xima de 30 a\u00f1os de reclusi\u00f3n a un hombre que mat\u00f3 a su compa\u00f1era sentimental y a los tres hijos de esta en febrero del a\u00f1o pasado en un barrio de la capital, en un hecho que estremeci\u00f3 a la sociedad. V\u00edctor Alexander Portorreal Mendoza \u201cCham\u00e1n Chacra\u201d fue condenado por asesinar a su pareja Reyna Isabel Encarnaci\u00f3n Gonz\u00e1lez y a sus tres hijastros menores de edad, entre ellos dos ni\u00f1as de quienes abus\u00f3 sexualmente luego de asesinarlas, seg\u00fan el expediente acusador. Un d\u00eda despu\u00e9s de dar muerte a su concubina y a las dos ni\u00f1as, Portorreal tambi\u00e9n asesin\u00f3 al tercer hijo, un ni\u00f1o de nueve a\u00f1os, en la casa donde viv\u00edan los cinco en el sector Enriquillo del Distrito Nacional. El Ministerio P\u00fablico determin\u00f3 que Portorreal cometi\u00f3 el cu\u00e1druple asesinato luego de que su pareja descubriera que hab\u00eda abusado sexualmente de una de las ni\u00f1as. El Primer Tribunal Colegiado del Distrito Nacional orden\u00f3 que el condenado cumpla la pena en la c\u00e1rcel p\u00fablica de la provincia de San pedro de Macor\u00eds. Tras consumar los hechos, Portorreal se fue a la playa con una amiga y luego divag\u00f3 por algunos puntos de la ciudad de Santo Domingo. En la audiencia de hoy el condenado pidi\u00f3 perd\u00f3n a la sociedad dominicana y a la familia de las v\u00edctimas y afirm\u00f3 que no se quit\u00f3 la vida porque ni as\u00ed pod\u00eda pagar lo que hizo.<\/p>\n","protected":false},"author":1,"featured_media":83353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83352"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83352\/revisions"}],"predecessor-version":[{"id":83354,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83352\/revisions\/83354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83353"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}