{"id":83386,"date":"2019-01-11T13:15:26","date_gmt":"2019-01-11T17:15:26","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83386"},"modified":"2019-01-11T13:15:49","modified_gmt":"2019-01-11T17:15:49","slug":"presidente-adoco-dice-la-corrupcion-se-les-a-salido-de-la-mano-a-las-autoridades","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/11\/presidente-adoco-dice-la-corrupcion-se-les-a-salido-de-la-mano-a-las-autoridades\/","title":{"rendered":"Presidente ADOCO dice: la corrupci\u00f3n se les a salido de la mano a las autoridades"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-83387 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/Julio-Cesar-De-la-Rosa-Tiburcio-Coordinador-General-ADOCCO.jpg\" alt=\"\" width=\"296\" height=\"340\" \/>Santo Domingo-El presidente de la Aliansa Dominicana Contra la Corrupci\u00f3n, Julio C\u00e9sar de la Rosa, expreso que el micro-trafico se le ha salido de las manos a las autoridades policiales.<\/p>\n<p>Julio Cesar de la Rosa, resalt\u00f3 acerca de la complicidad que tienen algunos miembros de organismos militares, en el cual no se mueve un gramo sin autorizaci\u00f3n de los mismos.<\/p>\n<p>En ese sentido, tambi\u00e9n critic\u00f3 las labores por parte de las instituciones como la Direcci\u00f3n Nacional de Control de Drogas y el de la DICAN, que seg\u00fan de la Rosa no se ve en resultados para el combate de flagelo del narcotr\u00e1fico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El presidente de la Aliansa Dominicana Contra la Corrupci\u00f3n, Julio C\u00e9sar de la Rosa, expreso que el micro-trafico se le ha salido de las manos a las autoridades policiales. Julio Cesar de la Rosa, resalt\u00f3 acerca de la complicidad que tienen algunos miembros de organismos militares, en el cual no se mueve un gramo sin autorizaci\u00f3n de los mismos. En ese sentido, tambi\u00e9n critic\u00f3 las labores por parte de las instituciones como la Direcci\u00f3n Nacional de Control de Drogas y el de la DICAN, que seg\u00fan de la Rosa no se ve en resultados para el combate de flagelo del narcotr\u00e1fico.<\/p>\n","protected":false},"author":1,"featured_media":83387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83386"}],"version-history":[{"count":2,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83386\/revisions"}],"predecessor-version":[{"id":83389,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83386\/revisions\/83389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83387"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}