{"id":83435,"date":"2019-01-14T10:39:30","date_gmt":"2019-01-14T14:39:30","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83435"},"modified":"2019-01-14T10:39:30","modified_gmt":"2019-01-14T14:39:30","slug":"al-muerzo-con-guterre-canciller-miguel-vargas-afirma-retos-de-la-paz-y-seguridad-reclaman-decisiones-coherentes","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/14\/al-muerzo-con-guterre-canciller-miguel-vargas-afirma-retos-de-la-paz-y-seguridad-reclaman-decisiones-coherentes\/","title":{"rendered":"Al muerzo con Guterre Canciller Miguel Vargas afirma retos de la paz y seguridad reclaman decisiones coherentes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-83436 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/canciller-Miguel-Vargas-y-Ant\u00f3nio-Guterres-800x534.jpg\" alt=\"\" width=\"715\" height=\"477\" \/>Santo Domingo- El ministro de Relaciones Exteriores, Miguel Vargas, particip\u00f3 este viernes en un almuerzo ofrecido por el secretario general de la Organizaci\u00f3n de las Naciones Unidas (ONU), Ant\u00f3nio Guterres, en apoyo a la presidencia temporal que Rep\u00fablica Dominicana ejerce en el Consejo de Seguridad.<\/p>\n<p>Al dirigirse a los representantes de los quince pa\u00edses miembros de ese \u00f3rgano de la ONU, el canciller dominicano advirti\u00f3 que los retos actuales reclaman \u201cdecisiones coherentes\u201d con el mantenimiento de la paz y la seguridad en el mundo.<\/p>\n<p>Asegur\u00f3 que una de las prioridades de Rep\u00fablica Dominicana es la de \u201cevitar que la aprobaci\u00f3n de resoluciones para atajar amenazas apremiantes, siga asumiendo la forma de una carrera de obst\u00e1culos\u201d.<\/p>\n<p>En consecuencia, explic\u00f3, la agenda dominicana en el Consejo de Seguridad se enfocar\u00e1 en tender puentes en el proceso de toma de decisiones y \u201ctejer consensos con la paciencia, la creatividad y la dedicaci\u00f3n que sean necesarios\u201d.<\/p>\n<p>Asimismo, el canciller Vargas ratific\u00f3 que el pa\u00eds impulsar\u00e1 el an\u00e1lisis y toma de decisiones respecto al impacto de los desastres naturales y la degradaci\u00f3n medioambiental sobre la paz, la seguridad y el desarrollo.<\/p>\n<p>Igualmente, el ministro Vargas se refiri\u00f3 a otros asuntos pendientes, tales como \u201cel avance del proceso de reforma pol\u00edtica en Siria, las gestiones de paz\u00a0en Yemen, la situaci\u00f3n agravada en Afganist\u00e1n fruto, en parte, de una sequ\u00eda prolongada.\u201d<\/p>\n<p>Tambi\u00e9n mencion\u00f3 la\u00a0fragilidad de la situaci\u00f3n en Somalia y \u201cla incertidumbre generada por las cuestionadas elecciones en el Congo, paso crucial para la democratizaci\u00f3n de ese importante pa\u00eds africano.\u201d<\/p>\n<p>Durante el almuerzo en la ONU, el canciller estuvo acompa\u00f1ado de Jos\u00e9 Singer, embajador dominicano en misi\u00f3n especial ante el Consejo de Seguridad. Adem\u00e1s, el embajador Francisco Cortorreal, representante permanente de Rep\u00fablica Dominicana en la ONU.<\/p>\n<p>Rep\u00fablica Dominicana ingres\u00f3 a este \u00f3rgano, como miembro no permanente, el pasado primero de enero, para el per\u00edodo 2019-2020. Este mes est\u00e1 a cargo de la presidencia temporal de esa instancia de la ONU, cuya misi\u00f3n es velar por la paz y la seguridad en el mundo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo- El ministro de Relaciones Exteriores, Miguel Vargas, particip\u00f3 este viernes en un almuerzo ofrecido por el secretario general de la Organizaci\u00f3n de las Naciones Unidas (ONU), Ant\u00f3nio Guterres, en apoyo a la presidencia temporal que Rep\u00fablica Dominicana ejerce en el Consejo de Seguridad. Al dirigirse a los representantes de los quince pa\u00edses miembros de ese \u00f3rgano de la ONU, el canciller dominicano advirti\u00f3 que los retos actuales reclaman \u201cdecisiones coherentes\u201d con el mantenimiento de la paz y la seguridad en el mundo. Asegur\u00f3 que una de las prioridades de Rep\u00fablica Dominicana es la de \u201cevitar que la aprobaci\u00f3n de resoluciones para atajar amenazas apremiantes, siga asumiendo la forma de una carrera de obst\u00e1culos\u201d. En consecuencia, explic\u00f3, la agenda dominicana en el Consejo de Seguridad se enfocar\u00e1 en tender puentes en el proceso de toma de decisiones y \u201ctejer consensos con la paciencia, la creatividad y la dedicaci\u00f3n que sean necesarios\u201d. Asimismo, el canciller Vargas ratific\u00f3 que el pa\u00eds impulsar\u00e1 el an\u00e1lisis y toma de decisiones respecto al impacto de los desastres naturales y la degradaci\u00f3n medioambiental sobre la paz, la seguridad y el desarrollo. Igualmente, el ministro Vargas se refiri\u00f3 a otros asuntos pendientes, tales como \u201cel avance del proceso de reforma pol\u00edtica en Siria, las gestiones de paz\u00a0en Yemen, la situaci\u00f3n agravada en Afganist\u00e1n fruto, en parte, de una sequ\u00eda prolongada.\u201d Tambi\u00e9n mencion\u00f3 la\u00a0fragilidad de la situaci\u00f3n en Somalia y \u201cla incertidumbre generada por las cuestionadas elecciones en el Congo, paso crucial para la democratizaci\u00f3n de ese importante pa\u00eds africano.\u201d Durante el almuerzo en la ONU, el canciller estuvo acompa\u00f1ado de Jos\u00e9 Singer, embajador dominicano en misi\u00f3n especial ante el Consejo de Seguridad. Adem\u00e1s, el embajador Francisco Cortorreal, representante permanente de Rep\u00fablica Dominicana en la ONU. Rep\u00fablica Dominicana ingres\u00f3 a este \u00f3rgano, como miembro no permanente, el pasado primero de enero, para el per\u00edodo 2019-2020. Este mes est\u00e1 a cargo de la presidencia temporal de esa instancia de la ONU, cuya misi\u00f3n es velar por la paz y la seguridad en el mundo<\/p>\n","protected":false},"author":1,"featured_media":83436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83435"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83435\/revisions"}],"predecessor-version":[{"id":83437,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83435\/revisions\/83437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83436"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}