{"id":83509,"date":"2019-01-15T10:09:39","date_gmt":"2019-01-15T14:09:39","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83509"},"modified":"2019-01-15T10:09:39","modified_gmt":"2019-01-15T14:09:39","slug":"mem-y-pequenos-mineros-coordinan-acciones-para-mejorar-explotacion-de-larimar","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/15\/mem-y-pequenos-mineros-coordinan-acciones-para-mejorar-explotacion-de-larimar\/","title":{"rendered":"MEM y peque\u00f1os mineros coordinan acciones para mejorar explotaci\u00f3n de Larimar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-83510 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/DSC_2376-800x421.jpg\" alt=\"\" width=\"627\" height=\"330\" \/>Santo Domingo-El ministro de Energ\u00eda y Minas, Antonio Isa Conde, sostuvo la primera reuni\u00f3n de trabajo de 2019 con cooperativas y asociaciones mineras para impulsar la miner\u00eda de larimar, luego del decreto 431-18 que ordena a esta instituci\u00f3n regular la explotaci\u00f3n, permisolog\u00eda, procesamiento y exportaci\u00f3n tanto de esta piedra como del \u00e1mbar.<\/p>\n<p>La interacci\u00f3n de Isa Conde se produjo con Luis Arboleda, presidente de la Cooperativa Larimar Barahona; Salvador Minier C., presidente de la Asociaci\u00f3n Nuestra Se\u00f1ora de Las Mercedes; Jairo Feliz, de la Cooperativa Bahoruco; Juan Feliz M\u00e9ndez, presidente del Consejo de la Cooperativa Larimar Las Filipinas.<\/p>\n<p>Luego de que el Poder Ejecutivo publicara el citado decreto, el MEM emiti\u00f3 la resoluci\u00f3n R-MEM-REG-040-2018, mediante la cual orden\u00f3 al Viceministerio de Minas y a la Direcci\u00f3n General de Miner\u00eda realizar un inventario de las cantidades de \u00e1mbar y larimar extra\u00eddas y almacenadas por disposiciones previas que prohib\u00edan la exportaci\u00f3n en bruto. Igualmente, concede un plazo de seis meses para la exportaci\u00f3n de hasta el 80% del \u00e1mbar y el larimar inventariado.<\/p>\n<p>En la reuni\u00f3n participaron el Director General de Miner\u00eda, Alexander Medina; el viceministro de Minas Lisandro Lemberg; la Directora de Programas Especiales del MEM, Yris Nelsi Gonz\u00e1lez; la Directora Jur\u00eddica Raysa Paulino y el Director de Gesti\u00f3n Social, Fulsis Yovanny Melo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El ministro de Energ\u00eda y Minas, Antonio Isa Conde, sostuvo la primera reuni\u00f3n de trabajo de 2019 con cooperativas y asociaciones mineras para impulsar la miner\u00eda de larimar, luego del decreto 431-18 que ordena a esta instituci\u00f3n regular la explotaci\u00f3n, permisolog\u00eda, procesamiento y exportaci\u00f3n tanto de esta piedra como del \u00e1mbar. La interacci\u00f3n de Isa Conde se produjo con Luis Arboleda, presidente de la Cooperativa Larimar Barahona; Salvador Minier C., presidente de la Asociaci\u00f3n Nuestra Se\u00f1ora de Las Mercedes; Jairo Feliz, de la Cooperativa Bahoruco; Juan Feliz M\u00e9ndez, presidente del Consejo de la Cooperativa Larimar Las Filipinas. Luego de que el Poder Ejecutivo publicara el citado decreto, el MEM emiti\u00f3 la resoluci\u00f3n R-MEM-REG-040-2018, mediante la cual orden\u00f3 al Viceministerio de Minas y a la Direcci\u00f3n General de Miner\u00eda realizar un inventario de las cantidades de \u00e1mbar y larimar extra\u00eddas y almacenadas por disposiciones previas que prohib\u00edan la exportaci\u00f3n en bruto. Igualmente, concede un plazo de seis meses para la exportaci\u00f3n de hasta el 80% del \u00e1mbar y el larimar inventariado. En la reuni\u00f3n participaron el Director General de Miner\u00eda, Alexander Medina; el viceministro de Minas Lisandro Lemberg; la Directora de Programas Especiales del MEM, Yris Nelsi Gonz\u00e1lez; la Directora Jur\u00eddica Raysa Paulino y el Director de Gesti\u00f3n Social, Fulsis Yovanny Melo.<\/p>\n","protected":false},"author":1,"featured_media":83510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83509"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83509\/revisions"}],"predecessor-version":[{"id":83511,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83509\/revisions\/83511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83510"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}