{"id":83657,"date":"2019-01-16T14:13:34","date_gmt":"2019-01-16T18:13:34","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=83657"},"modified":"2019-01-16T14:15:08","modified_gmt":"2019-01-16T18:15:08","slug":"83657","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/01\/16\/83657\/","title":{"rendered":"Familia Rosario reclama fondos de herencia frente al Palacio Nacional"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83658 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/01\/herencia-640x376.jpg\" alt=\"\" width=\"640\" height=\"376\" \/>Santo Domingo-Cientos de personas pertenecientes a la familia Rosario se manifestaron la ma\u00f1ana de este mi\u00e9rcoles frente al Palacio Nacional en respuesta de que las autoridades gestionen los fondos de una supuesta herencia millonaria dejada por sus ancestros y que afirman est\u00e1n en el pa\u00eds desde hace m\u00e1s de seis meses y les pertenece.<\/p>\n<p>Dijeron, adem\u00e1s, que han acudido a la embajada de Espa\u00f1a en Rep\u00fablica Dominicana en busca de mediaci\u00f3n y otras instancias internacionales, pero que creen ya es un asunto del Estado dominicano, raz\u00f3n por la que pidieron la intervenci\u00f3n del mandatario Danilo Medina.<\/p>\n<p>Unos 13 trillones de euros es el monto que reclama la familia Rosario como parte de la referida herencia, la cual aseguran fue depositada en el Banco Central.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-Cientos de personas pertenecientes a la familia Rosario se manifestaron la ma\u00f1ana de este mi\u00e9rcoles frente al Palacio Nacional en respuesta de que las autoridades gestionen los fondos de una supuesta herencia millonaria dejada por sus ancestros y que afirman est\u00e1n en el pa\u00eds desde hace m\u00e1s de seis meses y les pertenece. Dijeron, adem\u00e1s, que han acudido a la embajada de Espa\u00f1a en Rep\u00fablica Dominicana en busca de mediaci\u00f3n y otras instancias internacionales, pero que creen ya es un asunto del Estado dominicano, raz\u00f3n por la que pidieron la intervenci\u00f3n del mandatario Danilo Medina. Unos 13 trillones de euros es el monto que reclama la familia Rosario como parte de la referida herencia, la cual aseguran fue depositada en el Banco Central.<\/p>\n","protected":false},"author":1,"featured_media":83658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-83657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83657"}],"version-history":[{"count":3,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83657\/revisions"}],"predecessor-version":[{"id":83661,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83657\/revisions\/83661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/83658"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}