{"id":84550,"date":"2019-02-05T13:12:30","date_gmt":"2019-02-05T17:12:30","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=84550"},"modified":"2019-02-05T13:12:30","modified_gmt":"2019-02-05T17:12:30","slug":"presidenta-de-adp-reclama-a-ssrl-cumplimiento-de-sentencia-a-tc","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/02\/05\/presidenta-de-adp-reclama-a-ssrl-cumplimiento-de-sentencia-a-tc\/","title":{"rendered":"Presidenta de ADP reclama a SSRL cumplimiento de sentencia a TC"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-84551 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/02\/f93a97b2-299e-4d06-aa63-4cdeff345139-800x450.jpg\" alt=\"\" width=\"580\" height=\"326\" \/>Santo Domingo-La Presidenta de la Asociaci\u00f3n Dominicana de Profesores, Xiomara Guante reclam\u00f3 a la Superintendencia de Salud y Riesgos Laborales el cumplimiento de la sentencia del Tribunal Constitucional, que dispone el traslado de los docentes del sector p\u00fablico a la ARS-SEMMA.<\/p>\n<p>En una visita a la Superintendencia de Salud y Riesgos Laborales, Xiomara Guante, solicit\u00f3 que se disponga a la mayor brevedad posible la incorporaci\u00f3n del 65 por ciento de docentes con edades superiores a los 45 a\u00f1os, a la ARS SEMMA. Esto a ra\u00edz de la sentencia emitida por el Tribunal Constitucional que dispone el traslado de empleados p\u00fablicos a las ARS Seguro Nacional de Salud y de autogesti\u00f3n, como el SEMMA.<\/p>\n<p>En otro orden, la presidenta de la ADP, revel\u00f3 que la Iglesia Cat\u00f3lica y otros sectores est\u00e1n ejerciendo presi\u00f3n al Ministerio de Educaci\u00f3n para que no se implemente la educaci\u00f3n sexual en las escuelas. En ese sentido, Xiomara Guante, invit\u00f3 al Ministerio de Educaci\u00f3n, a la iglesia cat\u00f3lica y otros sectores a sentarse en la mesa del di\u00e1logo para abordar pol\u00edticas orientadas finalmente a la implementaci\u00f3n de la educaci\u00f3n sexual en las escuelas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-La Presidenta de la Asociaci\u00f3n Dominicana de Profesores, Xiomara Guante reclam\u00f3 a la Superintendencia de Salud y Riesgos Laborales el cumplimiento de la sentencia del Tribunal Constitucional, que dispone el traslado de los docentes del sector p\u00fablico a la ARS-SEMMA. En una visita a la Superintendencia de Salud y Riesgos Laborales, Xiomara Guante, solicit\u00f3 que se disponga a la mayor brevedad posible la incorporaci\u00f3n del 65 por ciento de docentes con edades superiores a los 45 a\u00f1os, a la ARS SEMMA. Esto a ra\u00edz de la sentencia emitida por el Tribunal Constitucional que dispone el traslado de empleados p\u00fablicos a las ARS Seguro Nacional de Salud y de autogesti\u00f3n, como el SEMMA. En otro orden, la presidenta de la ADP, revel\u00f3 que la Iglesia Cat\u00f3lica y otros sectores est\u00e1n ejerciendo presi\u00f3n al Ministerio de Educaci\u00f3n para que no se implemente la educaci\u00f3n sexual en las escuelas. En ese sentido, Xiomara Guante, invit\u00f3 al Ministerio de Educaci\u00f3n, a la iglesia cat\u00f3lica y otros sectores a sentarse en la mesa del di\u00e1logo para abordar pol\u00edticas orientadas finalmente a la implementaci\u00f3n de la educaci\u00f3n sexual en las escuelas.<\/p>\n","protected":false},"author":1,"featured_media":84551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-84550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=84550"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84550\/revisions"}],"predecessor-version":[{"id":84552,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84550\/revisions\/84552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/84551"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=84550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=84550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=84550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}