{"id":84908,"date":"2019-02-15T10:41:51","date_gmt":"2019-02-15T14:41:51","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=84908"},"modified":"2019-02-15T10:41:51","modified_gmt":"2019-02-15T14:41:51","slug":"un-estudio-del-map-indica-que-mas-de-92-de-la-poblacion-esta-satisfecha-con-la-respuesta-oportuna-de-la-institucion","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/02\/15\/un-estudio-del-map-indica-que-mas-de-92-de-la-poblacion-esta-satisfecha-con-la-respuesta-oportuna-de-la-institucion\/","title":{"rendered":"Un estudio del MAP indica que m\u00e1s de 92% de la poblaci\u00f3n est\u00e1  satisfecha  con la respuesta oportuna de la instituci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-84909 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/02\/DSC_2804.jpg\" alt=\"\" width=\"697\" height=\"462\" \/>Santo Domingo. -El\u00a092.2\u00a0por ciento de la ciudadan\u00eda se siente satisfecha con los servicios y nivel de respuesta que ofrece el Ministerio de Salud P\u00fablica (MSP), mientras que un\u00a088.9% expres\u00f3 haber superado sus expectativas, seg\u00fan lo establece el Ministerio de\u00a0Administraci\u00f3n \u00a0P\u00fablica (MAP), en los \u00a0resultados de la Encuesta de Satisfacci\u00f3n Ciudadana sobre Calidad de los Servicios P\u00fablicos 2018.<\/p>\n<p>Para determinar los niveles de satisfacci\u00f3n, la encuesta se aplico en una \u00a0muestra\u00a0 de 398 personas usuarias de los servicios del Ministerio de Salud, quienes identificaron y se identificaron con factores como: empat\u00eda, seguridad, elementos, tangibles, fiabilidad y capacidad de respuesta.<\/p>\n<p>En cuanto a la adecuaci\u00f3n de los servicios a las necesidades del usuario, el resultado obtenido por el organismo de Salud fue de un 93%, asimismo la encuesta muestra el incremento del contacto del p\u00fablico con la p\u00e1gina web institucional.<\/p>\n<p>Otro aspecto del estudio donde las personas encuestadas identificaron mejoras, se refiere a\u00a0 al nivel de los servicios esperados, donde el MSP alcanz\u00f3\u00a0un porcentaje de 89%. No obstante estos resultados, la instituci\u00f3n informo en nota de prensa que \u00a0trabaja para alcanzar los m\u00e1ximos niveles de aceptaci\u00f3n de \u00a0la poblaci\u00f3n,<\/p>\n<p>El MAP para la realizaci\u00f3n del estudio aplic\u00f3 el Modelo SERVQUAL, el cual est\u00e1 compuesto por cinco dimensiones\u00a0relativas a los criterios de evaluaci\u00f3n que utiliza la ciudadan\u00eda \u00a0para valorar la calidad de los servicios.<\/p>\n<p>La evaluaci\u00f3n se aplic\u00f3 a unas 59 instituciones del Gobierno Central Dominicano, 20 Ministerios y 39 Direcciones Generales, Institutos, Consejos, entre otros; que la muestra total fue de 17,775 entrevistas distribuidas en las diferentes instituciones, durante los meses de mayo y agosto del 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. -El\u00a092.2\u00a0por ciento de la ciudadan\u00eda se siente satisfecha con los servicios y nivel de respuesta que ofrece el Ministerio de Salud P\u00fablica (MSP), mientras que un\u00a088.9% expres\u00f3 haber superado sus expectativas, seg\u00fan lo establece el Ministerio de\u00a0Administraci\u00f3n \u00a0P\u00fablica (MAP), en los \u00a0resultados de la Encuesta de Satisfacci\u00f3n Ciudadana sobre Calidad de los Servicios P\u00fablicos 2018. Para determinar los niveles de satisfacci\u00f3n, la encuesta se aplico en una \u00a0muestra\u00a0 de 398 personas usuarias de los servicios del Ministerio de Salud, quienes identificaron y se identificaron con factores como: empat\u00eda, seguridad, elementos, tangibles, fiabilidad y capacidad de respuesta. En cuanto a la adecuaci\u00f3n de los servicios a las necesidades del usuario, el resultado obtenido por el organismo de Salud fue de un 93%, asimismo la encuesta muestra el incremento del contacto del p\u00fablico con la p\u00e1gina web institucional. Otro aspecto del estudio donde las personas encuestadas identificaron mejoras, se refiere a\u00a0 al nivel de los servicios esperados, donde el MSP alcanz\u00f3\u00a0un porcentaje de 89%. No obstante estos resultados, la instituci\u00f3n informo en nota de prensa que \u00a0trabaja para alcanzar los m\u00e1ximos niveles de aceptaci\u00f3n de \u00a0la poblaci\u00f3n, El MAP para la realizaci\u00f3n del estudio aplic\u00f3 el Modelo SERVQUAL, el cual est\u00e1 compuesto por cinco dimensiones\u00a0relativas a los criterios de evaluaci\u00f3n que utiliza la ciudadan\u00eda \u00a0para valorar la calidad de los servicios. La evaluaci\u00f3n se aplic\u00f3 a unas 59 instituciones del Gobierno Central Dominicano, 20 Ministerios y 39 Direcciones Generales, Institutos, Consejos, entre otros; que la muestra total fue de 17,775 entrevistas distribuidas en las diferentes instituciones, durante los meses de mayo y agosto del 2018.<\/p>\n","protected":false},"author":1,"featured_media":84909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-84908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=84908"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84908\/revisions"}],"predecessor-version":[{"id":84910,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/84908\/revisions\/84910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/84909"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=84908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=84908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=84908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}