{"id":85076,"date":"2019-02-20T10:10:58","date_gmt":"2019-02-20T14:10:58","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=85076"},"modified":"2019-02-20T10:10:58","modified_gmt":"2019-02-20T14:10:58","slug":"canciller-vargas-impulsa-alianza-estrategica-con-alemania","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/02\/20\/canciller-vargas-impulsa-alianza-estrategica-con-alemania\/","title":{"rendered":"Canciller Vargas impulsa alianza estrat\u00e9gica con Alemania"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-85077 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/02\/CANCILLER-MIGUEL-Y-PARTICIPANTES-EN-LA-CONFERENCIA-HOY-EN-BERLIN-800x534.jpg\" alt=\"\" width=\"565\" height=\"377\" \/>Santo Domingo-El ministro de Relaciones Exteriores Miguel Vargas, propuso hoy la conformaci\u00f3n de una alianza para el desarrollo y la competitividad entre Rep\u00fablica Dominicana y Alemania, atendiendo la fortaleza de la relaci\u00f3n entre ambos pa\u00edses y las posiciones comunes que mantienen en temas estrat\u00e9gicos de la agenda global.<\/p>\n<p>El Canciller hizo el planteamiento durante la ceremonia de apertura de la XVI Conferencia Latinoamericana de la Econom\u00eda Alemana, en la que pronunci\u00f3 un discurso en representaci\u00f3n de la regi\u00f3n.<\/p>\n<p>La XVI Conferencia Latinoamericana de la Econom\u00eda Alemana, organizada por la Iniciativa Latinoamericana de la Econom\u00eda Alemana, abri\u00f3 con los discursos de Vargas y el ministro de \u00a0Econom\u00eda alem\u00e1n Peter Altmater, quienes hablaron ante una variada representaci\u00f3n del sector privado del pa\u00eds europeo y de Latinoam\u00e9rica.<\/p>\n<p>El Canciller Vargas expuso ampliamente sobre el auspicioso desempe\u00f1o de la econom\u00eda dominicana y el favorable clima de negocios, as\u00ed como los estrechos v\u00ednculos con Alemania.<\/p>\n<p>En ese sentido, resalt\u00f3 el avance del intercambio comercial entre las dos naciones, ascendente en 2018 a 475 millones de d\u00f3lares, desde la entrada en vigor del Acuerdo de Asociaci\u00f3n Econ\u00f3mica entre Rep\u00fablica Dominicana y la Uni\u00f3n Europea (EPA), pero existe el desaf\u00edo del incremento de los vol\u00famenes, puntualiz\u00f3.<\/p>\n<p>Miguel Vargas relat\u00f3 la pol\u00edtica del gobierno del presidente Danilo Medina basada en\u00a0 impulsar una alianza duradera del sector p\u00fablico y privado, lo cual, afirm\u00f3, es indispensable para el \u00e9xito de un programa\u00a0 nacional de fomento de la producci\u00f3n y del comercio, complement\u00e1ndola a trav\u00e9s de acuerdos de colaboraci\u00f3n con las principales asociaciones gremiales y empresariales del pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El ministro de Relaciones Exteriores Miguel Vargas, propuso hoy la conformaci\u00f3n de una alianza para el desarrollo y la competitividad entre Rep\u00fablica Dominicana y Alemania, atendiendo la fortaleza de la relaci\u00f3n entre ambos pa\u00edses y las posiciones comunes que mantienen en temas estrat\u00e9gicos de la agenda global. El Canciller hizo el planteamiento durante la ceremonia de apertura de la XVI Conferencia Latinoamericana de la Econom\u00eda Alemana, en la que pronunci\u00f3 un discurso en representaci\u00f3n de la regi\u00f3n. La XVI Conferencia Latinoamericana de la Econom\u00eda Alemana, organizada por la Iniciativa Latinoamericana de la Econom\u00eda Alemana, abri\u00f3 con los discursos de Vargas y el ministro de \u00a0Econom\u00eda alem\u00e1n Peter Altmater, quienes hablaron ante una variada representaci\u00f3n del sector privado del pa\u00eds europeo y de Latinoam\u00e9rica. El Canciller Vargas expuso ampliamente sobre el auspicioso desempe\u00f1o de la econom\u00eda dominicana y el favorable clima de negocios, as\u00ed como los estrechos v\u00ednculos con Alemania. En ese sentido, resalt\u00f3 el avance del intercambio comercial entre las dos naciones, ascendente en 2018 a 475 millones de d\u00f3lares, desde la entrada en vigor del Acuerdo de Asociaci\u00f3n Econ\u00f3mica entre Rep\u00fablica Dominicana y la Uni\u00f3n Europea (EPA), pero existe el desaf\u00edo del incremento de los vol\u00famenes, puntualiz\u00f3. Miguel Vargas relat\u00f3 la pol\u00edtica del gobierno del presidente Danilo Medina basada en\u00a0 impulsar una alianza duradera del sector p\u00fablico y privado, lo cual, afirm\u00f3, es indispensable para el \u00e9xito de un programa\u00a0 nacional de fomento de la producci\u00f3n y del comercio, complement\u00e1ndola a trav\u00e9s de acuerdos de colaboraci\u00f3n con las principales asociaciones gremiales y empresariales del pa\u00eds. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":85077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-85076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85076"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85076\/revisions"}],"predecessor-version":[{"id":85078,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85076\/revisions\/85078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/85077"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}