{"id":85307,"date":"2019-02-28T11:25:21","date_gmt":"2019-02-28T15:25:21","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=85307"},"modified":"2019-02-28T11:25:21","modified_gmt":"2019-02-28T15:25:21","slug":"ocuparon-52-paquetes-de-marihuana-en-el-aeropuerto-internacional-de-punta-cana","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/02\/28\/ocuparon-52-paquetes-de-marihuana-en-el-aeropuerto-internacional-de-punta-cana\/","title":{"rendered":"ocuparon 52 paquetes de marihuana en el Aeropuerto Internacional de Punta Cana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-85308 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/02\/Foto-Marihuana.-600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" \/>Santo Domingo.-\u00a0La Direcci\u00f3n Nacional de Control de Drogas (DNCD) con apoyo del Cuerpo Especializado de Seguridad Aeroportuaria y la coordinaci\u00f3n del Ministerio P\u00fablico, ocuparon 52 paquetes\u00a0de marihuana en el Aeropuerto Internacional de Punta Cana, provincia la Altagracia.<\/p>\n<p>La sustancia fue decomisada envuelta en fundas pl\u00e1sticas en el interior de una maleta que fue dejada abandonada pr\u00f3ximo al \u00e1rea de una de las correas de la terminal aeroportuaria.<\/p>\n<p>Seg\u00fan las investigaciones el equipaje, sin pasajero, en cuyo interior se encontr\u00f3 la marihuana, lleg\u00f3 a la terminal de Punta Cana desde Canad\u00e1 en un vuelo comercial.<\/p>\n<p>Los 52 paquetes decomisados dentro de la maleta tienen un peso preliminar de unas 30 libras de marihuana, mientras las autoridades contin\u00faan ampliando las investigaciones para determinar quien o quienes recibir\u00edan el vegetal en el pa\u00eds.<\/p>\n<p>La DNCD, con apoyo de las Fuerzas Armadas, la Polic\u00eda Nacional y la Procuradur\u00eda sigue reforzando las intervenciones en contra del tr\u00e1fico il\u00edcito de drogas en aeropuertos, puertos, fronteras y todo el territorio nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-\u00a0La Direcci\u00f3n Nacional de Control de Drogas (DNCD) con apoyo del Cuerpo Especializado de Seguridad Aeroportuaria y la coordinaci\u00f3n del Ministerio P\u00fablico, ocuparon 52 paquetes\u00a0de marihuana en el Aeropuerto Internacional de Punta Cana, provincia la Altagracia. La sustancia fue decomisada envuelta en fundas pl\u00e1sticas en el interior de una maleta que fue dejada abandonada pr\u00f3ximo al \u00e1rea de una de las correas de la terminal aeroportuaria. Seg\u00fan las investigaciones el equipaje, sin pasajero, en cuyo interior se encontr\u00f3 la marihuana, lleg\u00f3 a la terminal de Punta Cana desde Canad\u00e1 en un vuelo comercial. Los 52 paquetes decomisados dentro de la maleta tienen un peso preliminar de unas 30 libras de marihuana, mientras las autoridades contin\u00faan ampliando las investigaciones para determinar quien o quienes recibir\u00edan el vegetal en el pa\u00eds. La DNCD, con apoyo de las Fuerzas Armadas, la Polic\u00eda Nacional y la Procuradur\u00eda sigue reforzando las intervenciones en contra del tr\u00e1fico il\u00edcito de drogas en aeropuertos, puertos, fronteras y todo el territorio nacional. &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":85308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-85307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85307"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85307\/revisions"}],"predecessor-version":[{"id":85309,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85307\/revisions\/85309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/85308"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}