{"id":85403,"date":"2019-03-04T12:52:27","date_gmt":"2019-03-04T16:52:27","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=85403"},"modified":"2019-03-04T12:52:27","modified_gmt":"2019-03-04T16:52:27","slug":"presidente-danilo-medina-se-reune-con-pleno-jce","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/03\/04\/presidente-danilo-medina-se-reune-con-pleno-jce\/","title":{"rendered":"Presidente Danilo Medina se re\u00fane con pleno JCE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-85404 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/03\/unnamed-800x450.jpg\" alt=\"\" width=\"587\" height=\"330\" \/>Santo Domingo-El presidente Danilo Medina sostuvo hoy una reuni\u00f3n con el pleno de la Junta Central Electoral (JCE), en la que recibi\u00f3 explicaciones sobre el funcionamiento del sistema de votaci\u00f3n automatizada.<\/p>\n<p>Durante la demostraci\u00f3n, que tuvo lugar en el Sal\u00f3n Privado del Palacio Nacional, el presidente de la Rep\u00fablica prob\u00f3 el novedoso sistema.<\/p>\n<p>Participaron en la reuni\u00f3n:<\/p>\n<p>\u00b7Julio C\u00e9sar Casta\u00f1os Guzm\u00e1n, presidente de la JCE.<\/p>\n<p>\u00b7Roberto Salad\u00edn Selin, miembro titular del pleno de la JCE.<\/p>\n<p>\u00b7Carmen Imbert Brugal, miembro titular del pleno de la JCE.<\/p>\n<p>\u00b7Rosario Graciano de los Santos, miembro titular del pleno de la JCE.<\/p>\n<p>\u00b7Henry Mej\u00eda Oviedo, miembro titular del pleno de la JCE.<\/p>\n<p>\u00b7Mario N\u00fanez, director nacional de Elecciones.<\/p>\n<p>\u00b7Miguel \u00c1ngel Garc\u00eda, director nacional de Inform\u00e1tica.<\/p>\n<p>\u00b7Di\u00f3medes Ogando, director financiero de la JCE.<\/p>\n<p>\u00b7Laura Castellanos, directora de Comunicaciones de la JCE.<\/p>\n<p>El jefe de Estado estuvo acompa\u00f1ado de:<\/p>\n<p>\u00b7Jos\u00e9 Ram\u00f3n Fadul, ministro de Interior y Polic\u00eda.<\/p>\n<p>\u00b7Danilo D\u00edaz, ministro de Deportes.<\/p>\n<p>\u00b7\u00a0Luis Reyes, director general de Presupuesto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El presidente Danilo Medina sostuvo hoy una reuni\u00f3n con el pleno de la Junta Central Electoral (JCE), en la que recibi\u00f3 explicaciones sobre el funcionamiento del sistema de votaci\u00f3n automatizada. Durante la demostraci\u00f3n, que tuvo lugar en el Sal\u00f3n Privado del Palacio Nacional, el presidente de la Rep\u00fablica prob\u00f3 el novedoso sistema. Participaron en la reuni\u00f3n: \u00b7Julio C\u00e9sar Casta\u00f1os Guzm\u00e1n, presidente de la JCE. \u00b7Roberto Salad\u00edn Selin, miembro titular del pleno de la JCE. \u00b7Carmen Imbert Brugal, miembro titular del pleno de la JCE. \u00b7Rosario Graciano de los Santos, miembro titular del pleno de la JCE. \u00b7Henry Mej\u00eda Oviedo, miembro titular del pleno de la JCE. \u00b7Mario N\u00fanez, director nacional de Elecciones. \u00b7Miguel \u00c1ngel Garc\u00eda, director nacional de Inform\u00e1tica. \u00b7Di\u00f3medes Ogando, director financiero de la JCE. \u00b7Laura Castellanos, directora de Comunicaciones de la JCE. El jefe de Estado estuvo acompa\u00f1ado de: \u00b7Jos\u00e9 Ram\u00f3n Fadul, ministro de Interior y Polic\u00eda. \u00b7Danilo D\u00edaz, ministro de Deportes. \u00b7\u00a0Luis Reyes, director general de Presupuesto.<\/p>\n","protected":false},"author":1,"featured_media":85404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-85403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85403"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85403\/revisions"}],"predecessor-version":[{"id":85405,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85403\/revisions\/85405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/85404"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}