{"id":85406,"date":"2019-03-04T12:54:24","date_gmt":"2019-03-04T16:54:24","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=85406"},"modified":"2019-03-04T12:54:24","modified_gmt":"2019-03-04T16:54:24","slug":"micm-y-aird-financiaran-soluciones-tecnologicas-para-encadenar-mipymes-a-grandes-empresas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/03\/04\/micm-y-aird-financiaran-soluciones-tecnologicas-para-encadenar-mipymes-a-grandes-empresas\/","title":{"rendered":"MICM y AIRD financiar\u00e1n soluciones tecnol\u00f3gicas para encadenar mipymes a grandes empresas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-85407 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/03\/3185-753x800.jpg\" alt=\"\" width=\"616\" height=\"654\" \/>Santo Domingo-El Ministerio de Industria, Comercio y Mipymes (MICM) y la Asociaci\u00f3n de Industrias de la Rep\u00fablica Dominicana (AIRD) abrieron la primera convocatoria p\u00fablica para proyectos del Programa de Encadenamiento Productivo Digital (PEPD).<\/p>\n<p>En un acto encabezado por Ignacio M\u00e9ndez, viceministro de Fomento a las Mipymes del MICM, y Julio Virgilio Brache, vicepresidente de la Directiva Nacional de la AIRD, los ejecutivos destacaron las oportunidades de desarrollo que presenta el programa gracias a la alianza p\u00fablico \u2013 privada, inform\u00f3 una nota de la Direcci\u00f3n de Comunicaciones del MICM.<\/p>\n<p>El viceministro indic\u00f3 que el objetivo de la convocatoria es recibir proyectos que ayuden a transformar el uso que las mipymes dan a las tecnolog\u00edas para vender m\u00e1s y reducir costos, y as\u00ed conectarse a grandes empresas \u201ctractoras\u201d a trav\u00e9s del uso de herramientas de base tecnol\u00f3gica.<\/p>\n<p>Se\u00f1al\u00f3 que en Rep\u00fablica Dominicana menos del 45 por ciento de las mipymes tienen tel\u00e9fonos m\u00f3viles para actividades propias de su negocio, un escenario que el Ministerio se propone cambiar.<\/p>\n<p>A\u00f1adi\u00f3 que menos del 14 por ciento tiene computadoras y menos del 9 por ciento posee una p\u00e1gina web de la empresa, seg\u00fan datos de las Encuestas Enhogar 2014 y Fondomicro, de 2013.<\/p>\n<p>M\u00e9ndez manifest\u00f3 que la iniciativa se enmarca en el Programa Rep\u00fablica Digital, espec\u00edficamente en el eje de productividad y empleo, la cual ayuda a transformar la forma en la que muchas mipymes llevan su contabilidad en una mascota o c\u00f3mo venden sus productos a trav\u00e9s de canales tradicionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El Ministerio de Industria, Comercio y Mipymes (MICM) y la Asociaci\u00f3n de Industrias de la Rep\u00fablica Dominicana (AIRD) abrieron la primera convocatoria p\u00fablica para proyectos del Programa de Encadenamiento Productivo Digital (PEPD). En un acto encabezado por Ignacio M\u00e9ndez, viceministro de Fomento a las Mipymes del MICM, y Julio Virgilio Brache, vicepresidente de la Directiva Nacional de la AIRD, los ejecutivos destacaron las oportunidades de desarrollo que presenta el programa gracias a la alianza p\u00fablico \u2013 privada, inform\u00f3 una nota de la Direcci\u00f3n de Comunicaciones del MICM. El viceministro indic\u00f3 que el objetivo de la convocatoria es recibir proyectos que ayuden a transformar el uso que las mipymes dan a las tecnolog\u00edas para vender m\u00e1s y reducir costos, y as\u00ed conectarse a grandes empresas \u201ctractoras\u201d a trav\u00e9s del uso de herramientas de base tecnol\u00f3gica. Se\u00f1al\u00f3 que en Rep\u00fablica Dominicana menos del 45 por ciento de las mipymes tienen tel\u00e9fonos m\u00f3viles para actividades propias de su negocio, un escenario que el Ministerio se propone cambiar. A\u00f1adi\u00f3 que menos del 14 por ciento tiene computadoras y menos del 9 por ciento posee una p\u00e1gina web de la empresa, seg\u00fan datos de las Encuestas Enhogar 2014 y Fondomicro, de 2013. M\u00e9ndez manifest\u00f3 que la iniciativa se enmarca en el Programa Rep\u00fablica Digital, espec\u00edficamente en el eje de productividad y empleo, la cual ayuda a transformar la forma en la que muchas mipymes llevan su contabilidad en una mascota o c\u00f3mo venden sus productos a trav\u00e9s de canales tradicionales.<\/p>\n","protected":false},"author":1,"featured_media":85407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-85406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85406"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85406\/revisions"}],"predecessor-version":[{"id":85408,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85406\/revisions\/85408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/85407"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}