{"id":85984,"date":"2019-03-13T10:27:16","date_gmt":"2019-03-13T14:27:16","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=85984"},"modified":"2019-03-13T10:27:17","modified_gmt":"2019-03-13T14:27:17","slug":"aprueban-planes-para-implementar-estrategia-nacional-de-ciberseguridad","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/03\/13\/aprueban-planes-para-implementar-estrategia-nacional-de-ciberseguridad\/","title":{"rendered":"Aprueban planes para implementar Estrategia Nacional de Ciberseguridad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-85989 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/03\/unnamed-4-800x450.jpg\" alt=\"\" width=\"441\" height=\"248\" \/>Santo Domingo-El Consejo Nacional de Ciberseguridad aprob\u00f3 los planes para implementar la Estrategia Nacional de Ciberseguridad 2018-2021, que viene a fortalecer las respuestas y las l\u00edneas de acci\u00f3n frente a cualquier ataque, desastre natural u otra emergencia.<\/p>\n<p>En una reuni\u00f3n encabezada por el ministro de la Presidencia, Gustavo Montalvo, en su calidad de presidente del consejo, fueron presentadas las respuestas y l\u00edneas de acci\u00f3n para proteger el ciberespacio local.<\/p>\n<p>Gustavo Montalvo explic\u00f3 que el Gobierno se ha caracterizado por apostar de manera decidida a las nuevas tecnolog\u00edas, pero sin dejar de lado la protecci\u00f3n de todas las actividades que se realizan en el ciberespacio, sean comerciales, educativas, de esparcimiento, entre muchas otras.<\/p>\n<p>\u201cSabemos que, desde el robo de identidad, el narcotr\u00e1fico y el espionaje industrial, hasta el abuso de menores, todas estas actividades tienen su mayor espacio de crecimiento en Internet. Y por eso el Estado debe estar presente, para asegurar que la ley se cumpla\u201d.<\/p>\n<p><strong>Fortalecimiento marco legal e institucional<\/strong><\/p>\n<p>Dijo que la estrategia est\u00e1 basada en cuatro pilares y para cada uno de ellos se elabor\u00f3 un plan de acci\u00f3n.<\/p>\n<p>En primer lugar, est\u00e1 el fortalecimiento del marco legal e institucional, para lo cual se actualizar\u00e1n algunas leyes y se elaborar\u00e1n otras nuevas.<\/p>\n<p>El segundo es la protecci\u00f3n de las infraestructuras cr\u00edticas nacionales y de tecnolog\u00edas de la informaci\u00f3n del Estado.<\/p>\n<p>\u201cAl respecto, ya se realiz\u00f3 el levantamiento que nos permiti\u00f3 identificar la infraestructura cr\u00edtica con la que se estar\u00e1 trabajando de manera preventiva y proactiva. Para reforzar la protecci\u00f3n de \u00e9stas, se actualizar\u00e1n y ampliar\u00e1n tanto el equipamiento como el personal a su cargo\u201d.<\/p>\n<p><strong>Fomentar educaci\u00f3n en cuestiones de seguridad<\/strong><\/p>\n<p>A\u00f1adi\u00f3 que el tercer pilar consiste en fomentar la educaci\u00f3n en cuestiones de seguridad al utilizar las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n, para lo cual se llevar\u00e1 a cabo un amplio programa de capacitaci\u00f3n, en todos los niveles, para hacer conciencia sobre la importancia de la ciberseguridad.<\/p>\n<p><strong>Alianzas nacionales e internacionales<\/strong><\/p>\n<p>Sobre el cuarto pilar, Montalvo explic\u00f3 que tiene como objetivo establecer y consolidar alianzas nacionales e internacionales, ya que es imposible la protecci\u00f3n en el nivel de ciberseguridad sin el concierto global.<\/p>\n<p>Se\u00f1al\u00f3 que todos los planes de acci\u00f3n contienen objetivos, medidas, responsables, indicadores medibles, origen del presupuesto y plazos espec\u00edficos.<\/p>\n<p>\u201cDe esa forma se aseguran de que las medidas se implementen y los resultados sean concretos\u201d.<\/p>\n<p>El ministro de la Presidencia indic\u00f3 que el Departamento de Investigaci\u00f3n de Cr\u00edmenes y Delitos de Alta Tecnolog\u00eda (DICAT), de la Polic\u00eda Nacional, viene realizando un amplio monitoreo de los productos que se venden a trav\u00e9s de la paginas nacionales de internet.<\/p>\n<p>De esa manera, se refuerza la seguridad de las transacciones electr\u00f3nicas ejecutadas a trav\u00e9s de estos medios.<\/p>\n<p><strong>Respeto derechos a propiedad, privacidad y seguridad<\/strong><\/p>\n<p>El Gobierno busca asegurar que se respeten los derechos de los dominicanos a la propiedad, a la privacidad y la seguridad al utilizar internet.<\/p>\n<p>\u201cPor eso, pueden estar seguros de que desde el Gobierno seguiremos trabajando para proporcionar seguridad a todos los dominicanos, tambi\u00e9n en esta nueva frontera digital\u201d.<\/p>\n<p>El encuentro se realiz\u00f3 en el Sal\u00f3n Los Trinitarios del Palacio Nacional, con la participaci\u00f3n del ministro de Defensa, teniente general Rub\u00e9n Dar\u00edo Paulino Sem; el presidente del Indotel, Luis Henry Molina; y la viceministra de la Presidencia, Zoraima Cuello.<\/p>\n<p>Junto a ellos, el director de la OPTIC, Armando Garc\u00eda; el director de la Polic\u00eda Nacional, Ney Aldrin Bautista; el titular de la Direcci\u00f3n Nacional de Investigaciones (DNI), Sigfrido Pared P\u00e9rez; el director ejecutivo del Centro Nacional de Ciberseguridad, James Pichardo, y el director de Ciberseguridad de Indotel, C\u00e9sar Molin\u00e9.<\/p>\n<p>Asimismo, el director de Tecnolog\u00eda de la Procuradur\u00eda General de la Rep\u00fablica, Javier Forteza; el procurador de Alta Tecnolog\u00eda, Iv\u00e1n F\u00e9lix; el director central de Desarrollo Humano de la Polic\u00eda Nacional, Licurgo Yunes; Carlos Ram\u00edrez Casta\u00f1os, de la Polic\u00eda Nacional, y el consultor Carlos Leonardo Garc\u00eda, director de respuestas a incidentes cibern\u00e9ticos, del Centro Nacional de Ciberseguridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El Consejo Nacional de Ciberseguridad aprob\u00f3 los planes para implementar la Estrategia Nacional de Ciberseguridad 2018-2021, que viene a fortalecer las respuestas y las l\u00edneas de acci\u00f3n frente a cualquier ataque, desastre natural u otra emergencia. En una reuni\u00f3n encabezada por el ministro de la Presidencia, Gustavo Montalvo, en su calidad de presidente del consejo, fueron presentadas las respuestas y l\u00edneas de acci\u00f3n para proteger el ciberespacio local. Gustavo Montalvo explic\u00f3 que el Gobierno se ha caracterizado por apostar de manera decidida a las nuevas tecnolog\u00edas, pero sin dejar de lado la protecci\u00f3n de todas las actividades que se realizan en el ciberespacio, sean comerciales, educativas, de esparcimiento, entre muchas otras. \u201cSabemos que, desde el robo de identidad, el narcotr\u00e1fico y el espionaje industrial, hasta el abuso de menores, todas estas actividades tienen su mayor espacio de crecimiento en Internet. Y por eso el Estado debe estar presente, para asegurar que la ley se cumpla\u201d. Fortalecimiento marco legal e institucional Dijo que la estrategia est\u00e1 basada en cuatro pilares y para cada uno de ellos se elabor\u00f3 un plan de acci\u00f3n. En primer lugar, est\u00e1 el fortalecimiento del marco legal e institucional, para lo cual se actualizar\u00e1n algunas leyes y se elaborar\u00e1n otras nuevas. El segundo es la protecci\u00f3n de las infraestructuras cr\u00edticas nacionales y de tecnolog\u00edas de la informaci\u00f3n del Estado. \u201cAl respecto, ya se realiz\u00f3 el levantamiento que nos permiti\u00f3 identificar la infraestructura cr\u00edtica con la que se estar\u00e1 trabajando de manera preventiva y proactiva. Para reforzar la protecci\u00f3n de \u00e9stas, se actualizar\u00e1n y ampliar\u00e1n tanto el equipamiento como el personal a su cargo\u201d. Fomentar educaci\u00f3n en cuestiones de seguridad A\u00f1adi\u00f3 que el tercer pilar consiste en fomentar la educaci\u00f3n en cuestiones de seguridad al utilizar las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n, para lo cual se llevar\u00e1 a cabo un amplio programa de capacitaci\u00f3n, en todos los niveles, para hacer conciencia sobre la importancia de la ciberseguridad. Alianzas nacionales e internacionales Sobre el cuarto pilar, Montalvo explic\u00f3 que tiene como objetivo establecer y consolidar alianzas nacionales e internacionales, ya que es imposible la protecci\u00f3n en el nivel de ciberseguridad sin el concierto global. Se\u00f1al\u00f3 que todos los planes de acci\u00f3n contienen objetivos, medidas, responsables, indicadores medibles, origen del presupuesto y plazos espec\u00edficos. \u201cDe esa forma se aseguran de que las medidas se implementen y los resultados sean concretos\u201d. El ministro de la Presidencia indic\u00f3 que el Departamento de Investigaci\u00f3n de Cr\u00edmenes y Delitos de Alta Tecnolog\u00eda (DICAT), de la Polic\u00eda Nacional, viene realizando un amplio monitoreo de los productos que se venden a trav\u00e9s de la paginas nacionales de internet. De esa manera, se refuerza la seguridad de las transacciones electr\u00f3nicas ejecutadas a trav\u00e9s de estos medios. Respeto derechos a propiedad, privacidad y seguridad El Gobierno busca asegurar que se respeten los derechos de los dominicanos a la propiedad, a la privacidad y la seguridad al utilizar internet. \u201cPor eso, pueden estar seguros de que desde el Gobierno seguiremos trabajando para proporcionar seguridad a todos los dominicanos, tambi\u00e9n en esta nueva frontera digital\u201d. El encuentro se realiz\u00f3 en el Sal\u00f3n Los Trinitarios del Palacio Nacional, con la participaci\u00f3n del ministro de Defensa, teniente general Rub\u00e9n Dar\u00edo Paulino Sem; el presidente del Indotel, Luis Henry Molina; y la viceministra de la Presidencia, Zoraima Cuello. Junto a ellos, el director de la OPTIC, Armando Garc\u00eda; el director de la Polic\u00eda Nacional, Ney Aldrin Bautista; el titular de la Direcci\u00f3n Nacional de Investigaciones (DNI), Sigfrido Pared P\u00e9rez; el director ejecutivo del Centro Nacional de Ciberseguridad, James Pichardo, y el director de Ciberseguridad de Indotel, C\u00e9sar Molin\u00e9. Asimismo, el director de Tecnolog\u00eda de la Procuradur\u00eda General de la Rep\u00fablica, Javier Forteza; el procurador de Alta Tecnolog\u00eda, Iv\u00e1n F\u00e9lix; el director central de Desarrollo Humano de la Polic\u00eda Nacional, Licurgo Yunes; Carlos Ram\u00edrez Casta\u00f1os, de la Polic\u00eda Nacional, y el consultor Carlos Leonardo Garc\u00eda, director de respuestas a incidentes cibern\u00e9ticos, del Centro Nacional de Ciberseguridad.<\/p>\n","protected":false},"author":8,"featured_media":85987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[222,221],"class_list":["post-85984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-ciberseguridad","tag-estrategia"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85984"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85984\/revisions"}],"predecessor-version":[{"id":85990,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85984\/revisions\/85990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/85987"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}