{"id":87254,"date":"2019-03-28T10:38:49","date_gmt":"2019-03-28T14:38:49","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=87254"},"modified":"2019-03-28T10:38:49","modified_gmt":"2019-03-28T14:38:49","slug":"incautaran-vehiculos-encuentren-en-lavaderos-improvisados","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/03\/28\/incautaran-vehiculos-encuentren-en-lavaderos-improvisados\/","title":{"rendered":"Incautar\u00e1n veh\u00edculos encuentren en lavaderos improvisados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-87256 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/03\/2c7c71c9-whatsapp-image-2018-10-20-at-7_52_14-pm-1024x550-1-800x430.jpg\" alt=\"\" width=\"687\" height=\"369\" \/>Santo Domingo-La Procuradur\u00eda para la Defensa del Medio Ambiente y los Recursos Naturales amenaz\u00f3 con incautar los veh\u00edculos que sean lavados en las calles y en otros sitios p\u00fablicos as\u00ed como someter a la justicia a las personas que se dediquen a esas labores de manera irregular.<\/p>\n<p>El titular de la Procuradur\u00eda de Medio Ambiente, Francisco Contreras, dijo que para contrarrestar esa pr\u00e1ctica y llamar al ahorro del agua, debido a la sequ\u00eda, la instituci\u00f3n que dirige lleva a cabo una campa\u00f1a de concienciaci\u00f3n dirigida a los lavadores informales de veh\u00edculos del Gran Santo Domingo.<\/p>\n<p>Contreras destac\u00f3 que el objetivo de los operativos es contrarrestar el uso inadecuado del agua potable, mediante la implementaci\u00f3n de un programa de orientaci\u00f3n ciudadana sobre la importancia del uso racional del l\u00edquido y la operaci\u00f3n de los lavaderos improvisados.<\/p>\n<p>Se\u00f1al\u00f3 que las labores se llevan a cabo de manera conjunta por miembros del Ministerio P\u00fablico y la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD), as\u00ed como del Servicio Nacional de Protecci\u00f3n Ambiental (SENPA).<\/p>\n<p>Durante la jornada de concienciaci\u00f3n, Contreras convers\u00f3 con j\u00f3venes que se encontraban en lavaderos improvisados en distintos sectores del Distrito Nacional y la provincia Santo Domingo, a quienes advirti\u00f3 que de no acatar las medidas dispuestas por las autoridades ser\u00e1n sometidos a la justicia.<\/p>\n<p>\u201cLa Ley No. 498-73, que regula el tratamiento y manejo del agua y por disposici\u00f3n de la Procuradur\u00eda General de Medio Ambiente, est\u00e1 prohibido el uso inadecuado del agua potable, el Ministerio P\u00fablico est\u00e1 haciendo la advertencia de que queda total y rotundamente prohibido lavar veh\u00edculos en las calles\u201d, advirti\u00f3.<\/p>\n<p>El funcionario del Ministerio P\u00fablico hizo un llamado a cumplir las disposiciones establecidas para contrarrestar el uso inadecuado del agua potable en virtud de la fuerte sequ\u00eda que afecta al pa\u00eds.<\/p>\n<p>Las autoridades tambi\u00e9n advirtieron que dentro de las medidas adoptadas adem\u00e1s proceder\u00e1n a incautar todos los veh\u00edculos que al momento de los operativos se encuentren en los lavaderos improvisados, as\u00ed como todos los aparatos y utensilios que se encuentren en el lugar, como mangueras, bombas de agua, tanques y cubetas, entre otros.<\/p>\n<p>Indicaron que a partir de ahora, durante la segunda etapa del operativo comenzar\u00e1n a clausurar todos los lavaderos informales que se encuentren en las calles, al tiempo de indicar que a los lavaderos formales se le est\u00e1 notificando para que contribuyan con el ahorro del agua potable.<\/p>\n<p>La informaci\u00f3n fue ofrecida a trav\u00e9s de un comunicado de prensa, el cual destaca que las autoridades continuar\u00e1n con los operativos sorpresa, para evitar el funcionamiento de los lavadores informales y las conexiones ilegales a las tuber\u00edas de la CAASD.<\/p>\n<p>En el comunicado divulgado por el Ministerio P\u00fablico, esta instituci\u00f3n reiter\u00f3 el llamado a la poblaci\u00f3n a contribuir con las acciones que llevan a cabo para enfrentar la problem\u00e1tica, haciendo un uso consciente y razonable del preciado l\u00edquido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-La Procuradur\u00eda para la Defensa del Medio Ambiente y los Recursos Naturales amenaz\u00f3 con incautar los veh\u00edculos que sean lavados en las calles y en otros sitios p\u00fablicos as\u00ed como someter a la justicia a las personas que se dediquen a esas labores de manera irregular. El titular de la Procuradur\u00eda de Medio Ambiente, Francisco Contreras, dijo que para contrarrestar esa pr\u00e1ctica y llamar al ahorro del agua, debido a la sequ\u00eda, la instituci\u00f3n que dirige lleva a cabo una campa\u00f1a de concienciaci\u00f3n dirigida a los lavadores informales de veh\u00edculos del Gran Santo Domingo. Contreras destac\u00f3 que el objetivo de los operativos es contrarrestar el uso inadecuado del agua potable, mediante la implementaci\u00f3n de un programa de orientaci\u00f3n ciudadana sobre la importancia del uso racional del l\u00edquido y la operaci\u00f3n de los lavaderos improvisados. Se\u00f1al\u00f3 que las labores se llevan a cabo de manera conjunta por miembros del Ministerio P\u00fablico y la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD), as\u00ed como del Servicio Nacional de Protecci\u00f3n Ambiental (SENPA). Durante la jornada de concienciaci\u00f3n, Contreras convers\u00f3 con j\u00f3venes que se encontraban en lavaderos improvisados en distintos sectores del Distrito Nacional y la provincia Santo Domingo, a quienes advirti\u00f3 que de no acatar las medidas dispuestas por las autoridades ser\u00e1n sometidos a la justicia. \u201cLa Ley No. 498-73, que regula el tratamiento y manejo del agua y por disposici\u00f3n de la Procuradur\u00eda General de Medio Ambiente, est\u00e1 prohibido el uso inadecuado del agua potable, el Ministerio P\u00fablico est\u00e1 haciendo la advertencia de que queda total y rotundamente prohibido lavar veh\u00edculos en las calles\u201d, advirti\u00f3. El funcionario del Ministerio P\u00fablico hizo un llamado a cumplir las disposiciones establecidas para contrarrestar el uso inadecuado del agua potable en virtud de la fuerte sequ\u00eda que afecta al pa\u00eds. Las autoridades tambi\u00e9n advirtieron que dentro de las medidas adoptadas adem\u00e1s proceder\u00e1n a incautar todos los veh\u00edculos que al momento de los operativos se encuentren en los lavaderos improvisados, as\u00ed como todos los aparatos y utensilios que se encuentren en el lugar, como mangueras, bombas de agua, tanques y cubetas, entre otros. Indicaron que a partir de ahora, durante la segunda etapa del operativo comenzar\u00e1n a clausurar todos los lavaderos informales que se encuentren en las calles, al tiempo de indicar que a los lavaderos formales se le est\u00e1 notificando para que contribuyan con el ahorro del agua potable. La informaci\u00f3n fue ofrecida a trav\u00e9s de un comunicado de prensa, el cual destaca que las autoridades continuar\u00e1n con los operativos sorpresa, para evitar el funcionamiento de los lavadores informales y las conexiones ilegales a las tuber\u00edas de la CAASD. En el comunicado divulgado por el Ministerio P\u00fablico, esta instituci\u00f3n reiter\u00f3 el llamado a la poblaci\u00f3n a contribuir con las acciones que llevan a cabo para enfrentar la problem\u00e1tica, haciendo un uso consciente y razonable del preciado l\u00edquido.<\/p>\n","protected":false},"author":8,"featured_media":87255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[299,584],"class_list":["post-87254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-lavaderos","tag-vehiculos"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=87254"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87254\/revisions"}],"predecessor-version":[{"id":87257,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87254\/revisions\/87257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/87255"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=87254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=87254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=87254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}