{"id":87854,"date":"2019-04-05T10:24:25","date_gmt":"2019-04-05T14:24:25","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=87854"},"modified":"2019-04-05T10:24:25","modified_gmt":"2019-04-05T14:24:25","slug":"ongs-condenan-represion-contra-adictos-a-drogas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/04\/05\/ongs-condenan-represion-contra-adictos-a-drogas\/","title":{"rendered":"ONGs condenan represi\u00f3n contra adictos a drogas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-87856 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/04\/Crecen-incautaciones-anfetaminas-Mexico-EEUU_EDIIMA20150303_0266_24.jpg\" alt=\"\" width=\"618\" height=\"348\" \/>Santo Domingo-Asociaciones Sin Fines de Lucro (ONGs), que trabajan en la Prevenci\u00f3n y Tratamiento con las adicciones a drogas, reclaman a los poderes del Estado modificar la vigente ley 50-88, sobre drogas.<\/p>\n<p>\u201cNuestro pa\u00eds ha mantenido por m\u00e1s de treinta a\u00f1os la innecesaria represi\u00f3n abusiva hacia el simple usuario. Entendemos que a toda luz es un accionar \u00a0castigador y carente de los derechos a la salud\u00a0 hacia personas que ninguna culpa tienen de ser v\u00edctimas de su propia condici\u00f3n fruto de una enfermedad. Tenemos a\u00f1os haciendo el mismo reclamo a las autoridades, sin dar \u00e9stas soluci\u00f3n real, solo menciones y hasta discursos de momento, especialmente ante acontecimientos que generan opini\u00f3n p\u00fablica al respecto\u201d, puntualizaron.<\/p>\n<p>Sostiene que en diferentes escenarios han tratado tema sin por el momento haber logrado resultados positivos.<\/p>\n<p>Explicaron que, con la simulada persecuci\u00f3n, sin objetivo espec\u00edfico contra el microtr\u00e1fico y el consumo, las autoridades solo est\u00e1n saturando los Tribunales y los recintos carcelarios de todo el pa\u00eds.<\/p>\n<p>Reprocharon que desde el Estado no haya una pol\u00edtica de acci\u00f3n y seguimiento a personas involucradas en el uso y abuso de las drogas.<\/p>\n<p>Criticaron que es inconcebible que el crimen del tr\u00e1fico de drogas, en todas sus dimensiones se organizan y solidifican al penetrar en los diferentes organismos del Estado.<\/p>\n<p>\u201cNuestras experiencias en el trabajo que hacemos, con una intervenci\u00f3n biopsicosocial con cada persona que se presenta buscando alternativas a su problema, son labores altruistas que asumimos como misi\u00f3n, rol que es competencia del Estado. Las limitadas condiciones en las que nuestras instituciones han asumido estas desafiantes labores y con pocas herramientas de manejo, conlleva, a un bajo porcentaje de efectividad y soluci\u00f3n definitiva para todo el que llega a nuestros Centros\u201d, explicaron.<\/p>\n<p>Recordaron que recientemente mediante la firma de un \u201cmanifiesto\u201d han solicitado al Poder Ejecutivo, el Senado de la Rep\u00fablica y la C\u00e1mara de Diputados, la modificaci\u00f3n de la legislaci\u00f3n 50-88.<\/p>\n<p>Entre las\u00a0 ONGs que exigen la modificaci\u00f3n de la pieza est\u00e1n la Asociaci\u00f3n Casa Abierta, Hogar Crea Internacional, Inc., El Mes\u00f3n de Dios, La Fundaci\u00f3n Dios es Fiel, Nuevo Amanecer, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-Asociaciones Sin Fines de Lucro (ONGs), que trabajan en la Prevenci\u00f3n y Tratamiento con las adicciones a drogas, reclaman a los poderes del Estado modificar la vigente ley 50-88, sobre drogas. \u201cNuestro pa\u00eds ha mantenido por m\u00e1s de treinta a\u00f1os la innecesaria represi\u00f3n abusiva hacia el simple usuario. Entendemos que a toda luz es un accionar \u00a0castigador y carente de los derechos a la salud\u00a0 hacia personas que ninguna culpa tienen de ser v\u00edctimas de su propia condici\u00f3n fruto de una enfermedad. Tenemos a\u00f1os haciendo el mismo reclamo a las autoridades, sin dar \u00e9stas soluci\u00f3n real, solo menciones y hasta discursos de momento, especialmente ante acontecimientos que generan opini\u00f3n p\u00fablica al respecto\u201d, puntualizaron. Sostiene que en diferentes escenarios han tratado tema sin por el momento haber logrado resultados positivos. Explicaron que, con la simulada persecuci\u00f3n, sin objetivo espec\u00edfico contra el microtr\u00e1fico y el consumo, las autoridades solo est\u00e1n saturando los Tribunales y los recintos carcelarios de todo el pa\u00eds. Reprocharon que desde el Estado no haya una pol\u00edtica de acci\u00f3n y seguimiento a personas involucradas en el uso y abuso de las drogas. Criticaron que es inconcebible que el crimen del tr\u00e1fico de drogas, en todas sus dimensiones se organizan y solidifican al penetrar en los diferentes organismos del Estado. \u201cNuestras experiencias en el trabajo que hacemos, con una intervenci\u00f3n biopsicosocial con cada persona que se presenta buscando alternativas a su problema, son labores altruistas que asumimos como misi\u00f3n, rol que es competencia del Estado. Las limitadas condiciones en las que nuestras instituciones han asumido estas desafiantes labores y con pocas herramientas de manejo, conlleva, a un bajo porcentaje de efectividad y soluci\u00f3n definitiva para todo el que llega a nuestros Centros\u201d, explicaron. Recordaron que recientemente mediante la firma de un \u201cmanifiesto\u201d han solicitado al Poder Ejecutivo, el Senado de la Rep\u00fablica y la C\u00e1mara de Diputados, la modificaci\u00f3n de la legislaci\u00f3n 50-88. Entre las\u00a0 ONGs que exigen la modificaci\u00f3n de la pieza est\u00e1n la Asociaci\u00f3n Casa Abierta, Hogar Crea Internacional, Inc., El Mes\u00f3n de Dios, La Fundaci\u00f3n Dios es Fiel, Nuevo Amanecer, entre otras.<\/p>\n","protected":false},"author":8,"featured_media":87855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[170,684],"class_list":["post-87854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-drogas","tag-ongs"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=87854"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87854\/revisions"}],"predecessor-version":[{"id":87857,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/87854\/revisions\/87857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/87855"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=87854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=87854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=87854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}