{"id":88279,"date":"2019-04-12T13:22:53","date_gmt":"2019-04-12T17:22:53","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=88279"},"modified":"2019-04-12T13:22:53","modified_gmt":"2019-04-12T17:22:53","slug":"develizan-estatua-de-jack-veneno-en-el-parque-eugenio-maria-de-hostos","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/04\/12\/develizan-estatua-de-jack-veneno-en-el-parque-eugenio-maria-de-hostos\/","title":{"rendered":"Develizan estatua de Jack Veneno en el Parque Eugenio Mar\u00eda de Hostos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-88280 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/04\/60145a7c-5a43-4461-a132-870ff0d6cbdf-600x800.jpg\" alt=\"\" width=\"478\" height=\"637\" \/>Santo Domingo-La explanada frontal del Parque Eugenio Mar\u00eda de Hostos es el escenario escogido para exhibir permanentemente la estatua del legendario luchador dominicano Rafael Antonio S\u00e1nchez, mejor conocido como Jack Veneno, quien por d\u00e9cadas puso a vibrar de emoci\u00f3n ese espacio, con los tradicionales domingos de Lucha Libre.<\/p>\n<p>La iniciativa de la Fundaci\u00f3n Luces y Sombras Espacio de Arte, tiene como prop\u00f3sito rendir honor a quien por muchos a\u00f1os, fue ejemplo de perseverancia, alegr\u00eda y buen accionar, ejerciendo el deporte de la lucha libre sustentado en valores y respeto a las t\u00e9cnicas profesionales del momento, enfrentando as\u00ed a los \u201cmuchachos malos\u201d de la cuadra de los rudos, que lideraba Rel\u00e1mpago Hern\u00e1ndez.<\/p>\n<p>Juan Gilberto N\u00fa\u00f1ez, presidente de la Fundaci\u00f3n Luces y Sombras, manifest\u00f3 su agradecimiento a la Sala Capitular de la Alcald\u00eda del Distrito Nacional, por acoger la solicitud realizada para la colocaci\u00f3n de la estatua, cuya escultura fue elaborada por los artistas de la fundaci\u00f3n y est\u00e1 colocada sobre una base de coralina finamente terminada en forma de pir\u00e1mide truncada de 2.0 metros de altura, representando la imagen del \u201ccampe\u00f3n de la bolita del mundo\u201d, conocido tambi\u00e9n como \u201cel hijo de do\u00f1a Tatica\u201d, Jack Veneno.<\/p>\n<p>\u201cHoy nos encontramos haciendo un acto de justicia, con un ser humano maravilloso que nos puso a vibrar de emoci\u00f3n y que todos vimos en \u00e9l a ese h\u00e9roe que quisimos ser. Otros pa\u00edses han tenido h\u00e9roes con capas que vuelan, h\u00e9roes que trascienden y traspasan la estrat\u00f3sfera y se van muy lejos, pero Rep\u00fablica Dominicana tiene su propio h\u00e9roe, un hombre que no ten\u00eda capa pero que se sub\u00eda en la tercera cuerda del cuadril\u00e1tero y saltaba, volaba y nos hac\u00eda saltar con \u00e9l llenos de emoci\u00f3n. Jack Veneno fue un \u00edcono de lo que es la moralidad, los buenos modales y lo que era el esp\u00edritu de justicia, llevando siempre con orgullo la bandera de nuestro pa\u00eds. Gracias Jack Veneno, por ense\u00f1arnos que vale la pena estar del lado de los t\u00e9cnicos, luchar con coderas, luchado por pol\u00e9micas siempre en pro del bien\u201d, expres\u00f3 Juan Gilberto N\u00fa\u00f1ez.<\/p>\n<p>De su lado, Rafael Antonio S\u00e1nchez, Jack Veneno, agradeci\u00f3 a las instituciones y personalidades que pusieron voluntad en hacer posible su reconocimiento, en especial a la Fundaci\u00f3n Luces y Sombras en la persona de su presidente Juan Gilberto N\u00fa\u00f1ez, \u201cpor este noble gesto que recibo humildemente y que dedico a todo ese pueblo que no solamente me apoy\u00f3 y me llevaron a sus casas a trav\u00e9s de la televisi\u00f3n y viniendo a este parque cada domingo, sino, que me sigue apoyando y dando cari\u00f1o a trav\u00e9s de mis redes sociales. Mi mam\u00e1 Do\u00f1a Tatica en el cielo est\u00e1 mirando que a su hijo lo est\u00e1n reconociendo en vida, estamos vivos aqu\u00ed para celebrarlo\u201d, expres\u00f3 pleno de emotividad Jack Veneno.<\/p>\n<p>Rafael Antonio S\u00e1nchez, nacido el 2 de febrero de 1942, se inici\u00f3 en el deporte de la lucha libre en el a\u00f1o 1969, logrando despertar la admiraci\u00f3n de una gran fanaticada que vio en \u00e9l, a una especie de superh\u00e9roe sin capa, que se desplazaba con agilidad en el cuadril\u00e1tero y saltaba por los aires, siempre promoviendo el buen accionar y el rechazo a las acciones incorrectas.<\/p>\n<p>Miles de dominicanos recuerdan con entra\u00f1able cari\u00f1o esa \u00e9poca de oro de la Lucha Libre, siendo Jack Veneno el l\u00edder a seguir y quien conquist\u00f3 al menos seis t\u00edtulos de campe\u00f3n en diferentes categor\u00edas tanto nacionales, como internacionales.<\/p>\n<p>El acto estuvo encabezado por el alcalde del Distrito Nacional, David Collado, el ministro de cultura, Eduardo Selman, el viceministro de la Presidencia Lionel Senior, presidente de la Comisi\u00f3n Permanente de Efem\u00e9rides Patrias, Juan Daniel Balc\u00e1cer, el regidor Alejandro Bar\u00f3n, Rosanna Rivera, presidenta de la Asociaci\u00f3n de Amigos de la Zona Colonial, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-La explanada frontal del Parque Eugenio Mar\u00eda de Hostos es el escenario escogido para exhibir permanentemente la estatua del legendario luchador dominicano Rafael Antonio S\u00e1nchez, mejor conocido como Jack Veneno, quien por d\u00e9cadas puso a vibrar de emoci\u00f3n ese espacio, con los tradicionales domingos de Lucha Libre. La iniciativa de la Fundaci\u00f3n Luces y Sombras Espacio de Arte, tiene como prop\u00f3sito rendir honor a quien por muchos a\u00f1os, fue ejemplo de perseverancia, alegr\u00eda y buen accionar, ejerciendo el deporte de la lucha libre sustentado en valores y respeto a las t\u00e9cnicas profesionales del momento, enfrentando as\u00ed a los \u201cmuchachos malos\u201d de la cuadra de los rudos, que lideraba Rel\u00e1mpago Hern\u00e1ndez. Juan Gilberto N\u00fa\u00f1ez, presidente de la Fundaci\u00f3n Luces y Sombras, manifest\u00f3 su agradecimiento a la Sala Capitular de la Alcald\u00eda del Distrito Nacional, por acoger la solicitud realizada para la colocaci\u00f3n de la estatua, cuya escultura fue elaborada por los artistas de la fundaci\u00f3n y est\u00e1 colocada sobre una base de coralina finamente terminada en forma de pir\u00e1mide truncada de 2.0 metros de altura, representando la imagen del \u201ccampe\u00f3n de la bolita del mundo\u201d, conocido tambi\u00e9n como \u201cel hijo de do\u00f1a Tatica\u201d, Jack Veneno. \u201cHoy nos encontramos haciendo un acto de justicia, con un ser humano maravilloso que nos puso a vibrar de emoci\u00f3n y que todos vimos en \u00e9l a ese h\u00e9roe que quisimos ser. Otros pa\u00edses han tenido h\u00e9roes con capas que vuelan, h\u00e9roes que trascienden y traspasan la estrat\u00f3sfera y se van muy lejos, pero Rep\u00fablica Dominicana tiene su propio h\u00e9roe, un hombre que no ten\u00eda capa pero que se sub\u00eda en la tercera cuerda del cuadril\u00e1tero y saltaba, volaba y nos hac\u00eda saltar con \u00e9l llenos de emoci\u00f3n. Jack Veneno fue un \u00edcono de lo que es la moralidad, los buenos modales y lo que era el esp\u00edritu de justicia, llevando siempre con orgullo la bandera de nuestro pa\u00eds. Gracias Jack Veneno, por ense\u00f1arnos que vale la pena estar del lado de los t\u00e9cnicos, luchar con coderas, luchado por pol\u00e9micas siempre en pro del bien\u201d, expres\u00f3 Juan Gilberto N\u00fa\u00f1ez. De su lado, Rafael Antonio S\u00e1nchez, Jack Veneno, agradeci\u00f3 a las instituciones y personalidades que pusieron voluntad en hacer posible su reconocimiento, en especial a la Fundaci\u00f3n Luces y Sombras en la persona de su presidente Juan Gilberto N\u00fa\u00f1ez, \u201cpor este noble gesto que recibo humildemente y que dedico a todo ese pueblo que no solamente me apoy\u00f3 y me llevaron a sus casas a trav\u00e9s de la televisi\u00f3n y viniendo a este parque cada domingo, sino, que me sigue apoyando y dando cari\u00f1o a trav\u00e9s de mis redes sociales. Mi mam\u00e1 Do\u00f1a Tatica en el cielo est\u00e1 mirando que a su hijo lo est\u00e1n reconociendo en vida, estamos vivos aqu\u00ed para celebrarlo\u201d, expres\u00f3 pleno de emotividad Jack Veneno. Rafael Antonio S\u00e1nchez, nacido el 2 de febrero de 1942, se inici\u00f3 en el deporte de la lucha libre en el a\u00f1o 1969, logrando despertar la admiraci\u00f3n de una gran fanaticada que vio en \u00e9l, a una especie de superh\u00e9roe sin capa, que se desplazaba con agilidad en el cuadril\u00e1tero y saltaba por los aires, siempre promoviendo el buen accionar y el rechazo a las acciones incorrectas. Miles de dominicanos recuerdan con entra\u00f1able cari\u00f1o esa \u00e9poca de oro de la Lucha Libre, siendo Jack Veneno el l\u00edder a seguir y quien conquist\u00f3 al menos seis t\u00edtulos de campe\u00f3n en diferentes categor\u00edas tanto nacionales, como internacionales. El acto estuvo encabezado por el alcalde del Distrito Nacional, David Collado, el ministro de cultura, Eduardo Selman, el viceministro de la Presidencia Lionel Senior, presidente de la Comisi\u00f3n Permanente de Efem\u00e9rides Patrias, Juan Daniel Balc\u00e1cer, el regidor Alejandro Bar\u00f3n, Rosanna Rivera, presidenta de la Asociaci\u00f3n de Amigos de la Zona Colonial, entre otros.<\/p>\n","protected":false},"author":1,"featured_media":88280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-88279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=88279"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88279\/revisions"}],"predecessor-version":[{"id":88281,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88279\/revisions\/88281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/88280"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=88279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=88279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=88279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}