{"id":88701,"date":"2019-04-23T08:46:11","date_gmt":"2019-04-23T12:46:11","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=88701"},"modified":"2019-04-23T08:46:11","modified_gmt":"2019-04-23T12:46:11","slug":"caasd-culmino-trabajos-en-tiempo-record-durante-semana-santa","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/04\/23\/caasd-culmino-trabajos-en-tiempo-record-durante-semana-santa\/","title":{"rendered":"CAASD culmin\u00f3 trabajos en tiempo r\u00e9cord durante Semana Santa\u00a0"},"content":{"rendered":"<p>Busca mejorar abastecimiento de agua potable a sector Cristo Rey con estas obras<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-88702 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-22-at-12.04.10-PM-600x800.jpeg\" alt=\"\" width=\"502\" height=\"669\" \/>Santo Domingo-El director general de la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD), arquitecto Alejandro Mont\u00e1s, inform\u00f3 que durante el asueto de Semana Santa la instituci\u00f3n realiz\u00f3 diferentes obras en diversos puntos del Gran Santo Domingo, al aprovechar el descongestionamiento vehicular propio de esos d\u00edas.<\/p>\n<p>\u00abNuestras brigadas se mantuvieron trabajando, atendiendo a los reportes que rutinariamente se presentan, sobre todo en lo referente a la correcci\u00f3n de aver\u00edas en las redes de agua potable y de alcantarillado sanitario\u00bb, se\u00f1al\u00f3 Mont\u00e1s.<\/p>\n<p>Indic\u00f3 que realizaron la sustituci\u00f3n de una v\u00e1lvula de 24 pulgadas en la avenida M\u00e1ximo G\u00f3mez esquina Nicol\u00e1s Ovando y la colocaci\u00f3n de un empalme y de una tuber\u00eda en las calles Respaldo 35 y Respaldo Ortega y Gasset, en el Distrito Nacional.<\/p>\n<p>\u00abDurante esta Semana Santa, en nuestra instituci\u00f3n aprovechamos este per\u00edodo para ejecutar algunos trabajos que estaban previstos anteriormente y que, por la ubicaci\u00f3n y el tr\u00e1nsito en la zona, no se hab\u00edan podido ejecutar\u00bb, detall\u00f3.<\/p>\n<p>El funcionario se\u00f1al\u00f3 que la Corporaci\u00f3n que dirige busca mejorar abastecimiento de agua potable al sector Cristo Rey con estas obras.<\/p>\n<p>El arquitecto Mont\u00e1s salud\u00f3 el comportamiento c\u00edvico de la poblaci\u00f3n del Gran Santo Domingo durante el asueto de Semana Santa, en cuanto a la reducci\u00f3n del uso de piscinas que se registr\u00f3 tras el llamado que hiciera la entidad debido a la sequ\u00eda que afecta al pa\u00eds.<\/p>\n<p>Alert\u00f3 que la producci\u00f3n de agua potable al d\u00eda de hoy est\u00e1 en unos 385 millones de galones diarios, lo que implica una reducci\u00f3n de 35 millones de galones por d\u00eda.<\/p>\n<p>\u00abEl sistema Haina, aunque tiene su obra de toma reducida, sigue operando en niveles aceptables de producci\u00f3n. Hoy la operaci\u00f3n de este acueducto es de 2.50 metros c\u00fabicos por segundo, pero si en esta semana no se producen lluvias es seguro que su producci\u00f3n bajar\u00e1\u00bb, precis\u00f3 el director de la CAASD.<\/p>\n<p>En tal sentido, Mont\u00e1s exhort\u00f3 a los ciudadanos a seguir haciendo un uso racional del preciado l\u00edquido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Busca mejorar abastecimiento de agua potable a sector Cristo Rey con estas obras Santo Domingo-El director general de la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD), arquitecto Alejandro Mont\u00e1s, inform\u00f3 que durante el asueto de Semana Santa la instituci\u00f3n realiz\u00f3 diferentes obras en diversos puntos del Gran Santo Domingo, al aprovechar el descongestionamiento vehicular propio de esos d\u00edas. \u00abNuestras brigadas se mantuvieron trabajando, atendiendo a los reportes que rutinariamente se presentan, sobre todo en lo referente a la correcci\u00f3n de aver\u00edas en las redes de agua potable y de alcantarillado sanitario\u00bb, se\u00f1al\u00f3 Mont\u00e1s. Indic\u00f3 que realizaron la sustituci\u00f3n de una v\u00e1lvula de 24 pulgadas en la avenida M\u00e1ximo G\u00f3mez esquina Nicol\u00e1s Ovando y la colocaci\u00f3n de un empalme y de una tuber\u00eda en las calles Respaldo 35 y Respaldo Ortega y Gasset, en el Distrito Nacional. \u00abDurante esta Semana Santa, en nuestra instituci\u00f3n aprovechamos este per\u00edodo para ejecutar algunos trabajos que estaban previstos anteriormente y que, por la ubicaci\u00f3n y el tr\u00e1nsito en la zona, no se hab\u00edan podido ejecutar\u00bb, detall\u00f3. El funcionario se\u00f1al\u00f3 que la Corporaci\u00f3n que dirige busca mejorar abastecimiento de agua potable al sector Cristo Rey con estas obras. El arquitecto Mont\u00e1s salud\u00f3 el comportamiento c\u00edvico de la poblaci\u00f3n del Gran Santo Domingo durante el asueto de Semana Santa, en cuanto a la reducci\u00f3n del uso de piscinas que se registr\u00f3 tras el llamado que hiciera la entidad debido a la sequ\u00eda que afecta al pa\u00eds. Alert\u00f3 que la producci\u00f3n de agua potable al d\u00eda de hoy est\u00e1 en unos 385 millones de galones diarios, lo que implica una reducci\u00f3n de 35 millones de galones por d\u00eda. \u00abEl sistema Haina, aunque tiene su obra de toma reducida, sigue operando en niveles aceptables de producci\u00f3n. Hoy la operaci\u00f3n de este acueducto es de 2.50 metros c\u00fabicos por segundo, pero si en esta semana no se producen lluvias es seguro que su producci\u00f3n bajar\u00e1\u00bb, precis\u00f3 el director de la CAASD. En tal sentido, Mont\u00e1s exhort\u00f3 a los ciudadanos a seguir haciendo un uso racional del preciado l\u00edquido.<\/p>\n","protected":false},"author":8,"featured_media":88702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[365,789,269],"class_list":["post-88701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-caasd","tag-record","tag-semana-santa"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=88701"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88701\/revisions"}],"predecessor-version":[{"id":88703,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88701\/revisions\/88703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/88702"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=88701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=88701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=88701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}