{"id":88970,"date":"2019-04-25T13:11:14","date_gmt":"2019-04-25T17:11:14","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=88970"},"modified":"2019-04-25T13:11:14","modified_gmt":"2019-04-25T17:11:14","slug":"rd-haiti-firman-acuerdo-transfronterizo-en-conservacion-marina","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/04\/25\/rd-haiti-firman-acuerdo-transfronterizo-en-conservacion-marina\/","title":{"rendered":"RD-Hait\u00ed firman acuerdo transfronterizo en conservaci\u00f3n marina"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-88971 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/04\/bc8b48d8-b4d0-4324-b7e6-cb76a0363792-800x399.jpg\" alt=\"\" width=\"531\" height=\"265\" \/>Santo Domingo-El Comit\u00e9 Binacional para la Gesti\u00f3n sostenible de la Pesca de la regi\u00f3n de Tres Bah\u00edas y Monte Cristi, apoyado y financiado por el Programa Caribe\u00f1o sobre Biodiversidad Marina( CMBP), Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), se reuni\u00f3 para firmar la Carta del Comit\u00e9 Binacional.<\/p>\n<p>Entres los miembros del Comit\u00e9 Binacional se encuentran altos funcionarios de agencias medioambientales y de pesca de los gobiernos de Hait\u00ed y de la Republica Dominicana.<\/p>\n<p>El directos de pesca y de acuacultura de Hait\u00ed el agr\u00f3nomo \u00a0Robert Bad\u00edo, explic\u00f3 \u2018\u2019 El Comit\u00e9 Binacional es una ocasi\u00f3n para nosotros de compartir conocimientos de ambos lados de la frontera para proteger un paisaje marino compartido que es importante a la vez para las comunidades en Hait\u00ed y en la republica dominicana, y de reforzar la cadena de valores y la econom\u00eda local\u2019\u2019.<\/p>\n<p>El CMBP, es un programa quinquenal implementado en cinco pa\u00edses caribe\u00f1os, Rep\u00fablica Dominicana, Hait\u00ed, Canad\u00e1, Las Granadinas y Jamaica, por un consorcio dirigido por Conservaci\u00f3n de la Naturaleza, los objetivos principales de este programa son reducir las amenazas a los recursos costeros marinos en las zonas prioritarias a fin de realizar una conservaci\u00f3n sostenible de la biodiversidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El Comit\u00e9 Binacional para la Gesti\u00f3n sostenible de la Pesca de la regi\u00f3n de Tres Bah\u00edas y Monte Cristi, apoyado y financiado por el Programa Caribe\u00f1o sobre Biodiversidad Marina( CMBP), Agencia de los Estados Unidos para el Desarrollo Internacional (USAID), se reuni\u00f3 para firmar la Carta del Comit\u00e9 Binacional. Entres los miembros del Comit\u00e9 Binacional se encuentran altos funcionarios de agencias medioambientales y de pesca de los gobiernos de Hait\u00ed y de la Republica Dominicana. El directos de pesca y de acuacultura de Hait\u00ed el agr\u00f3nomo \u00a0Robert Bad\u00edo, explic\u00f3 \u2018\u2019 El Comit\u00e9 Binacional es una ocasi\u00f3n para nosotros de compartir conocimientos de ambos lados de la frontera para proteger un paisaje marino compartido que es importante a la vez para las comunidades en Hait\u00ed y en la republica dominicana, y de reforzar la cadena de valores y la econom\u00eda local\u2019\u2019. El CMBP, es un programa quinquenal implementado en cinco pa\u00edses caribe\u00f1os, Rep\u00fablica Dominicana, Hait\u00ed, Canad\u00e1, Las Granadinas y Jamaica, por un consorcio dirigido por Conservaci\u00f3n de la Naturaleza, los objetivos principales de este programa son reducir las amenazas a los recursos costeros marinos en las zonas prioritarias a fin de realizar una conservaci\u00f3n sostenible de la biodiversidad.<\/p>\n","protected":false},"author":1,"featured_media":88971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-88970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=88970"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88970\/revisions"}],"predecessor-version":[{"id":88973,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88970\/revisions\/88973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/88971"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=88970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=88970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=88970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}