{"id":89103,"date":"2019-04-26T12:51:07","date_gmt":"2019-04-26T16:51:07","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=89103"},"modified":"2019-04-26T12:51:08","modified_gmt":"2019-04-26T16:51:08","slug":"gobierno-asegura-nacionalidad-es-un-atributo-soberano-e-irrenunciable","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/04\/26\/gobierno-asegura-nacionalidad-es-un-atributo-soberano-e-irrenunciable\/","title":{"rendered":"Gobierno asegura nacionalidad es un atributo soberano e irrenunciable"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-89104 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/04\/Flavio-Dar\u00edo-Espinal-1024x550-800x430.jpg\" alt=\"\" width=\"497\" height=\"268\" \/>Santo Domingo-El Gobierno Dominicano asegur\u00f3 que\u00a0su ausencia a la audiencia\u00a0de la Corte Interamericana de Derechos Humanos se debe a que acataron la sentencia del Tribunal Constitucional y que esto no constituye una afrenta a la CorteIDH.<\/p>\n<p>\u201cEsa ausencia de dicha audiencia, no representa una afrenta a la Corte Interamericana como esta se\u00f1ala sino un acatamiento por parte del Gobierno Dominicano a una decisi\u00f3n del Tribunal Constitucional de la Rep\u00fablica Dominicana\u201d, dijo en rueda de prensa el consultor jur\u00eddico del Poder Ejecutivo, Flavio Dar\u00edo Espinal.<br \/>\nAfirm\u00f3 que la nacionalidad es un atributo soberano e irrenunciable.<br \/>\nSobre\u00a0la resoluci\u00f3n de la CorteIDH de atribuirse competencia\u00a0para conocer los casos que tenga que ver con la nacionalidad, el Gobierno dominicano reiter\u00f3 que \u201cla definici\u00f3n de la normativa sobre nacionalidad es un atributo soberano e irrenunciable del Estado dominicano, el cual aplica de manera objetiva e imparcial sus disposiciones constitucionales y legales sobre esta materia\u201d.<\/p>\n<p>En una sorpresiva rueda de prensa el consultor jur\u00eddico del Poder Ejecutivo, Flavio Dar\u00edo Espinal, agreg\u00f3 que lo de la soberan\u00eda en lo referente a la nacionalidad ha sido reconocido por otros organismos y agencias internacionales, as\u00ed como por diferentes actores nacionales o internacionales que le dan seguimiento.<\/p>\n<p>\u201cEl Estado dominicano se ha dotado de una base normativa, tanto a nivel constitucional como legal, que da respuesta a las diferentes situaciones que en materia de nacionalidad puedan presentarse en el pa\u00eds\u201d, asegur\u00f3.<\/p>\n<p>Dijo que, contrario a lo que plantea la CIDH, el ordenamiento jur\u00eddico dominicano no genera apatridia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-El Gobierno Dominicano asegur\u00f3 que\u00a0su ausencia a la audiencia\u00a0de la Corte Interamericana de Derechos Humanos se debe a que acataron la sentencia del Tribunal Constitucional y que esto no constituye una afrenta a la CorteIDH. \u201cEsa ausencia de dicha audiencia, no representa una afrenta a la Corte Interamericana como esta se\u00f1ala sino un acatamiento por parte del Gobierno Dominicano a una decisi\u00f3n del Tribunal Constitucional de la Rep\u00fablica Dominicana\u201d, dijo en rueda de prensa el consultor jur\u00eddico del Poder Ejecutivo, Flavio Dar\u00edo Espinal. Afirm\u00f3 que la nacionalidad es un atributo soberano e irrenunciable. Sobre\u00a0la resoluci\u00f3n de la CorteIDH de atribuirse competencia\u00a0para conocer los casos que tenga que ver con la nacionalidad, el Gobierno dominicano reiter\u00f3 que \u201cla definici\u00f3n de la normativa sobre nacionalidad es un atributo soberano e irrenunciable del Estado dominicano, el cual aplica de manera objetiva e imparcial sus disposiciones constitucionales y legales sobre esta materia\u201d. En una sorpresiva rueda de prensa el consultor jur\u00eddico del Poder Ejecutivo, Flavio Dar\u00edo Espinal, agreg\u00f3 que lo de la soberan\u00eda en lo referente a la nacionalidad ha sido reconocido por otros organismos y agencias internacionales, as\u00ed como por diferentes actores nacionales o internacionales que le dan seguimiento. \u201cEl Estado dominicano se ha dotado de una base normativa, tanto a nivel constitucional como legal, que da respuesta a las diferentes situaciones que en materia de nacionalidad puedan presentarse en el pa\u00eds\u201d, asegur\u00f3. Dijo que, contrario a lo que plantea la CIDH, el ordenamiento jur\u00eddico dominicano no genera apatridia.<\/p>\n","protected":false},"author":8,"featured_media":89104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[163,876],"class_list":["post-89103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-gobierno","tag-nacionalidad"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=89103"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89103\/revisions"}],"predecessor-version":[{"id":89105,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89103\/revisions\/89105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/89104"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=89103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=89103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=89103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}