{"id":89289,"date":"2019-05-01T10:19:50","date_gmt":"2019-05-01T14:19:50","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=89289"},"modified":"2019-05-01T10:19:50","modified_gmt":"2019-05-01T14:19:50","slug":"apresan-a-dos-jovenes-acusados-de-presunta-violencia-de-genero-e-intrafamiliar-en-montecristi","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/05\/01\/apresan-a-dos-jovenes-acusados-de-presunta-violencia-de-genero-e-intrafamiliar-en-montecristi\/","title":{"rendered":"Apresan a dos j\u00f3venes acusados de presunta violencia de g\u00e9nero e intrafamiliar en Montecristi"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-89290 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/05\/Apresados-1024x550-800x430.jpg\" alt=\"\" width=\"508\" height=\"273\" \/>MONTECRISTI-La Polic\u00eda inform\u00f3 este mi\u00e9rcoles que fueron apresados Carlos Guevara Abreu y Miguel Rom\u00e1n Almonte Fern\u00e1ndez, de 22 y 18 a\u00f1os de edad, respectivamente, acusados de presunta violencia de g\u00e9nero e intrafamiliar, en hechos registrados por separado en esta provincia.<\/p>\n<p>Un comunicado de la Polic\u00eda se\u00f1ala que Guevara Abreu, residente en el sector Buenos Aires, de este municipio, fue detenido con una orden de arresto, emitida por la Oficina Judicial de Servicio de Atenci\u00f3n Permanente, del distrito judicial de Montecristi, tras formal querella presentada en su contra por su expareja Andrea Mariel Guzm\u00e1n Ortiz.<\/p>\n<p>En tanto que, Almonte Fern\u00e1ndez, residente en el sector Los \u00c1ngeles, de este municipio, fue apresado con orden de arresto, por presunta violaci\u00f3n a los art\u00edculos 309-1 y 2 del C\u00f3digo Penal Dominicano, en perjuicio de su madre Candy Ver\u00f3nica de Jes\u00fas Fern\u00e1ndez Ortega.<\/p>\n<p>El citado comunicado indica que al momento de su detenci\u00f3n, Almonte se resisti\u00f3 al arresto, por lo que \u00a0result\u00f3 con hematoma en el brazo izquierdo y laceraciones tor\u00e1cicas y rodilla derecha, al aplic\u00e1rsele t\u00e9cnicas policiales para someterlo a la obediencia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTECRISTI-La Polic\u00eda inform\u00f3 este mi\u00e9rcoles que fueron apresados Carlos Guevara Abreu y Miguel Rom\u00e1n Almonte Fern\u00e1ndez, de 22 y 18 a\u00f1os de edad, respectivamente, acusados de presunta violencia de g\u00e9nero e intrafamiliar, en hechos registrados por separado en esta provincia. Un comunicado de la Polic\u00eda se\u00f1ala que Guevara Abreu, residente en el sector Buenos Aires, de este municipio, fue detenido con una orden de arresto, emitida por la Oficina Judicial de Servicio de Atenci\u00f3n Permanente, del distrito judicial de Montecristi, tras formal querella presentada en su contra por su expareja Andrea Mariel Guzm\u00e1n Ortiz. En tanto que, Almonte Fern\u00e1ndez, residente en el sector Los \u00c1ngeles, de este municipio, fue apresado con orden de arresto, por presunta violaci\u00f3n a los art\u00edculos 309-1 y 2 del C\u00f3digo Penal Dominicano, en perjuicio de su madre Candy Ver\u00f3nica de Jes\u00fas Fern\u00e1ndez Ortega. El citado comunicado indica que al momento de su detenci\u00f3n, Almonte se resisti\u00f3 al arresto, por lo que \u00a0result\u00f3 con hematoma en el brazo izquierdo y laceraciones tor\u00e1cicas y rodilla derecha, al aplic\u00e1rsele t\u00e9cnicas policiales para someterlo a la obediencia. &nbsp;<\/p>\n","protected":false},"author":8,"featured_media":89290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[910,891,257],"class_list":["post-89289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-intrafamiliar","tag-jovenes","tag-montecristi"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=89289"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89289\/revisions"}],"predecessor-version":[{"id":89291,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89289\/revisions\/89291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/89290"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=89289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=89289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=89289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}