{"id":89474,"date":"2019-05-03T12:25:25","date_gmt":"2019-05-03T16:25:25","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=89474"},"modified":"2019-05-03T12:25:25","modified_gmt":"2019-05-03T16:25:25","slug":"wilson-roa-aqui-hay-que-echar-dos-pleitos-tras-levantar-paro-ars-humano","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/05\/03\/wilson-roa-aqui-hay-que-echar-dos-pleitos-tras-levantar-paro-ars-humano\/","title":{"rendered":"Wilson Roa \u201caqu\u00ed hay que echar dos pleitos\u201d , tras levantar paro ARS-Humano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-89475 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/05\/ars-y-cmf_11580648_20190502185701.jpg\" alt=\"\" width=\"509\" height=\"326\" \/>Santo Domingo-\u201cEstamos en un pa\u00eds que se llama Rep\u00fablica Dominicana. Aqu\u00ed hay que echar dos pleitos: uno para ponernos de acuerdo y otro para hacer que los acuerdos se cumplan\u201d, dijo el presidente del Colegio M\u00e9dico Dominicano (CMD), Wilson Roa, tras firmar un convenio que la tarde de ayer levant\u00f3 el paro de servicios que ese gremio y otros manten\u00edan desde el mi\u00e9rcoles en contra de la aseguradora Primera ARS de Humano.<\/p>\n<p>Roa se refer\u00eda a que para terminar el conflicto se tuvo que firmar un \u201cAcuerdo de Ratificaci\u00f3n de Compromisos\u201d establecidos el 31 de mayo de 2017, que incluyen impulsar un aumento de la c\u00e1pita para producir la actualizaci\u00f3n de los honorarios y tarifas profesionales, esto, ahora, a m\u00e1s tardar en julio.<\/p>\n<p>Antes de comenzar el paro contra la Primera ARS de Humano -de 1.4 millones de afiliados-, Roa se quej\u00f3 de que la aseguradora paga a un especialista RD$262 por paciente. Anunci\u00f3 que se comenz\u00f3 con esa administradora y luego tomar\u00edan acciones con otras.<\/p>\n<p>Adem\u00e1s de ARS Humano, el acuerdo de ayer tambi\u00e9n lo firmaron ARS Palic Salud y ARS Universal, del grupo con m\u00e1s afiliados en el r\u00e9gimen contributivo del Seguro Familiar de Salud.<\/p>\n<p>\u201cAqu\u00ed hay dos opciones: o cumplimos lo acordado que no se hab\u00eda cumplido hasta el acuerdo de hoy (ayer) o cumplimos lo acordado que hoy (ayer) hemos ratificado\u201d, sentenci\u00f3 Roa.<\/p>\n<p>Durante la rueda de prensa en la que se anunci\u00f3 el convenio, Jos\u00e9 Manuel Vargas, presidente ejecutivo de la Asociaci\u00f3n Dominicana de Administradoras de Riesgos de Salud (ADARS), evadi\u00f3 responder por qu\u00e9 no se ha cumplido con el acuerdo que la entidad firm\u00f3 en 2017 con el CMD y el Consejo Nacional de Sociedades M\u00e9dicas Especializadas (Conasomep). \u201cEsperamos que este sea el camino: el di\u00e1logo\u201d, dijo.<br \/>\nPacientes: los sufridos<br \/>\nEn un principio se anunci\u00f3 que el acuerdo se firmar\u00eda el mi\u00e9rcoles, sin embargo ese d\u00eda los gremios en paro lo analizaban mientras la suspensi\u00f3n corr\u00eda.<\/p>\n<p>Ayer en la ma\u00f1ana, el flujo de pacientes en busca de servicios en cl\u00ednicas privadas disminuy\u00f3 significativamente debido al conflicto que se super\u00f3 en la tarde. En un recorrido por varios centros asistenciales se pudo comprobar que muchos afiliados a la Primera ARS de Humano no acudieron a las consultas ni a realizarse procedimientos o an\u00e1lisis m\u00e9dicos.<\/p>\n<p>En tres cl\u00ednicas visitadas por\u00a0Diario Libre\u00a0solo fueron contactados tres pacientes de la ARS, dos de los cuales desconoc\u00edan la suspensi\u00f3n de los servicios a la Administradora de Riesgos de Salud (ARS), en tanto que las secretarias de algunos m\u00e9dicos informaron que, de manera privada, atendieron a \u201cuna persona\u201d.<\/p>\n<p>Humano notific\u00f3 que reembolsar\u00e1 a todos los afiliados que hayan pagado consultas u otros servicios m\u00e9dicos, sin embargo, esto se ha visto afectado porque algunos doctores no entregan facturas a los pacientes.<\/p>\n<p>Solo un m\u00e9dico pediatra afiliado a la ARS no se hab\u00eda acogido al paro ejecutado por el CMD, junto al Conasomep y a la Asociaci\u00f3n Nacional de Cl\u00ednicas y Hospitales Privados (Andeclip).<\/p>\n<p>Algunos puntos del acuerdo ser\u00e1n de implementaci\u00f3n directa y otros deben ir al Consejo Nacional de Seguridad Social (CNSS). Fungir\u00e1n como garantes de que el convenio ahora s\u00ed se cumpla el Ministerio de Trabajo y la Superintendencia de Salud y Riesgos Laborales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-\u201cEstamos en un pa\u00eds que se llama Rep\u00fablica Dominicana. Aqu\u00ed hay que echar dos pleitos: uno para ponernos de acuerdo y otro para hacer que los acuerdos se cumplan\u201d, dijo el presidente del Colegio M\u00e9dico Dominicano (CMD), Wilson Roa, tras firmar un convenio que la tarde de ayer levant\u00f3 el paro de servicios que ese gremio y otros manten\u00edan desde el mi\u00e9rcoles en contra de la aseguradora Primera ARS de Humano. Roa se refer\u00eda a que para terminar el conflicto se tuvo que firmar un \u201cAcuerdo de Ratificaci\u00f3n de Compromisos\u201d establecidos el 31 de mayo de 2017, que incluyen impulsar un aumento de la c\u00e1pita para producir la actualizaci\u00f3n de los honorarios y tarifas profesionales, esto, ahora, a m\u00e1s tardar en julio. Antes de comenzar el paro contra la Primera ARS de Humano -de 1.4 millones de afiliados-, Roa se quej\u00f3 de que la aseguradora paga a un especialista RD$262 por paciente. Anunci\u00f3 que se comenz\u00f3 con esa administradora y luego tomar\u00edan acciones con otras. Adem\u00e1s de ARS Humano, el acuerdo de ayer tambi\u00e9n lo firmaron ARS Palic Salud y ARS Universal, del grupo con m\u00e1s afiliados en el r\u00e9gimen contributivo del Seguro Familiar de Salud. \u201cAqu\u00ed hay dos opciones: o cumplimos lo acordado que no se hab\u00eda cumplido hasta el acuerdo de hoy (ayer) o cumplimos lo acordado que hoy (ayer) hemos ratificado\u201d, sentenci\u00f3 Roa. Durante la rueda de prensa en la que se anunci\u00f3 el convenio, Jos\u00e9 Manuel Vargas, presidente ejecutivo de la Asociaci\u00f3n Dominicana de Administradoras de Riesgos de Salud (ADARS), evadi\u00f3 responder por qu\u00e9 no se ha cumplido con el acuerdo que la entidad firm\u00f3 en 2017 con el CMD y el Consejo Nacional de Sociedades M\u00e9dicas Especializadas (Conasomep). \u201cEsperamos que este sea el camino: el di\u00e1logo\u201d, dijo. Pacientes: los sufridos En un principio se anunci\u00f3 que el acuerdo se firmar\u00eda el mi\u00e9rcoles, sin embargo ese d\u00eda los gremios en paro lo analizaban mientras la suspensi\u00f3n corr\u00eda. Ayer en la ma\u00f1ana, el flujo de pacientes en busca de servicios en cl\u00ednicas privadas disminuy\u00f3 significativamente debido al conflicto que se super\u00f3 en la tarde. En un recorrido por varios centros asistenciales se pudo comprobar que muchos afiliados a la Primera ARS de Humano no acudieron a las consultas ni a realizarse procedimientos o an\u00e1lisis m\u00e9dicos. En tres cl\u00ednicas visitadas por\u00a0Diario Libre\u00a0solo fueron contactados tres pacientes de la ARS, dos de los cuales desconoc\u00edan la suspensi\u00f3n de los servicios a la Administradora de Riesgos de Salud (ARS), en tanto que las secretarias de algunos m\u00e9dicos informaron que, de manera privada, atendieron a \u201cuna persona\u201d. Humano notific\u00f3 que reembolsar\u00e1 a todos los afiliados que hayan pagado consultas u otros servicios m\u00e9dicos, sin embargo, esto se ha visto afectado porque algunos doctores no entregan facturas a los pacientes. Solo un m\u00e9dico pediatra afiliado a la ARS no se hab\u00eda acogido al paro ejecutado por el CMD, junto al Conasomep y a la Asociaci\u00f3n Nacional de Cl\u00ednicas y Hospitales Privados (Andeclip). Algunos puntos del acuerdo ser\u00e1n de implementaci\u00f3n directa y otros deben ir al Consejo Nacional de Seguridad Social (CNSS). Fungir\u00e1n como garantes de que el convenio ahora s\u00ed se cumpla el Ministerio de Trabajo y la Superintendencia de Salud y Riesgos Laborales.<\/p>\n","protected":false},"author":1,"featured_media":89475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-89474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=89474"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89474\/revisions"}],"predecessor-version":[{"id":89476,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89474\/revisions\/89476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/89475"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=89474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=89474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=89474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}