{"id":89917,"date":"2019-05-09T11:52:40","date_gmt":"2019-05-09T15:52:40","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=89917"},"modified":"2019-05-09T11:52:40","modified_gmt":"2019-05-09T15:52:40","slug":"expresidente-michel-temer-se-entregara-a-justicia-con-total-tranquilidad-tras-tribunal-ordenara-regreso-a-prision","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/05\/09\/expresidente-michel-temer-se-entregara-a-justicia-con-total-tranquilidad-tras-tribunal-ordenara-regreso-a-prision\/","title":{"rendered":"Expresidente Michel Temer se entregar\u00e1 a Justicia \u201ccon total tranquilidad\u201d tras tribunal ordenara regreso a prisi\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-89918 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/05\/AFP_008272714-676x450.jpg\" alt=\"\" width=\"500\" height=\"333\" \/>Sao Paulo.- El expresidente brasile\u00f1o Michel Temer asegur\u00f3 este mi\u00e9rcoles que se presentar\u00e1 ante las autoridades \u201ccon total tranquilidad\u201d el jueves, despu\u00e9s de que un tribunal de segunda instancia ordenara su regreso a prisi\u00f3n por sospechas de corrupci\u00f3n.<\/p>\n<p>\u201cVoy a presentarme, no tengo ning\u00fan problema con eso\u201d, afirm\u00f3 en declaraciones a los periodistas en frente a su casa en la ciudad de Sao Paulo y a\u00f1adi\u00f3 que, tras la decisi\u00f3n judicial, pasar\u00e1 la noche en su domicilio.<\/p>\n<p>El Tribunal Regional de la Segunda Regi\u00f3n (TRF-2) de R\u00edo de Janeiro determin\u00f3 este mi\u00e9rcoles por 2 votos a 1 el regreso a prisi\u00f3n de Temer, quien ya hab\u00eda sido arrestado el pasado 21 de marzo por orden del juez de primera instancia Marcelo Bretas.<\/p>\n<p>El exmandatario, de 78 a\u00f1os y quien gobern\u00f3 entre\u00a02016 y 2018,\u00a0pas\u00f3 cuatro d\u00edas entre rejas tras ser detenido en una v\u00eda p\u00fablica de Sao Paulo el pasado marzo, pero uno de los jueces del TRF-2 le concedi\u00f3 un h\u00e1beas corpus antes de que la decisi\u00f3n fuera analizada por el \u00f3rgano colegiado.<\/p>\n<p>Temer se dijo sorprendido con la medida y consider\u00f3 que est\u00e1 \u201ctotalmente equivocada\u201d desde el punto de vista jur\u00eddico. \u201cSiempre sostuve que en esas cuestiones no hay prueba. Para m\u00ed, fue una sorpresa desagradable, pero yo ma\u00f1ana me presento voluntariamente\u201d, agreg\u00f3.<\/p>\n<p>El ex jefe de Estado, quien durante m\u00e1s de una d\u00e9cada presidi\u00f3 el partido del Movimiento Democr\u00e1tico Brasile\u00f1o (MDB), asegur\u00f3 que presentar\u00e1 una solicitud de h\u00e1beas corpus ante el Tribunal Superior de Justicia, instancia superior, y recalc\u00f3 que defender\u00e1 sus derechos \u201chasta el fin\u201d.<\/p>\n<p>El pol\u00edtico fue arrestado el pasado 21 de marzo y fue trasladado a la sede de la Polic\u00eda Federal de R\u00edo de Janeiro, donde permaneci\u00f3 detenido cuatro d\u00edas tras la orden de prisi\u00f3n del juez de primera instancia Marcelo Bretas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sao Paulo.- El expresidente brasile\u00f1o Michel Temer asegur\u00f3 este mi\u00e9rcoles que se presentar\u00e1 ante las autoridades \u201ccon total tranquilidad\u201d el jueves, despu\u00e9s de que un tribunal de segunda instancia ordenara su regreso a prisi\u00f3n por sospechas de corrupci\u00f3n. \u201cVoy a presentarme, no tengo ning\u00fan problema con eso\u201d, afirm\u00f3 en declaraciones a los periodistas en frente a su casa en la ciudad de Sao Paulo y a\u00f1adi\u00f3 que, tras la decisi\u00f3n judicial, pasar\u00e1 la noche en su domicilio. El Tribunal Regional de la Segunda Regi\u00f3n (TRF-2) de R\u00edo de Janeiro determin\u00f3 este mi\u00e9rcoles por 2 votos a 1 el regreso a prisi\u00f3n de Temer, quien ya hab\u00eda sido arrestado el pasado 21 de marzo por orden del juez de primera instancia Marcelo Bretas. El exmandatario, de 78 a\u00f1os y quien gobern\u00f3 entre\u00a02016 y 2018,\u00a0pas\u00f3 cuatro d\u00edas entre rejas tras ser detenido en una v\u00eda p\u00fablica de Sao Paulo el pasado marzo, pero uno de los jueces del TRF-2 le concedi\u00f3 un h\u00e1beas corpus antes de que la decisi\u00f3n fuera analizada por el \u00f3rgano colegiado. Temer se dijo sorprendido con la medida y consider\u00f3 que est\u00e1 \u201ctotalmente equivocada\u201d desde el punto de vista jur\u00eddico. \u201cSiempre sostuve que en esas cuestiones no hay prueba. Para m\u00ed, fue una sorpresa desagradable, pero yo ma\u00f1ana me presento voluntariamente\u201d, agreg\u00f3. El ex jefe de Estado, quien durante m\u00e1s de una d\u00e9cada presidi\u00f3 el partido del Movimiento Democr\u00e1tico Brasile\u00f1o (MDB), asegur\u00f3 que presentar\u00e1 una solicitud de h\u00e1beas corpus ante el Tribunal Superior de Justicia, instancia superior, y recalc\u00f3 que defender\u00e1 sus derechos \u201chasta el fin\u201d. El pol\u00edtico fue arrestado el pasado 21 de marzo y fue trasladado a la sede de la Polic\u00eda Federal de R\u00edo de Janeiro, donde permaneci\u00f3 detenido cuatro d\u00edas tras la orden de prisi\u00f3n del juez de primera instancia Marcelo Bretas.<\/p>\n","protected":false},"author":8,"featured_media":89918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[632,962,173],"class_list":["post-89917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","tag-justicia","tag-michel-temer","tag-prision"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=89917"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89917\/revisions"}],"predecessor-version":[{"id":89919,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/89917\/revisions\/89919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/89918"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=89917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=89917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=89917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}