{"id":90980,"date":"2019-05-30T15:06:55","date_gmt":"2019-05-30T19:06:55","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=90980"},"modified":"2019-05-30T15:06:55","modified_gmt":"2019-05-30T19:06:55","slug":"residentes-de-barrio-nuevo-de-los-frailes-ii-dicen-delincuencia-los-tiene-en-zozobra","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/05\/30\/residentes-de-barrio-nuevo-de-los-frailes-ii-dicen-delincuencia-los-tiene-en-zozobra\/","title":{"rendered":"Residentes de Barrio Nuevo de Los Frailes II dicen: delincuencia los tiene en Zozobra"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-90981 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/05\/Codo-se\u00f1ora-Yanet-Acevedo-800x411.jpg\" alt=\"\" width=\"415\" height=\"213\" \/>Santo Domingo-Residentes de Barrio Nuevo de Los Frailes II expresan vivir en zozobra con los atracos a mano armada, rob\u00f3 de motocicletas, lavadora, electrodom\u00e9sticos bater\u00eda de inversores y de carros, tambi\u00e9n celulares,\u00a0son solo algunas de las acciones delictivas de desaprensivos en el sector de Barrio Nuevo en Los Frailes II de Santo\u00a0Domingo Este.<\/p>\n<p>Tan\u00a0solo en una semana se registraron 6 acciones delictivas en una misma cuadra, en todos los casos los\u00a0violadores\u00a0de la ley,\u00a0portaban armas de fuego.<\/p>\n<p>La imagen muestra el codo ensangrentado, de la se\u00f1ora\u00a0Yanet Acevedo,\u00a0de 28 a\u00f1os de edad,\u00a0una herida ocasionada cuando\u00a0fue arrastrada cuando dos en una motocicleta intentaron arrebatarle la cartera en hora de la ma\u00f1ana, cuando se dirig\u00eda a su trabajo.<\/p>\n<p>D\u00edas antes le dispararon a un joven que salv\u00f3 la vida de milagro cuando no dej\u00f3 que le robaran su celular.<\/p>\n<p>Lo delincuente mantienen acciones sistem\u00e1ticas, robando bater\u00edas de veh\u00edculos y otros art\u00edculos.<\/p>\n<p>Una familia tambi\u00e9n denunci\u00f3, el robo de una lavadora, sustra\u00edda en horas de la madrugada de su vivienda.<\/p>\n<p>Los mun\u00edcipes afirman que en la zona la\u00a0polic\u00eda\u00a0est\u00e1 ausente,\u00a0no hay patrullas situaci\u00f3n por la cual los\u00a0delincuentes andan en sus anchas.<\/p>\n<p>Piden al presidente Danilo Medina que d\u00e9 instrucciones al director de la polic\u00eda para dispongan de la vigilancia necesaria para llevar tranquilidad a esta comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo-Residentes de Barrio Nuevo de Los Frailes II expresan vivir en zozobra con los atracos a mano armada, rob\u00f3 de motocicletas, lavadora, electrodom\u00e9sticos bater\u00eda de inversores y de carros, tambi\u00e9n celulares,\u00a0son solo algunas de las acciones delictivas de desaprensivos en el sector de Barrio Nuevo en Los Frailes II de Santo\u00a0Domingo Este. Tan\u00a0solo en una semana se registraron 6 acciones delictivas en una misma cuadra, en todos los casos los\u00a0violadores\u00a0de la ley,\u00a0portaban armas de fuego. La imagen muestra el codo ensangrentado, de la se\u00f1ora\u00a0Yanet Acevedo,\u00a0de 28 a\u00f1os de edad,\u00a0una herida ocasionada cuando\u00a0fue arrastrada cuando dos en una motocicleta intentaron arrebatarle la cartera en hora de la ma\u00f1ana, cuando se dirig\u00eda a su trabajo. D\u00edas antes le dispararon a un joven que salv\u00f3 la vida de milagro cuando no dej\u00f3 que le robaran su celular. Lo delincuente mantienen acciones sistem\u00e1ticas, robando bater\u00edas de veh\u00edculos y otros art\u00edculos. Una familia tambi\u00e9n denunci\u00f3, el robo de una lavadora, sustra\u00edda en horas de la madrugada de su vivienda. Los mun\u00edcipes afirman que en la zona la\u00a0polic\u00eda\u00a0est\u00e1 ausente,\u00a0no hay patrullas situaci\u00f3n por la cual los\u00a0delincuentes andan en sus anchas. Piden al presidente Danilo Medina que d\u00e9 instrucciones al director de la polic\u00eda para dispongan de la vigilancia necesaria para llevar tranquilidad a esta comunidad.<\/p>\n","protected":false},"author":1,"featured_media":90981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-90980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/90980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=90980"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/90980\/revisions"}],"predecessor-version":[{"id":90982,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/90980\/revisions\/90982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/90981"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=90980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=90980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=90980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}