{"id":91333,"date":"2019-06-06T19:49:32","date_gmt":"2019-06-06T23:49:32","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=91333"},"modified":"2019-06-06T19:49:32","modified_gmt":"2019-06-06T23:49:32","slug":"dncd-dice-510-paquetes-de-polvo-blanco-incautados-no-eran-de-droga","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/06\/06\/dncd-dice-510-paquetes-de-polvo-blanco-incautados-no-eran-de-droga\/","title":{"rendered":"DNCD dice 510 paquetes de polvo blanco incautados no eran de droga"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-91334 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/06\/droga-dncd_11750272_20190606152752.jpg\" alt=\"\" width=\"462\" height=\"296\" \/>La Direcci\u00f3n Nacional de Control de Drogas (DNCD) inform\u00f3 este jueves que no corresponden a sustancias controladas los 510 paquetes de un polvo que se presum\u00eda coca\u00edna ocupados en una residencia del sector Cancino, municipio Santo Domingo Este.<\/p>\n<p>En un comunicado de prensa la instituci\u00f3n dice que el Instituto Nacional de Ciencias Forenses (INACIF) certifico que solo 3.53 gramos del alijo result\u00f3 positivo a coca\u00edna, y en el resto \u201cno se encontraron muestras de drogas\u201d.<\/p>\n<p>\u00abLa DNCD y el Ministerio P\u00fablico manejan informes de inteligencia de que podr\u00eda tratarse de una estructura criminal que se dedica a preparar sustancias narc\u00f3ticas falsas para luego venderla a otros grupos dedicados a esa pr\u00e1ctica ilegal, tanto en el pa\u00eds como en el exterior\u00bb se\u00f1ala el comunicado.<\/p>\n<p>Ocupaci\u00f3n de la sustancia<\/p>\n<p>Durante una rueda de prensa la DNCD present\u00f3 510 paquetes de una sustancia que presume es coca\u00edna, la cual dijo fue incautada en un operativo en el sector Cancino, en el municipio Santo Domingo Este.<\/p>\n<p>En el operativo, en el cual adem\u00e1s de la DNCD particip\u00f3 la Polic\u00eda Nacional y la Procuradur\u00eda Especializada contra el Lavado de Activos, fueron apresadas cinco personas, cuatro dominicanos y un arube\u00f1o.<\/p>\n<p>Entre los cinco detenidos hay dos mujeres, de acuerdo a una nota de prensa de la entidad.<\/p>\n<p>Asimismo, las autoridades se incautaron alrededor de 10 mil d\u00f3lares estadounidenses, 60 mil pesos dominicanos dos veh\u00edculos y dos pistolas con decenas de c\u00e1psulas.<\/p>\n<p>Tambi\u00e9n se ocup\u00f3 prensas hidr\u00e1ulicas, papel de envoltura y otras evidencias.<\/p>\n<p>Los allanamientos fueron realizados en tres viviendas de las calles Capotillo, Manacla y Canoa, del sector Cancino.<\/p>\n<p>La que hasta ese momento se consideraba droga estaba escondida en una de las casas, distribuida de la siguiente manera: 396 paquetes, en la habitaci\u00f3n principal; 92 paquetes, en la parte trasera, y otros 22 paquetes en la despensa de la cocina.<\/p>\n<p>El vocero de la DNCD, Carlos Devers, dijo que otras 15 personas estaban siendo interrogadas con relaci\u00f3n a ese caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Nacional de Control de Drogas (DNCD) inform\u00f3 este jueves que no corresponden a sustancias controladas los 510 paquetes de un polvo que se presum\u00eda coca\u00edna ocupados en una residencia del sector Cancino, municipio Santo Domingo Este. En un comunicado de prensa la instituci\u00f3n dice que el Instituto Nacional de Ciencias Forenses (INACIF) certifico que solo 3.53 gramos del alijo result\u00f3 positivo a coca\u00edna, y en el resto \u201cno se encontraron muestras de drogas\u201d. \u00abLa DNCD y el Ministerio P\u00fablico manejan informes de inteligencia de que podr\u00eda tratarse de una estructura criminal que se dedica a preparar sustancias narc\u00f3ticas falsas para luego venderla a otros grupos dedicados a esa pr\u00e1ctica ilegal, tanto en el pa\u00eds como en el exterior\u00bb se\u00f1ala el comunicado. Ocupaci\u00f3n de la sustancia Durante una rueda de prensa la DNCD present\u00f3 510 paquetes de una sustancia que presume es coca\u00edna, la cual dijo fue incautada en un operativo en el sector Cancino, en el municipio Santo Domingo Este. En el operativo, en el cual adem\u00e1s de la DNCD particip\u00f3 la Polic\u00eda Nacional y la Procuradur\u00eda Especializada contra el Lavado de Activos, fueron apresadas cinco personas, cuatro dominicanos y un arube\u00f1o. Entre los cinco detenidos hay dos mujeres, de acuerdo a una nota de prensa de la entidad. Asimismo, las autoridades se incautaron alrededor de 10 mil d\u00f3lares estadounidenses, 60 mil pesos dominicanos dos veh\u00edculos y dos pistolas con decenas de c\u00e1psulas. Tambi\u00e9n se ocup\u00f3 prensas hidr\u00e1ulicas, papel de envoltura y otras evidencias. Los allanamientos fueron realizados en tres viviendas de las calles Capotillo, Manacla y Canoa, del sector Cancino. La que hasta ese momento se consideraba droga estaba escondida en una de las casas, distribuida de la siguiente manera: 396 paquetes, en la habitaci\u00f3n principal; 92 paquetes, en la parte trasera, y otros 22 paquetes en la despensa de la cocina. El vocero de la DNCD, Carlos Devers, dijo que otras 15 personas estaban siendo interrogadas con relaci\u00f3n a ese caso.<\/p>\n","protected":false},"author":8,"featured_media":91334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-91333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=91333"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91333\/revisions"}],"predecessor-version":[{"id":91335,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91333\/revisions\/91335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/91334"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=91333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=91333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=91333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}