{"id":92778,"date":"2019-07-09T08:42:13","date_gmt":"2019-07-09T12:42:13","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=92778"},"modified":"2019-07-09T08:42:13","modified_gmt":"2019-07-09T12:42:13","slug":"al-menos-34-personas-han-muerto-a-causa-de-dengue","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/07\/09\/al-menos-34-personas-han-muerto-a-causa-de-dengue\/","title":{"rendered":"Al menos 34 personas han muerto a causa de dengue"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-92779 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/07\/5A_El-Pa\u00eds_09_1okeyp01-800x450-800x450.jpg\" alt=\"\" width=\"476\" height=\"268\" \/>Al menos 34 personas han muerto por dengue en la Rep\u00fablica Dominicana en lo que va de a\u00f1o, seg\u00fan datos recabados en diferentes hospitales. Al respecto, el ministro de Salud, Rafael S\u00e1nchez C\u00e1rdenas, solo admite que han confirmado tres defunciones y dice que las dem\u00e1s son auditadas por una comisi\u00f3n oficial.<br \/>\nSolo en tres hospitales de Santo Domingo amanecieron con 63 ni\u00f1os ingresados con la enfermedad que es causada por el mosquito Aedes aegypti.<br \/>\nEl tema genera preocupaci\u00f3n pues a la semana epidemiol\u00f3gica n\u00famero 23 no se registra ninguna defunci\u00f3n: el bolet\u00edn oficial establece que el 82% de los casos corresponden a menores de 15 a\u00f1os de edad.<br \/>\nCon relaci\u00f3n al n\u00famero de casos, el Robert Reid Cabral ten\u00eda ingresados a 38 menores de edad y se hab\u00edan registrado 21 defunciones, el hospital Hugo Mendoza ten\u00eda 28 casos y una defunci\u00f3n, mientras que en lo que va de a\u00f1o el Hospital General de la Plaza de la Salud ha ingresado 208 personas con dengue y han fallecido dos, seg\u00fan se inform\u00f3 a Hoy.<br \/>\nAsimismo, en la maternidad San Lorenzo de Los Mina ha habido una defunci\u00f3n, dos menores fallecieron en el hospital Arturo Grull\u00f3n de Santiago y siete fueron reportados en el hospital de Barahona, en el Sur del pa\u00eds.<br \/>\nLas acciones. Los Ministerios de Salud de P\u00fablica, Defensa y Obras P\u00fablicas iniciaron la ejecuci\u00f3n de una campa\u00f1a contra el dengue, que se centra en eliminar criaderos de mosquitos, inclusi\u00f3n y concienciaci\u00f3n de la sociedad en promover la salud a fin de evitar la propagaci\u00f3n del mosquito Aedes Aegypti. S\u00e1nchez C\u00e1rdenas dijo que se tienen identificados los principales focos de acci\u00f3n donde el Ministerio de Defensa dar\u00e1 soporte con la disposici\u00f3n de su personal en labores de fumigaci\u00f3n, descacharrizaci\u00f3n y limpieza de espacios propensos a la multiplicaci\u00f3n del mosquito transmisor de dicha enfermedad. I ndic\u00f3 que estas acciones, en conjunto con los ministerios de Defesa y Obras P\u00fablicas, reforzar\u00e1n las estrategias que desarrolla el organismo de Salud, con la finalidad de disminuir la propagaci\u00f3n de enfermedades.\u201cHan sido identificados unos 32 municipios a los que se dar\u00e1 prioridad en estas labores\u201d.<br \/>\nEl pa\u00eds, al igual que otros pa\u00edses de Centro y Suramerica, se encuentra en una alerta emitida por la Organizaci\u00f3n Panamericana de la Salud y RD ocupa el puesto n\u00famero nueve de los diez pa\u00edses con mayor incidencia de dengue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 34 personas han muerto por dengue en la Rep\u00fablica Dominicana en lo que va de a\u00f1o, seg\u00fan datos recabados en diferentes hospitales. Al respecto, el ministro de Salud, Rafael S\u00e1nchez C\u00e1rdenas, solo admite que han confirmado tres defunciones y dice que las dem\u00e1s son auditadas por una comisi\u00f3n oficial. Solo en tres hospitales de Santo Domingo amanecieron con 63 ni\u00f1os ingresados con la enfermedad que es causada por el mosquito Aedes aegypti. El tema genera preocupaci\u00f3n pues a la semana epidemiol\u00f3gica n\u00famero 23 no se registra ninguna defunci\u00f3n: el bolet\u00edn oficial establece que el 82% de los casos corresponden a menores de 15 a\u00f1os de edad. Con relaci\u00f3n al n\u00famero de casos, el Robert Reid Cabral ten\u00eda ingresados a 38 menores de edad y se hab\u00edan registrado 21 defunciones, el hospital Hugo Mendoza ten\u00eda 28 casos y una defunci\u00f3n, mientras que en lo que va de a\u00f1o el Hospital General de la Plaza de la Salud ha ingresado 208 personas con dengue y han fallecido dos, seg\u00fan se inform\u00f3 a Hoy. Asimismo, en la maternidad San Lorenzo de Los Mina ha habido una defunci\u00f3n, dos menores fallecieron en el hospital Arturo Grull\u00f3n de Santiago y siete fueron reportados en el hospital de Barahona, en el Sur del pa\u00eds. Las acciones. Los Ministerios de Salud de P\u00fablica, Defensa y Obras P\u00fablicas iniciaron la ejecuci\u00f3n de una campa\u00f1a contra el dengue, que se centra en eliminar criaderos de mosquitos, inclusi\u00f3n y concienciaci\u00f3n de la sociedad en promover la salud a fin de evitar la propagaci\u00f3n del mosquito Aedes Aegypti. S\u00e1nchez C\u00e1rdenas dijo que se tienen identificados los principales focos de acci\u00f3n donde el Ministerio de Defensa dar\u00e1 soporte con la disposici\u00f3n de su personal en labores de fumigaci\u00f3n, descacharrizaci\u00f3n y limpieza de espacios propensos a la multiplicaci\u00f3n del mosquito transmisor de dicha enfermedad. I ndic\u00f3 que estas acciones, en conjunto con los ministerios de Defesa y Obras P\u00fablicas, reforzar\u00e1n las estrategias que desarrolla el organismo de Salud, con la finalidad de disminuir la propagaci\u00f3n de enfermedades.\u201cHan sido identificados unos 32 municipios a los que se dar\u00e1 prioridad en estas labores\u201d. El pa\u00eds, al igual que otros pa\u00edses de Centro y Suramerica, se encuentra en una alerta emitida por la Organizaci\u00f3n Panamericana de la Salud y RD ocupa el puesto n\u00famero nueve de los diez pa\u00edses con mayor incidencia de dengue.<\/p>\n","protected":false},"author":8,"featured_media":92779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-92778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/92778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=92778"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/92778\/revisions"}],"predecessor-version":[{"id":92780,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/92778\/revisions\/92780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/92779"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=92778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=92778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=92778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}