{"id":93282,"date":"2019-07-19T10:46:16","date_gmt":"2019-07-19T14:46:16","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=93282"},"modified":"2019-07-19T10:46:16","modified_gmt":"2019-07-19T14:46:16","slug":"muere-operador-de-rodillo-al-deslizarse-mientras-realizaba-trabajos-en-san-juan","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/07\/19\/muere-operador-de-rodillo-al-deslizarse-mientras-realizaba-trabajos-en-san-juan\/","title":{"rendered":"Muere operador de rodillo al deslizarse mientras realizaba trabajos en San Juan"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-93283 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/07\/sj-2-768x550.jpg\" alt=\"\" width=\"494\" height=\"354\" \/>SAN JUAN .-\u00a0 Un hombre perdi\u00f3 la vida al caer de un rodillo en momentos en que realiza trabajos con esa m\u00e1quina, en un hecho registrado en la comunidad de Guanito, de esta ciudad.<\/p>\n<p>El occiso fue identificado por las autoridades como Ram\u00f3n Bartolo Santana del Villar, de 63 a\u00f1os, el cual era operador de rodillo y oriundo de Santo Domingo.<\/p>\n<p>El cuerpo del fallecido presenta trauma cr\u00e1neo encef\u00e1lico severo abierto con exposici\u00f3n de masa encef\u00e1lica, causadas por el deslizamiento de la maquina pesada, seg\u00fan el certificado m\u00e9dico levantado por la doctora Miguelina Montero.<\/p>\n<p>El informe preliminar expresa que el hecho ocurri\u00f3 momentos en que Ram\u00f3n Bartolo Santana hac\u00eda trabajos en el paraje los Gajos ubicado en el tramo carretero Guanito Arrollo Cano al medio d\u00eda de ayer, seg\u00fan explica una nota policial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN JUAN .-\u00a0 Un hombre perdi\u00f3 la vida al caer de un rodillo en momentos en que realiza trabajos con esa m\u00e1quina, en un hecho registrado en la comunidad de Guanito, de esta ciudad. El occiso fue identificado por las autoridades como Ram\u00f3n Bartolo Santana del Villar, de 63 a\u00f1os, el cual era operador de rodillo y oriundo de Santo Domingo. El cuerpo del fallecido presenta trauma cr\u00e1neo encef\u00e1lico severo abierto con exposici\u00f3n de masa encef\u00e1lica, causadas por el deslizamiento de la maquina pesada, seg\u00fan el certificado m\u00e9dico levantado por la doctora Miguelina Montero. El informe preliminar expresa que el hecho ocurri\u00f3 momentos en que Ram\u00f3n Bartolo Santana hac\u00eda trabajos en el paraje los Gajos ubicado en el tramo carretero Guanito Arrollo Cano al medio d\u00eda de ayer, seg\u00fan explica una nota policial.<\/p>\n","protected":false},"author":8,"featured_media":93283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[1443,1274,1441,1442,1343,1444,183],"class_list":["post-93282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-deslizarse","tag-nacionales","tag-operador","tag-rodillo","tag-sanjuan","tag-trabajos","tag-muere"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=93282"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93282\/revisions"}],"predecessor-version":[{"id":93284,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93282\/revisions\/93284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/93283"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=93282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=93282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=93282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}