{"id":93379,"date":"2019-07-22T14:19:17","date_gmt":"2019-07-22T18:19:17","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=93379"},"modified":"2019-07-22T14:19:17","modified_gmt":"2019-07-22T18:19:17","slug":"la-one-reporta-variacion-en-los-costos-de-la-construccion-de-viviendas","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/07\/22\/la-one-reporta-variacion-en-los-costos-de-la-construccion-de-viviendas\/","title":{"rendered":"La ONE reporta variaci\u00f3n en los costos de la construcci\u00f3n de viviendas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-93380 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/07\/Alexandra-Izquierdo-1024x550-800x430.jpg\" alt=\"\" width=\"493\" height=\"265\" \/>SANTO DOMINGO.-La Directora Nacional de Estad\u00edstica, Alexandra Izquierdo explic\u00f3 que en los \u00faltimos seis meses, los precios de las maquinarias y las herramientas presentaron variaciones significativas.<\/p>\n<p>La Oficina Nacional de Estad\u00edstica (ONE) inform\u00f3 que en el mes de junio el \u00cdndice de Costos Directos de la Construcci\u00f3n de Viviendas (ICDV) fue de 158.62, lo que equivale a una variaci\u00f3n acumulada en los primeros seis meses de un 0.90 %, resultado inferior en comparaci\u00f3n al registrado en el mismo periodo del a\u00f1o anterior, que fue de un 5.07 %.<\/p>\n<p>As\u00ed lo inform\u00f3 la directora de la ONE, Alexandra Izquierdo, quien explic\u00f3 que por grupos de costos la principal disminuci\u00f3n se present\u00f3 en los subcontratos, con un -1.33 %, mientras que los principales aumentos se registraron en las maquinarias y las herramientas con un 3.92 %\u00a0 y un 2.52 %, respectivamente.<\/p>\n<p>Por sub-grupos de costos las principales bajas se presentaron en el subcontrato de herrer\u00eda, con un -8.94 %; los alambres, clavos, zinc y otros, con un -5.65 % y la madera, con un -5.40 %. Por otra parte, los mayores incrementos acumulados fueron los cementos y pegamentos, con un 5.79 %; seguido por los subcontrato de ebanister\u00eda, con un 4.42 %.<\/p>\n<p>El ICDV es un instrumento estad\u00edstico que permite conocer las variaciones mensuales\u00a0de costos en la construcci\u00f3n de cuatro tipos de viviendas. Se actualiza mediante la obtenci\u00f3n de los precios de 111 art\u00edculos, clasificados en cinco\u00a0grandes grupos: mano de obra, maquinarias, herramientas, materiales y sub-contratos; obtenidos al hacer un muestreo en establecimientos econ\u00f3micos que producen, comercializan o importan los insumos utilizados para la construcci\u00f3n de edificaciones.<\/p>\n<p>Este \u00edndice permite medir otras variables econ\u00f3micas y sirve como instrumento para el reajuste de los contratos para las obras. Tambi\u00e9n para estimar la evoluci\u00f3n de los precios de los insumos b\u00e1sicos; adem\u00e1s de medir las variaciones estacionales en los precios y orienta en la toma de decisiones en las \u00e1reas de inter\u00e9s, tanto para el sector p\u00fablico como el privado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-La Directora Nacional de Estad\u00edstica, Alexandra Izquierdo explic\u00f3 que en los \u00faltimos seis meses, los precios de las maquinarias y las herramientas presentaron variaciones significativas. La Oficina Nacional de Estad\u00edstica (ONE) inform\u00f3 que en el mes de junio el \u00cdndice de Costos Directos de la Construcci\u00f3n de Viviendas (ICDV) fue de 158.62, lo que equivale a una variaci\u00f3n acumulada en los primeros seis meses de un 0.90 %, resultado inferior en comparaci\u00f3n al registrado en el mismo periodo del a\u00f1o anterior, que fue de un 5.07 %. As\u00ed lo inform\u00f3 la directora de la ONE, Alexandra Izquierdo, quien explic\u00f3 que por grupos de costos la principal disminuci\u00f3n se present\u00f3 en los subcontratos, con un -1.33 %, mientras que los principales aumentos se registraron en las maquinarias y las herramientas con un 3.92 %\u00a0 y un 2.52 %, respectivamente. Por sub-grupos de costos las principales bajas se presentaron en el subcontrato de herrer\u00eda, con un -8.94 %; los alambres, clavos, zinc y otros, con un -5.65 % y la madera, con un -5.40 %. Por otra parte, los mayores incrementos acumulados fueron los cementos y pegamentos, con un 5.79 %; seguido por los subcontrato de ebanister\u00eda, con un 4.42 %. El ICDV es un instrumento estad\u00edstico que permite conocer las variaciones mensuales\u00a0de costos en la construcci\u00f3n de cuatro tipos de viviendas. Se actualiza mediante la obtenci\u00f3n de los precios de 111 art\u00edculos, clasificados en cinco\u00a0grandes grupos: mano de obra, maquinarias, herramientas, materiales y sub-contratos; obtenidos al hacer un muestreo en establecimientos econ\u00f3micos que producen, comercializan o importan los insumos utilizados para la construcci\u00f3n de edificaciones. Este \u00edndice permite medir otras variables econ\u00f3micas y sirve como instrumento para el reajuste de los contratos para las obras. Tambi\u00e9n para estimar la evoluci\u00f3n de los precios de los insumos b\u00e1sicos; adem\u00e1s de medir las variaciones estacionales en los precios y orienta en la toma de decisiones en las \u00e1reas de inter\u00e9s, tanto para el sector p\u00fablico como el privado.<\/p>\n","protected":false},"author":8,"featured_media":93380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-93379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=93379"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93379\/revisions"}],"predecessor-version":[{"id":93381,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93379\/revisions\/93381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/93380"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=93379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=93379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=93379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}