{"id":94491,"date":"2019-08-15T11:57:13","date_gmt":"2019-08-15T15:57:13","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=94491"},"modified":"2019-08-15T11:57:13","modified_gmt":"2019-08-15T15:57:13","slug":"hombre-mata-a-su-hijo-y-a-un-tecnico-porque-no-le-arreglo-el-televisor-en-dos-hechos-separados","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/08\/15\/hombre-mata-a-su-hijo-y-a-un-tecnico-porque-no-le-arreglo-el-televisor-en-dos-hechos-separados\/","title":{"rendered":"Hombre mata a su hijo y a un t\u00e9cnico porque no le arregl\u00f3 el televisor, en dos hechos separados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-94492 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/08\/download_12070466_20190815112728.jpg\" alt=\"\" width=\"423\" height=\"271\" \/>Un hombre mat\u00f3 a tiros su hijo, a un radio t\u00e9cnico de electrodom\u00e9sticos y se suicid\u00f3 de un disparo en el sector Los Molinos de Villa Duarte, Santo Domingo Este en un confuso incidente.<\/p>\n<p>Las v\u00edctimas son V\u00edctor Alfonso Nina Moreta, de 23 a\u00f1os, hijo y el t\u00e9cnico Leoncio Tolentino Tejada, de 62 a\u00f1os. En tanto que el homicida fue identificado como V\u00edctor Enelaisy Nina Guerrero, de 47 a\u00f1os.<\/p>\n<p>Informaciones preliminares de los hechos indican que Victor Enelaisy fue al taller de Tolentino Tejada a buscar un televisor que hab\u00eda dejado reparando y al percatarse de que no hab\u00eda terminado el trabajo se molest\u00f3 y apu\u00f1al\u00f3 al t\u00e9cnico adem\u00e1s de despojarlo de un revolver con el que luego fue a casa de una hija suya.<\/p>\n<p>En la casa de la hija de Nina Guerrero el hombre habr\u00eda tenido otra discusi\u00f3n aun no esclarecida tras al cual hiri\u00f3 de bala a su hijo V\u00edctor Alfonso. Al percatarse de lo ocurrido se dispar\u00f3 y se quit\u00f3 la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre mat\u00f3 a tiros su hijo, a un radio t\u00e9cnico de electrodom\u00e9sticos y se suicid\u00f3 de un disparo en el sector Los Molinos de Villa Duarte, Santo Domingo Este en un confuso incidente. Las v\u00edctimas son V\u00edctor Alfonso Nina Moreta, de 23 a\u00f1os, hijo y el t\u00e9cnico Leoncio Tolentino Tejada, de 62 a\u00f1os. En tanto que el homicida fue identificado como V\u00edctor Enelaisy Nina Guerrero, de 47 a\u00f1os. Informaciones preliminares de los hechos indican que Victor Enelaisy fue al taller de Tolentino Tejada a buscar un televisor que hab\u00eda dejado reparando y al percatarse de que no hab\u00eda terminado el trabajo se molest\u00f3 y apu\u00f1al\u00f3 al t\u00e9cnico adem\u00e1s de despojarlo de un revolver con el que luego fue a casa de una hija suya. En la casa de la hija de Nina Guerrero el hombre habr\u00eda tenido otra discusi\u00f3n aun no esclarecida tras al cual hiri\u00f3 de bala a su hijo V\u00edctor Alfonso. Al percatarse de lo ocurrido se dispar\u00f3 y se quit\u00f3 la vida.<\/p>\n","protected":false},"author":8,"featured_media":94492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-94491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/94491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=94491"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/94491\/revisions"}],"predecessor-version":[{"id":94493,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/94491\/revisions\/94493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/94492"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=94491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=94491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=94491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}