{"id":95310,"date":"2019-09-04T12:25:59","date_gmt":"2019-09-04T16:25:59","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=95310"},"modified":"2019-09-04T12:25:59","modified_gmt":"2019-09-04T16:25:59","slug":"pn-miembros-familia-rosario-hieren-a-cuatro-agentes-durante-manifestacion-frente-al-palacio","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/09\/04\/pn-miembros-familia-rosario-hieren-a-cuatro-agentes-durante-manifestacion-frente-al-palacio\/","title":{"rendered":"PN: Miembros familia Rosario hieren a cuatro agentes durante manifestaci\u00f3n frente al Palacio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-95311 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/09\/Policia-Rosario1-1024x550-800x430.jpg\" alt=\"\" width=\"497\" height=\"267\" \/>SANTO DOMINGO.- La Polic\u00eda Nacional inform\u00f3 este mi\u00e9rcoles que cuatro de sus agentes resultaron heridos a pedradas al tratar de controlar una manifestaci\u00f3n en la que supuestos miembros de la familia Rosario reclamaba una presunta herencia millonaria frente al Palacio Nacional en el d\u00eda de ayer.<\/p>\n<p>Una nota de prensa de la instituci\u00f3n del orden se\u00f1ala que los heridos son el teniente coronel Edward D\u00edaz N\u00fa\u00f1ez, y los rasos Keuri De Los Santos Marizan; Failot Gonz\u00e1lez Hern\u00e1ndez y Euri Antonio Ti\u00f3 De La Cruz, quienes fueron asistidos en diferentes centros de salud.<\/p>\n<p>La nota agrega que \u201cfrente a este lamentable suceso, se procedi\u00f3 al apresamiento de Jean Carlos Valdez, acusado de producir la herida en el rostro del raso Tio De la Cruz\u201d.<\/p>\n<p>La uniformada indica que la protesta se desarroll\u00f3 de manera pac\u00edfica hasta las 11:50 de la ma\u00f1ana del martes, en las inmediaciones del Palacio Nacional, pero se esparcieron en las calles adyacentes tratando de penetrar a la casa de gobierno sin tener los permisos requeridos.<\/p>\n<p>\u201cActo seguido, los manifestantes comenzaron a lanzar piedras y botellas, logrando impactar a los efectivos policiales\u201d, dice la nota.<\/p>\n<p>La instituci\u00f3n del orden hizo un llamado a los dominicanos, advirti\u00e9ndoles de que pueden ejercer su derecho a la protesta, \u201cpero sin violentar el per\u00edmetro de seguridad ni los permisos que se les otorgan para realizar sus manifestaciones\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La Polic\u00eda Nacional inform\u00f3 este mi\u00e9rcoles que cuatro de sus agentes resultaron heridos a pedradas al tratar de controlar una manifestaci\u00f3n en la que supuestos miembros de la familia Rosario reclamaba una presunta herencia millonaria frente al Palacio Nacional en el d\u00eda de ayer. Una nota de prensa de la instituci\u00f3n del orden se\u00f1ala que los heridos son el teniente coronel Edward D\u00edaz N\u00fa\u00f1ez, y los rasos Keuri De Los Santos Marizan; Failot Gonz\u00e1lez Hern\u00e1ndez y Euri Antonio Ti\u00f3 De La Cruz, quienes fueron asistidos en diferentes centros de salud. La nota agrega que \u201cfrente a este lamentable suceso, se procedi\u00f3 al apresamiento de Jean Carlos Valdez, acusado de producir la herida en el rostro del raso Tio De la Cruz\u201d. La uniformada indica que la protesta se desarroll\u00f3 de manera pac\u00edfica hasta las 11:50 de la ma\u00f1ana del martes, en las inmediaciones del Palacio Nacional, pero se esparcieron en las calles adyacentes tratando de penetrar a la casa de gobierno sin tener los permisos requeridos. \u201cActo seguido, los manifestantes comenzaron a lanzar piedras y botellas, logrando impactar a los efectivos policiales\u201d, dice la nota. La instituci\u00f3n del orden hizo un llamado a los dominicanos, advirti\u00e9ndoles de que pueden ejercer su derecho a la protesta, \u201cpero sin violentar el per\u00edmetro de seguridad ni los permisos que se les otorgan para realizar sus manifestaciones\u201d.<\/p>\n","protected":false},"author":8,"featured_media":95311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-95310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=95310"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95310\/revisions"}],"predecessor-version":[{"id":95312,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95310\/revisions\/95312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/95311"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=95310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=95310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=95310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}