{"id":95619,"date":"2019-09-11T11:49:36","date_gmt":"2019-09-11T15:49:36","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=95619"},"modified":"2019-09-11T11:49:36","modified_gmt":"2019-09-11T15:49:36","slug":"johnson-sufre-un-reves-tribunal-escoces-declara-ilegal-cierre-de-parlamento","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/09\/11\/johnson-sufre-un-reves-tribunal-escoces-declara-ilegal-cierre-de-parlamento\/","title":{"rendered":"Johnson sufre un rev\u00e9s; tribunal escoc\u00e9s declara ilegal cierre de parlamento"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-95620 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/09\/Johnson-sufre-un-reves-1024x550-800x430.jpeg\" alt=\"\" width=\"424\" height=\"228\" \/>EDIMBURGO, REINO UNIDO.- El Gobierno brit\u00e1nico sufri\u00f3 este mi\u00e9rcoles un duro rev\u00e9s, despu\u00e9s de que la Justicia escocesa declarase \u201cilegal\u201d la decisi\u00f3n del primer ministro, Boris Johnson, de suspender el Parlamento en el periodo previo a la salida del Reino Unido de la Uni\u00f3n Europea, el 31 de octubre.<\/p>\n<p>El Tribunal de Apelaci\u00f3n de Escocia consider\u00f3 que la acci\u00f3n del Ejecutivo conservador, que aconsej\u00f3 a la reina Isabel II refrendar la decisi\u00f3n de clausurar las c\u00e1maras desde ayer y hasta el 14 de octubre, quebrant\u00f3 la legalidad y estuvo motivada por \u201cel prop\u00f3sito inapropiado de obstaculizar el Parlamento\u201d.<\/p>\n<p>Tras conocerse el dictamen, el Gobierno comunic\u00f3 que recurrir\u00e1 el fallo ante el Tribunal Supremo, la m\u00e1xima instancia judicial del Reino Unido, que atender\u00e1 este y otro caso similar el pr\u00f3ximo martes, d\u00eda 17, en una sesi\u00f3n presidida por nueve magistrados.<\/p>\n<p>Los tres jueces en Escocia, presididos por Lord Carloway, emitieron su veredicto por unanimidad, pero no dieron ninguna orden espec\u00edfica para que las sesiones de la C\u00e1mara de los Comunes se reanuden, bajo el argumento de que el caso llegar\u00e1 al Supremo.<\/p>\n<p>Adem\u00e1s del caso escoc\u00e9s, el Supremo deber\u00e1 atender otro que persigue el mismo objetivo y que fue presentado en Inglaterra por la activista contraria al \u201cbrexit\u201d Gina Miller.<\/p>\n<p>En el caso de Miller, el Tribunal Superior de Londres hab\u00eda decretado la semana pasada que la suspensi\u00f3n parlamentaria no es ilegal y que se trata de un asunto pol\u00edtico, por lo que la activista y empresaria decidi\u00f3 apelar al Supremo.<\/p>\n<p>El fallo emitido hoy en Escocia revoca as\u00ed uno anterior del pasado 4 de septiembre, que dictamin\u00f3 que el cierre s\u00ed cumpl\u00eda con el ordenamiento -por razones muy similares a las del caso Miller-, y que no impidi\u00f3 que la actividad de las c\u00e1maras se paralizase este martes hasta el 14 de octubre.<\/p>\n<p>Para el 14 de octubre, el Gobierno ha programado el llamado \u201cDiscurso de la reina\u201d, la agenda legislativa del Ejecutivo para el pr\u00f3ximo a\u00f1o, un procedimiento que es habitual, pero que la oposici\u00f3n asegura que esta vez se ha usado para hacerlo coincidir con las jornadas anteriores al d\u00eda 31, la fecha prevista para el \u201cbrexit\u201d.<\/p>\n<p>El gabinete de Johnson se mostr\u00f3 \u201cdecepcionado\u201d con la decisi\u00f3n de la corte de apelaci\u00f3n de mayor rango de Escocia y se\u00f1al\u00f3 que suspender el Parlamento \u201ces la forma legal y necesaria\u201d para poder \u201cpresentar una agenda legislativa nacional s\u00f3lida\u201d.<\/p>\n<p>La querella resuelta en Escocia fue presentada por un grupo de m\u00e1s de 70 parlamentarios, entre ellos la representante del Partido Nacionalista Escoc\u00e9s (SNP) Joanna Cherry, la l\u00edder de los Liberales Dem\u00f3cratas, Jo Swinson, varios diputados laboristas e independientes y la asociaci\u00f3n contraria al \u201cbrexit\u201d \u201cThe Good Law Project\u201d.<\/p>\n<p>En declaraciones a los medios tras conocerse el dictamen, Cherry inst\u00f3 a que se decrete la reapertura del Parlamento para poder continuar \u201cescrutando lo que est\u00e1 dispuesto a hacer el Gobierno en relaci\u00f3n al \u2018brexit&#8217;\u201d.<\/p>\n<p>\u201cEsta es una decisi\u00f3n un\u00e1nime de la mayor corte de apelaci\u00f3n de Escocia sobre que el cierre del Parlamento por Boris Johnson es ilegal, por lo que, a cada instante que permanece cerrado, el Gobierno brit\u00e1nico est\u00e1 quebrantando la ley\u201d, afirm\u00f3 Cherry, rodeada por un grupo de manifestantes contrarios al abandono de la UE.<\/p>\n<p>La ministra principal de Escocia, Nicola Sturgeon, se pronunci\u00f3 en la misma l\u00ednea al llamar a una reanudaci\u00f3n de la actividad parlamentaria \u201cinmediata\u201d y afirm\u00f3 que el comportamiento de Johnson est\u00e1 siendo \u201cindignante\u201d e \u201cimprudente\u201d.<\/p>\n<p>El portavoz laborista para el \u201cbrexit\u201d, Keir Starmer, celebr\u00f3 la decisi\u00f3n, aunque reconoci\u00f3 que no era algo \u201cesperado\u201d, a pesar de que resultaba \u201cobvio para todos que cerrar el Parlamento en este momento crucial era algo incorrecto\u201d.<\/p>\n<p>Para el diputado conservador Dominic Grieve, se estar\u00eda ante \u201cuna cuesti\u00f3n muy seria\u201d si finalmente se sustancia que el primer ministro \u201cenga\u00f1\u00f3\u201d a la soberana al aconsejarle apoyar el procedimiento, por lo que \u201cser\u00eda el momento de Johnson de dimitir\u201d.<\/p>\n<p>La oposici\u00f3n -con el respaldo de un grupo de 21 diputados conservadores descontentos con la gesti\u00f3n del Gobierno- aprob\u00f3 la semana pasada una ley que obliga al \u201cpremier\u201d a pedir una pr\u00f3rroga del \u201cbrexit\u201d si no llega a un acuerdo con la UE para el 19 de octubre, de forma que se evite una ruptura no negociada.<\/p>\n<p>Johnson, sin embargo, sostiene que quiere lograr un pacto que permita una salida ordenada y ha recalcado que no est\u00e1 dispuesto a pedir un retraso de la retirada del bloque comunitario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EDIMBURGO, REINO UNIDO.- El Gobierno brit\u00e1nico sufri\u00f3 este mi\u00e9rcoles un duro rev\u00e9s, despu\u00e9s de que la Justicia escocesa declarase \u201cilegal\u201d la decisi\u00f3n del primer ministro, Boris Johnson, de suspender el Parlamento en el periodo previo a la salida del Reino Unido de la Uni\u00f3n Europea, el 31 de octubre. El Tribunal de Apelaci\u00f3n de Escocia consider\u00f3 que la acci\u00f3n del Ejecutivo conservador, que aconsej\u00f3 a la reina Isabel II refrendar la decisi\u00f3n de clausurar las c\u00e1maras desde ayer y hasta el 14 de octubre, quebrant\u00f3 la legalidad y estuvo motivada por \u201cel prop\u00f3sito inapropiado de obstaculizar el Parlamento\u201d. Tras conocerse el dictamen, el Gobierno comunic\u00f3 que recurrir\u00e1 el fallo ante el Tribunal Supremo, la m\u00e1xima instancia judicial del Reino Unido, que atender\u00e1 este y otro caso similar el pr\u00f3ximo martes, d\u00eda 17, en una sesi\u00f3n presidida por nueve magistrados. Los tres jueces en Escocia, presididos por Lord Carloway, emitieron su veredicto por unanimidad, pero no dieron ninguna orden espec\u00edfica para que las sesiones de la C\u00e1mara de los Comunes se reanuden, bajo el argumento de que el caso llegar\u00e1 al Supremo. Adem\u00e1s del caso escoc\u00e9s, el Supremo deber\u00e1 atender otro que persigue el mismo objetivo y que fue presentado en Inglaterra por la activista contraria al \u201cbrexit\u201d Gina Miller. En el caso de Miller, el Tribunal Superior de Londres hab\u00eda decretado la semana pasada que la suspensi\u00f3n parlamentaria no es ilegal y que se trata de un asunto pol\u00edtico, por lo que la activista y empresaria decidi\u00f3 apelar al Supremo. El fallo emitido hoy en Escocia revoca as\u00ed uno anterior del pasado 4 de septiembre, que dictamin\u00f3 que el cierre s\u00ed cumpl\u00eda con el ordenamiento -por razones muy similares a las del caso Miller-, y que no impidi\u00f3 que la actividad de las c\u00e1maras se paralizase este martes hasta el 14 de octubre. Para el 14 de octubre, el Gobierno ha programado el llamado \u201cDiscurso de la reina\u201d, la agenda legislativa del Ejecutivo para el pr\u00f3ximo a\u00f1o, un procedimiento que es habitual, pero que la oposici\u00f3n asegura que esta vez se ha usado para hacerlo coincidir con las jornadas anteriores al d\u00eda 31, la fecha prevista para el \u201cbrexit\u201d. El gabinete de Johnson se mostr\u00f3 \u201cdecepcionado\u201d con la decisi\u00f3n de la corte de apelaci\u00f3n de mayor rango de Escocia y se\u00f1al\u00f3 que suspender el Parlamento \u201ces la forma legal y necesaria\u201d para poder \u201cpresentar una agenda legislativa nacional s\u00f3lida\u201d. La querella resuelta en Escocia fue presentada por un grupo de m\u00e1s de 70 parlamentarios, entre ellos la representante del Partido Nacionalista Escoc\u00e9s (SNP) Joanna Cherry, la l\u00edder de los Liberales Dem\u00f3cratas, Jo Swinson, varios diputados laboristas e independientes y la asociaci\u00f3n contraria al \u201cbrexit\u201d \u201cThe Good Law Project\u201d. En declaraciones a los medios tras conocerse el dictamen, Cherry inst\u00f3 a que se decrete la reapertura del Parlamento para poder continuar \u201cescrutando lo que est\u00e1 dispuesto a hacer el Gobierno en relaci\u00f3n al \u2018brexit&#8217;\u201d. \u201cEsta es una decisi\u00f3n un\u00e1nime de la mayor corte de apelaci\u00f3n de Escocia sobre que el cierre del Parlamento por Boris Johnson es ilegal, por lo que, a cada instante que permanece cerrado, el Gobierno brit\u00e1nico est\u00e1 quebrantando la ley\u201d, afirm\u00f3 Cherry, rodeada por un grupo de manifestantes contrarios al abandono de la UE. La ministra principal de Escocia, Nicola Sturgeon, se pronunci\u00f3 en la misma l\u00ednea al llamar a una reanudaci\u00f3n de la actividad parlamentaria \u201cinmediata\u201d y afirm\u00f3 que el comportamiento de Johnson est\u00e1 siendo \u201cindignante\u201d e \u201cimprudente\u201d. El portavoz laborista para el \u201cbrexit\u201d, Keir Starmer, celebr\u00f3 la decisi\u00f3n, aunque reconoci\u00f3 que no era algo \u201cesperado\u201d, a pesar de que resultaba \u201cobvio para todos que cerrar el Parlamento en este momento crucial era algo incorrecto\u201d. Para el diputado conservador Dominic Grieve, se estar\u00eda ante \u201cuna cuesti\u00f3n muy seria\u201d si finalmente se sustancia que el primer ministro \u201cenga\u00f1\u00f3\u201d a la soberana al aconsejarle apoyar el procedimiento, por lo que \u201cser\u00eda el momento de Johnson de dimitir\u201d. La oposici\u00f3n -con el respaldo de un grupo de 21 diputados conservadores descontentos con la gesti\u00f3n del Gobierno- aprob\u00f3 la semana pasada una ley que obliga al \u201cpremier\u201d a pedir una pr\u00f3rroga del \u201cbrexit\u201d si no llega a un acuerdo con la UE para el 19 de octubre, de forma que se evite una ruptura no negociada. Johnson, sin embargo, sostiene que quiere lograr un pacto que permita una salida ordenada y ha recalcado que no est\u00e1 dispuesto a pedir un retraso de la retirada del bloque comunitario.<\/p>\n","protected":false},"author":8,"featured_media":95620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-95619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=95619"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95619\/revisions"}],"predecessor-version":[{"id":95621,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95619\/revisions\/95621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/95620"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=95619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=95619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=95619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}