{"id":95727,"date":"2019-09-12T11:20:50","date_gmt":"2019-09-12T15:20:50","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=95727"},"modified":"2019-09-12T11:20:50","modified_gmt":"2019-09-12T15:20:50","slug":"quique-antun-advierte-no-habra-piedad-para-quienes-crean-inseguridad-y-miedo-en-el-pais","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/09\/12\/quique-antun-advierte-no-habra-piedad-para-quienes-crean-inseguridad-y-miedo-en-el-pais\/","title":{"rendered":"Quique Ant\u00fan advierte \u201cno habr\u00e1 piedad\u201d para quienes crean inseguridad y miedo en el pa\u00eds"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-95728 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/wp-content\/uploads\/2019\/09\/Quique-Antun-1024x550-800x430.jpg\" alt=\"\" width=\"495\" height=\"266\" \/>SANTO DOMINGO.- El presidente del Partido Reformista Social Cristiano, Quique Ant\u00fan, advirti\u00f3 este mi\u00e9rcoles que los responsables de crear la inseguridad y el miedo que se vive en el pa\u00eds, deben prepararse porque cuando el PRSC llegue al poder en el 2020 no habr\u00e1 piedad con los que cometen actos delictivos.<\/p>\n<p>Advirti\u00f3 que todos los delincuentes responsables de la inseguridad que tiene aterrorizada a la poblaci\u00f3n, ser\u00e1n perseguidos, apresados y sometidos a la justicia \u201cy cuando sean condenados por un juez, ser\u00e1n encerrados en las diferentes c\u00e1rceles del pa\u00eds y no saldr\u00e1n hasta que no paguen por sus delitos\u201d.<\/p>\n<p>\u201cEl plan que tenemos es limpiar las calles de estas lacras sociales para recuperar la paz y la tranquilidad que disfrutaban los dominicanos hace dos d\u00e9cadas\u201d, dijo.<\/p>\n<p>Quique Ant\u00fan indic\u00f3 en ese sentido, que se crear\u00e1n cuerpos especializados de polic\u00edas y militares para perseguir y apresar a los malhechores responsables de la inseguridad que vive nuestra naci\u00f3n, cometiendo cr\u00edmenes, robos, asaltos, secuestros, sicariato y otros delitos graves.<\/p>\n<p>\u201cA los delincuentes, que se preparen, porque vamos a ser implacables tan pronto lleguemos al poder, hasta acabar con la inseguridad ciudadana que ha dejado tantos muertos, luto y dolor en los \u00faltimos a\u00f1os.\u201d, destac\u00f3.<\/p>\n<p>El l\u00edder reformista explic\u00f3 que en la administraci\u00f3n reformista se construir\u00e1n todas las c\u00e1rceles que sean necesarias \u201cpara mantener en prisi\u00f3n a los delincuentes y criminales que tienen aterrorizada a la sociedad\u201d.<\/p>\n<p>Resalt\u00f3 que se va acabar el relajo y la impunidad con que se mueven en el pa\u00eds los delincuentes.<\/p>\n<p>\u201cEsta inseguridad tiene que acabar y para ello tenemos que enviar a la c\u00e1rcel a todos los ladrones, asaltantes y criminales, incluidos los delincuentes de cuello blanco\u201d, dijo.<\/p>\n<p>Insisti\u00f3 que no habr\u00e1 piedad con los criminales, \u201cporque el compromiso que tenemos con el pueblo dominicano es devolverle la paz a todos los ciudadanos para que anden en las calles sin miedo\u201d.<\/p>\n<p>Advirti\u00f3 a los responsables de crear la inseguridad ciudadana, el miedo y el terror, que si no quieren enfrentarse a la \u201cmano duro\u201d que se aplicar\u00e1 en el gobierno reformista, \u201ctienen tiempo para reinsertarse en la sociedad haciendo otras cosas que les permitan ganarse la vida honradamente sin tener que delinquir ni hacerle da\u00f1o a otras personas\u201d.<\/p>\n<p>Quique Ant\u00fan manifest\u00f3 finalmente que en el gobierno reformista se crear\u00e1n miles de empleos para que los j\u00f3venes tengan oportunidades de trabajar, igual que facilidades para estudiar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El presidente del Partido Reformista Social Cristiano, Quique Ant\u00fan, advirti\u00f3 este mi\u00e9rcoles que los responsables de crear la inseguridad y el miedo que se vive en el pa\u00eds, deben prepararse porque cuando el PRSC llegue al poder en el 2020 no habr\u00e1 piedad con los que cometen actos delictivos. Advirti\u00f3 que todos los delincuentes responsables de la inseguridad que tiene aterrorizada a la poblaci\u00f3n, ser\u00e1n perseguidos, apresados y sometidos a la justicia \u201cy cuando sean condenados por un juez, ser\u00e1n encerrados en las diferentes c\u00e1rceles del pa\u00eds y no saldr\u00e1n hasta que no paguen por sus delitos\u201d. \u201cEl plan que tenemos es limpiar las calles de estas lacras sociales para recuperar la paz y la tranquilidad que disfrutaban los dominicanos hace dos d\u00e9cadas\u201d, dijo. Quique Ant\u00fan indic\u00f3 en ese sentido, que se crear\u00e1n cuerpos especializados de polic\u00edas y militares para perseguir y apresar a los malhechores responsables de la inseguridad que vive nuestra naci\u00f3n, cometiendo cr\u00edmenes, robos, asaltos, secuestros, sicariato y otros delitos graves. \u201cA los delincuentes, que se preparen, porque vamos a ser implacables tan pronto lleguemos al poder, hasta acabar con la inseguridad ciudadana que ha dejado tantos muertos, luto y dolor en los \u00faltimos a\u00f1os.\u201d, destac\u00f3. El l\u00edder reformista explic\u00f3 que en la administraci\u00f3n reformista se construir\u00e1n todas las c\u00e1rceles que sean necesarias \u201cpara mantener en prisi\u00f3n a los delincuentes y criminales que tienen aterrorizada a la sociedad\u201d. Resalt\u00f3 que se va acabar el relajo y la impunidad con que se mueven en el pa\u00eds los delincuentes. \u201cEsta inseguridad tiene que acabar y para ello tenemos que enviar a la c\u00e1rcel a todos los ladrones, asaltantes y criminales, incluidos los delincuentes de cuello blanco\u201d, dijo. Insisti\u00f3 que no habr\u00e1 piedad con los criminales, \u201cporque el compromiso que tenemos con el pueblo dominicano es devolverle la paz a todos los ciudadanos para que anden en las calles sin miedo\u201d. Advirti\u00f3 a los responsables de crear la inseguridad ciudadana, el miedo y el terror, que si no quieren enfrentarse a la \u201cmano duro\u201d que se aplicar\u00e1 en el gobierno reformista, \u201ctienen tiempo para reinsertarse en la sociedad haciendo otras cosas que les permitan ganarse la vida honradamente sin tener que delinquir ni hacerle da\u00f1o a otras personas\u201d. Quique Ant\u00fan manifest\u00f3 finalmente que en el gobierno reformista se crear\u00e1n miles de empleos para que los j\u00f3venes tengan oportunidades de trabajar, igual que facilidades para estudiar.<\/p>\n","protected":false},"author":8,"featured_media":95728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-95727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politic"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=95727"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95727\/revisions"}],"predecessor-version":[{"id":95729,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95727\/revisions\/95729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/95728"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=95727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=95727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=95727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}